{"id":1103,"count":48,"description":"<div class=\"divIntroduction\" style=\"width: 60%;float: left;padding-right: 10px\">\r\n\r\nDas <strong>Risikomanagement<\/strong> z\u00e4hlt zu den wichtigsten gesetzlichen Anforderungen, die Hersteller von Medizinprodukten erf\u00fcllen m\u00fcssen.\r\n\r\nDie <strong>ISO 14971<\/strong> ist die Norm zur <em>\u201eAnwendung des Risikomanagements auf Medizinprodukte\u201c<\/em>. Sie beschreibt einen Risikomanagementprozess, der sicherstellen soll, dass die Risiken durch Medizinprodukte bekannt und beherrscht sowie im Vergleich zum Nutzen akzeptabel sind.\r\n\r\n<\/div>\r\n<div>\r\n\r\n<span style=\"font-size: small;font-style: italic\">Abb. 1: Risikomanagementprozess nach ISO 14971 (zum Vergr\u00f6\u00dfern klicken)<\/span><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/03\/Risikomanagement-Prozess-ISO-14971-scaled.jpeg\"><img class=\"alignnone wp-image-13130 size-thumbnail\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/03\/Risikomanagement-Prozess-ISO-14971-klein.jpeg\" alt=\"Risikomanagement-Prozess nach ISO 14971\" width=\"200\" \/><\/a>\r\n\r\n<\/div>\r\n<div style=\"clear: both;border: 1px solid grey;background-color: #dddddd;padding: 10px;margin-top: 30px\">\r\n\r\n<strong>Inhalt<\/strong>\r\n\r\nSie finden auf dieser Seite Fachartikel \u2026\r\n<ol>\r\n \t<li>zu den Aktivit\u00e4ten im Risikomanagementprozess, welche die ISO 14971 vorschreibt,<\/li>\r\n \t<li>zur Norm selbst,<\/li>\r\n \t<li>zum Zusammenspiel von Risikomanagement und der IT-Sicherheit,<\/li>\r\n \t<li>zur Anwendung der Norm in bestimmten Kontexten, z. B. bei Standalone-Software und<\/li>\r\n \t<li>dazu, wo Sie Unterst\u00fctzung beim Risikomanagement bekommen.<\/li>\r\n<\/ol>\r\n<\/div>\r\n<h2>1. Artikel zu Aktivit\u00e4ten im Risikomanagementprozess<\/h2>\r\n<h3>a) Risikomanagementplan<\/h3>\r\nDer erste Schritt beim Risikomanagement f\u00fcr ein konkretes Produkt besteht darin, den <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/risikomanagementplan\/\">Risikomanagementplan<\/a> zu erstellen. Dieser legt fest,\r\n<ul>\r\n \t<li>welche Rollen bzw. Personen (mit welchen Kompetenzen)<\/li>\r\n \t<li>welche Aktivit\u00e4ten<\/li>\r\n \t<li>mit welchen Methoden<\/li>\r\n \t<li>zu welchem Zeitpunkt durchf\u00fchren.<\/li>\r\n<\/ul>\r\nDiesen Risikomanagementplan muss die Verfahrensanweisung zum Risikomanagement einfordern\r\n<h3>b) Gef\u00e4hrdungsanalyse<\/h3>\r\nHersteller m\u00fcssen zuerst die Zweckbestimmung des Produkts festlegen.\r\n\r\nDann m\u00fcssen sie im Rahmen einer <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/risikoanalyse\/\">Gef\u00e4hrdungsanalyse bzw. <strong>Risikoanalyse<\/strong><\/a> die <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/gefaehrdung-und-gefaehrdungssitation\/\">Gef\u00e4hrdungen und Gef\u00e4hrdungssituationen<\/a> identifizieren. Dazu gibt es mehrere Methoden:\r\n<ul>\r\n \t<li><a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/fmea-bei-medizinprodukten\/\">FMEA: Definition und Bedeutung am Beispiel von Medizinprodukten<\/a><\/li>\r\n \t<li><a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/fault-tree-analysis-fta\/\">Fehlerbaumanalyse | FTA: Fault Tree Analysis<\/a><\/li>\r\n \t<li><a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/hazop-iec-61882\/\">HAZOP \u2013 Risikoanalyse nach IEC 61882<\/a><\/li>\r\n<\/ul>\r\nUm Gef\u00e4hrdungen zu identifizieren, die von fehlerhaften Prozessen ausgehen, empfiehlt sich die <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/pfmea\/\">Prozess-FMEA (pFMEA)<\/a>.\r\n<h3>c) Risikobewertung<\/h3>\r\nIm n\u00e4chsten Schritt m\u00fcssen die Hersteller die Risiken absch\u00e4tzen. Dazu m\u00fcssen sie bestimmen:\r\n<ul>\r\n \t<li>Die (m\u00f6glichen) <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/schaden-gemaess-iso-14971\/\">Sch\u00e4den (gem\u00e4\u00df ISO 14971)<\/a> durch ihr Produkt<\/li>\r\n \t<li>Die <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/schweregrad-schaden-iso-14971\/\">Schweregrade m\u00f6glicher Sch\u00e4den gem\u00e4\u00df ISO 14971<\/a>. Bei manchen Sch\u00e4den hilft die <a href=\"https:\/\/www.johner-institut.de\/blog\/medizinische-informatik\/icf-international-classification-functioning-disability-health\/\">ICF bei der Klassifizierung der Sch\u00e4den<\/a>.<\/li>\r\n \t<li>Die Wahrscheinlichkeit des Auftretens dieser Sch\u00e4den (diese <a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/fehlerwahrscheinlichkeit-bei-software\/\">Wahrscheinlichkeit ist bei Software<\/a> besonders schwer abzusch\u00e4tzen)<\/li>\r\n<\/ul>\r\nViele Hersteller arbeiten mit einer <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/risikoprioritaetszahl-rpz\/\">Risikopriorit\u00e4tszahl (RPZ)<\/a>. Dieses Konzept entspricht allerdings nicht der ISO 14971.\r\n<h3>d) Risikoakzeptanz<\/h3>\r\nSp\u00e4testens jetzt besteht die Aufgabe der Hersteller darin, ihre Kriterien f\u00fcr die <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/risikoakzeptanz\/\">Risikoakzeptanz<\/a> zu bestimmen. Die Festlegung erfolgt meist in Form einer <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/risikoakzeptanzmatrix-risikobewertungsmatrix\/\">Risikoakzeptanzmatrix<\/a>.\r\n\r\nDabei hilft auch der <a href=\"https:\/\/www.johner-institut.de\/blog\/fda\/fda-benefit-risk-guidance\/\">Benefit-Risk-Guidance der FDA<\/a>.\r\n\r\nBei der Bewertung des <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/\">Restrisikos<\/a> sollten Sie diese Zahlen kennen. Auch die <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/kaplan-meier\/\">Kaplan-Meier-Kurve<\/a> hilft im Risikomanagement.\r\n<h3>e) Risikobeherrschung und Risikomanagementbericht<\/h3>\r\nGesetze wie die MDR und die IVDR verpflichten die Hersteller zur <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/risikominimierung\/\">Risikominimierung bzw. Risikobeherrschung<\/a>. D.h. sie m\u00fcssen die Risiken so weit wie m\u00f6glich und gem\u00e4\u00df ihrer Akzeptanzkriterien reduzieren.\r\n\r\nSehr hilfreich bei Diskussionen mit Auditoren und Beh\u00f6rden sind der Artikel zu <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/risikominimierung-durch-informationen\/\">Informationen als Ma\u00dfnahmen zur Risikominimierung<\/a> sowie die <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/safety-assurance-cases\/\">Safety Assurance Cases<\/a>, welche die FDA bei einigen Produkten sogar verlangt.\r\n\r\nDie Ergebnisse aller bisherigen Aktivit\u00e4ten m\u00fcssen die Hersteller in einem <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/risikomanagementbericht\/\">Risikomanagementbericht<\/a> dokumentieren. Bei dieser Bewertung sollten die Hersteller pr\u00fcfen, dass sie die <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/fehler-beim-risikomanagement\/\">7 h\u00e4ufigsten Fehler im Risikomanagement<\/a> vermeiden.\r\n\r\nAll diese Aufzeichnungen und Dokumente bilden dann die <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/risikomanagementakte\/\">Risikomanagementakte<\/a>.\r\n<h3>f) Nachgelagerte Phase<\/h3>\r\nDamit endet das Risikomanagement nicht. Vielmehr folgt die <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/post-market-phase\/\">Post-Market-Phase<\/a> bzw. die <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/nachgelagerte-phase-iso-14971\/\">nachgelagerte Phase<\/a>, wie die ISO 14971 sie nennt. Ein Teil derer ist die <a href=\"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/post-market-surveillance\/\">Post-Market Surveillance und \u00dcberwachung der Produkte im Markt<\/a>.\r\n<h2>2. Fachartikel zur Norm<\/h2>\r\nDie DIN EN ISO 14971 liegt in der Version 2022 vor. Die letzte wesentliche \u00c4nderung stammt aus dem Jahr 2019. Diese \u00c4nderungen wurden mit der <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/dritte-ausgabe-der-iso-14971\/\">dritten Ausgabe der ISO 14971<\/a> eingef\u00fchrt. Damit wird die <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/iso-149712012-annex-za\/\">EN ISO 14971:2012 mit dem Annex ZA<\/a> obsolet.\r\n\r\nIm <a href=\"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/harmonisierte-normen\/\">Beitrag zu den harmonisierten Normen<\/a> erfahren Sie mehr zur Bedeutung der Pr\u00e4fixe wie DIN, EN und ISO.\r\n\r\nWie Hersteller die (neue Version) der Norm anwenden sollten, beschreibt der Beitrag zur <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/iso-24971\/\">ISO 24971<\/a>.\r\n\r\nWichtig ist auch die Frage, ob die ISO 14971 \u00fcberhaupt anwendbar ist. In diesem Kontext sind die Begriffe <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/vorhersehbarer-missbrauch\/\">vorhersehbarer Missbrauch<\/a> und <a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/anormaler-gebrauch\/\">anormaler Gebrauch <\/a>wichtig.\r\n\r\nIn anderen Rechtsbereichen wird die <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/iso-31000\/\">ISO 31000<\/a> genutzt, die f\u00fcr die Medizinproduktehersteller zumindest als Anregung dienen kann.\r\n<h2>3. Fachartikel zum Zusammenspiel von Risikomanagement und IT-Sicherheit<\/h2>\r\nBei Medizinprodukten, die Software enthalten oder Software sind, wirkt sich die IT-Sicherheit wesentlich auf die Risiken aus. Hilfreich sind hier folgende Publikationen:\r\n<ul>\r\n \t<li>\u00dcbersichtsartikel zur <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/it-security\/\">IT-Security im Allgemeinen<\/a> und zur <a href=\"https:\/\/www.johner-institut.de\/blog\/medizinische-informatik\/it-sicherheit-im-gesundheitswesen\/\">IT-Sicherheit im Gesundheitswesen<\/a> und den regulatorischen Anforderungen<\/li>\r\n \t<li><a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/fda-guidance-zur-cybersecurity\/\">Cybersecurity in Medical Devices: Die Guidance-Dokumente der FDA<\/a><\/li>\r\n \t<li><a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/aami-tir-57-it-security-medizinprodukte\/\">AAMI TIR 57: IT-Sicherheit und Risikomanagement<\/a><\/li>\r\n \t<li><a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/ul-2900-2-1\/\">UL 2900: Weshalb Sie den IT-Security-Standard kennen, aber niemals kaufen sollten<\/a><\/li>\r\n \t<li><a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/cloud-computing-im-gesundheitswesen\/\">Medical Cloud: Cloud Computing im Gesundheitswesen<\/a><\/li>\r\n \t<li><a href=\"https:\/\/www.johner-institut.de\/blog\/systems-engineering\/iso-iec-15408\/\">ISO\/IEC 15408: IT-Sicherheit von (Medizin-)Produkten bewerten<\/a><\/li>\r\n<\/ul>\r\n<h2>4. Fachartikel zu bestimmten Kontexten<\/h2>\r\n<h3>a) Fachartikel f\u00fcr Software-Hersteller<\/h3>\r\nF\u00fcr Medizinprodukte, die Software enthalten oder eine Standalone-Software sind, empfehlen sich diese Fachartikel:\r\n<ul>\r\n \t<li><a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/software-risikomanagement-iso14971\/\">Software-Risikomanagement f\u00fcr medizinische Software<\/a><\/li>\r\n \t<li><a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/fehlerwahrscheinlichkeit-bei-software\/\">Fehlerwahrscheinlichkeit bei Software<\/a><\/li>\r\n<\/ul>\r\n<h3>b) Fachartikel f\u00fcr andere Organisationen<\/h3>\r\nDas Risikomanagement bei Medizinprodukteherstellern unterscheidet sich in manchen Aspekten von dem Risikomanagement bei anderen Organisationen:\r\n<ul>\r\n \t<li><a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/iec-80001\/\">Risikomanagement vernetzter Krankenhaus-IT &amp; IEC 80001-1<\/a><\/li>\r\n \t<li>Risikomanagement bei Entwicklungsdienstleistern<\/li>\r\n \t<li><a href=\"https:\/\/www.johner-institut.de\/blog\/medizinische-informatik\/risikomanagement-im-krankenhaus-und-bei-anderen-betreibern\/\">Risikomanagement im Krankenhaus und bei anderen Betreibern<\/a><\/li>\r\n<\/ul>\r\n<div style=\"border: 1px solid grey;background-color: #dddddd;padding: 10px;margin-top: 30px\">\r\n<h2>Das Johner Institut hilft<\/h2>\r\nNutzen Sie die Unterst\u00fctzung des Johner Instituts:\r\n<ul>\r\n \t<li>Haben Sie noch Fragen zum Risikomanagement? Dann nutzen Sie <a href=\"https:\/\/www.johner-institut.de\/micro-consulting\/\">das kostenfreie <strong>Micro-Consulting<\/strong><\/a>.<\/li>\r\n \t<li>Im <a href=\"https:\/\/www.johner-institut.de\/seminare\/produktentwicklung\/risikomanagement-und-iso-14971\/\"><strong>Seminar<\/strong> \u201eRisikomanagement &amp; ISO 14971\u201c<\/a> lernen Sie die gesetzlichen Anforderungen an das Risikomanagement kennen und erf\u00fcllen.<\/li>\r\n \t<li>Der <a href=\"https:\/\/www.johner-institut.de\/digitale-dienstleistungen\/auditgarant\/\"><strong>Auditgarant<\/strong><\/a> zeigt Ihnen mit Videotrainings, wie Sie Schritt f\u00fcr Schritt eine schlanke und ISO 14971 konforme Risikomanagementakte erstellen. Zus\u00e4tzlich nimmt Ihnen ein vollst\u00e4ndiger Satz an Templates f\u00fcr eine Risikomanagementakte viel Arbeit ab.<\/li>\r\n \t<li>Nutzen Sie auch die <strong>Unterst\u00fctzung<\/strong> des Risikomanagement-Teams. Es hilft Ihnen, Ihre <a href=\"https:\/\/www.johner-institut.de\/technische-dokumentation\/risikomanagement-iso-14971\/\">Akten zu schreiben, zu pr\u00fcfen<\/a> und auf Audits und Reviews vorzubereiten.<\/li>\r\n<\/ul>\r\n<a href=\"\/kontakt\/\"><strong>Melden Sie sich gleich<\/strong><\/a>, damit wir die n\u00e4chsten Schritte besprechen k\u00f6nnen. So stellen Sie sicher, dass die \u201eZulassung\u201c sicher gelingt und Ihre Produkte schnell in den Markt kommen.\r\n\r\n<\/div>","link":"https:\/\/www.johner-institut.de\/blog\/category\/iso-14971-risikomanagement\/","name":"Risikomanagement &amp; ISO 14971","slug":"iso-14971-risikomanagement","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Risikomanagement &amp; ISO 14971<\/title>\n<meta name=\"description\" content=\"Die ISO 14971 beschreibt f\u00fcr das Risikomanagement bei Medizinprodukten einen Prozess, den die Hersteller befolgen m\u00fcssen. Wie das geht!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.johner-institut.de\/blog\/category\/iso-14971-risikomanagement\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Risikomanagement &amp; ISO 14971\" \/>\n<meta property=\"og:description\" content=\"Die ISO 14971 beschreibt f\u00fcr das Risikomanagement bei Medizinprodukten einen Prozess, den die Hersteller befolgen m\u00fcssen. Wie das geht!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.johner-institut.de\/blog\/category\/iso-14971-risikomanagement\/\" \/>\n<meta property=\"og:site_name\" content=\"Regulatorisches Wissen f\u00fcr Medizinprodukte\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/04\/Regulatory-Affairs-Zulassung.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/category\\\/iso-14971-risikomanagement\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/category\\\/iso-14971-risikomanagement\\\/\",\"name\":\"Risikomanagement &amp; ISO 14971\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\"},\"description\":\"Die ISO 14971 beschreibt f\u00fcr das Risikomanagement bei Medizinprodukten einen Prozess, den die Hersteller befolgen m\u00fcssen. Wie das geht!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/category\\\/iso-14971-risikomanagement\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/category\\\/iso-14971-risikomanagement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Risikomanagement &amp; ISO 14971\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"name\":\"Regulatorisches Wissen f\u00fcr Medizinprodukte\",\"description\":\"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\",\"name\":\"Johner Institut GmbH\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"width\":1213,\"height\":286,\"caption\":\"Johner Institut GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JohnerInstitut\\\/\",\"https:\\\/\\\/x.com\\\/christianjohner\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/JohnerInstitut\"]}]}<\/script>\n<meta name=\"copyright\" content=\"Johner Institut GmbH\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Risikomanagement &amp; ISO 14971","description":"Die ISO 14971 beschreibt f\u00fcr das Risikomanagement bei Medizinprodukten einen Prozess, den die Hersteller befolgen m\u00fcssen. Wie das geht!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.johner-institut.de\/blog\/category\/iso-14971-risikomanagement\/","og_locale":"de_DE","og_type":"article","og_title":"Risikomanagement &amp; ISO 14971","og_description":"Die ISO 14971 beschreibt f\u00fcr das Risikomanagement bei Medizinprodukten einen Prozess, den die Hersteller befolgen m\u00fcssen. Wie das geht!","og_url":"https:\/\/www.johner-institut.de\/blog\/category\/iso-14971-risikomanagement\/","og_site_name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","og_image":[{"width":500,"height":433,"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/04\/Regulatory-Affairs-Zulassung.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.johner-institut.de\/blog\/category\/iso-14971-risikomanagement\/","url":"https:\/\/www.johner-institut.de\/blog\/category\/iso-14971-risikomanagement\/","name":"Risikomanagement &amp; ISO 14971","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/#website"},"description":"Die ISO 14971 beschreibt f\u00fcr das Risikomanagement bei Medizinprodukten einen Prozess, den die Hersteller befolgen m\u00fcssen. Wie das geht!","breadcrumb":{"@id":"https:\/\/www.johner-institut.de\/blog\/category\/iso-14971-risikomanagement\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.johner-institut.de\/blog\/category\/iso-14971-risikomanagement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.johner-institut.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Risikomanagement &amp; ISO 14971"}]},{"@type":"WebSite","@id":"https:\/\/www.johner-institut.de\/blog\/#website","url":"https:\/\/www.johner-institut.de\/blog\/","name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","description":"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen","publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.johner-institut.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.johner-institut.de\/blog\/#organization","name":"Johner Institut GmbH","url":"https:\/\/www.johner-institut.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","width":1213,"height":286,"caption":"Johner Institut GmbH"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JohnerInstitut\/","https:\/\/x.com\/christianjohner","https:\/\/www.youtube.com\/user\/JohnerInstitut"]}]}},"_links":{"self":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/categories\/1103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts?categories=1103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}