{"id":10836,"date":"2015-06-05T06:00:45","date_gmt":"2015-06-05T04:00:45","guid":{"rendered":"https:\/\/www.johner-institut.de\/blog\/?p=10836"},"modified":"2025-04-23T17:23:28","modified_gmt":"2025-04-23T15:23:28","slug":"design-review-ungleich-review-des-designs","status":"publish","type":"post","link":"https:\/\/www.johner-institut.de\/blog\/systems-engineering\/design-review-ungleich-review-des-designs\/","title":{"rendered":"Design Review ungleich Review des Designs!?"},"content":{"rendered":"\n<p>Auf die Frage, was ein Design Review sei, bekommt man h\u00e4ufig unterschiedliche Antworten &#8212; abh\u00e4ngig davon, ob man einen Entwickler oder&nbsp;einen Qualit\u00e4tsmanager fragt. Genau diese unterschiedlichen Sichten k\u00f6nnen im Audit zum Problem werden.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\" id=\"definition\">Begriffsdefinition: Was versteht man unter einem Design Review?<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/06\/Design-Review-ISO-13485.png\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"1434\" height=\"757\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/06\/Design-Review-ISO-13485.png\" alt=\"Design Review: Was die ISO-13485 und FDA darunter verstehen\" class=\"wp-image-10839\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/06\/Design-Review-ISO-13485.png 1434w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/06\/Design-Review-ISO-13485-300x158.png 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/06\/Design-Review-ISO-13485-1024x541.png 1024w\" sizes=\"auto, (max-width: 1434px) 100vw, 1434px\" \/><\/a><\/figure>\n\n\n\n<p>Viele&nbsp;Entwickler &#8222;missverstehen&#8220; unter dem Begriff <strong>Design Review<\/strong> ein <strong>Review des Designs<\/strong>. Bei einer eigenst\u00e4ndigen Software entspr\u00e4che letzteres dem, was die IEC 62304 mit&nbsp;der Verifizierung&nbsp; der Architektur bzw. des detaillierten Designs meint.&nbsp;Das entspricht aber nicht dem Design Review im Sinne der <a href=\"https:\/\/www.johner-institut.de\/blog\/category\/qualitaetsmanagement-iso-13485\/\">ISO 13485<\/a> und der FDA (<a href=\"https:\/\/www.ecfr.gov\/current\/title-21\/part-820\/section-820.30#p-820.30(e)\" target=\"_blank\" rel=\"noopener\">21 CFR part 820.30(e)<\/a>).&nbsp;<\/p>\n\n\n\n<p>Beide Regularien meinen mit dem Design Review die Bewertung&nbsp;der Entwicklung. Diese Bewertung&nbsp;sollte mehrfach w\u00e4hrend bzw. nach der Entwicklung stattfinden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ziele\">Ziele des Design Reviews<\/h2>\n\n\n\n<p>Das Design Review hat zum Ziel, innezuhalten und zu pr\u00fcfen, ob man&nbsp;noch auf dem richtigen Weg ist. Das betrifft Fragen wie:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Haben wir die richtigen Anforderungen unserer Kunden identifiziert?<\/li>\n\n\n\n<li>Sind die (bisherigen) Entwicklungsergebnisse geeignet, die Anforderungen zu erf\u00fcllen?<\/li>\n\n\n\n<li>Gibt es neue Erkenntnisse, die die Beteiligten kennen sollten?<\/li>\n\n\n\n<li>Wird&nbsp;das Produkt so entwickelt, dass es sp\u00e4ter problemlos produziert werden kann?<\/li>\n\n\n\n<li>Sind die Risiken im Sinn der <a href=\"https:\/\/www.johner-institut.de\/blog\/category\/iso-14971-risikomanagement\/\">ISO 14971<\/a> konsequent analysiert, den Beteiligten bekannt, und sind&nbsp;geeignete Ma\u00dfnahmen gefunden und implementiert?<\/li>\n\n\n\n<li>Ist das Projekt auf Spur? Liegt es im Zeitplan?<\/li>\n\n\n\n<li>Sind alle Dokumente erstellt, die zu diesem Projektfortschritt vorliegen sollten?<\/li>\n<\/ul>\n\n\n\n<p>Es geht also um weit mehr, als nur darum eine System- oder <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/software-architektur\">Software-Architektur<\/a> zu bewerten. Vielmehr soll dieses Design Review das Team synchronisieren und den ganzen Entwicklungsprozess kritisch hinterfragen.<\/p>\n\n\n\n<div class=\"jig_defbox\"><div class=\"jig_defbox-definition\"><div class=\"jig_defbox-icon-wrapper\"><\/div><span class=\"jig_defbox-header\" style=\"color:#919191\">Unterst\u00fctzung<\/span><\/div>\n<p>Ben\u00f6tigen Sie Unterst\u00fctzung dabei, ein ISO 13485 oder\/und FDA-konformes QM-System zu etablieren oder zu verbessern? Unser Expertenteam unterst\u00fctzt Sie gerne! <a href=\"https:\/\/www.johner-institut.de\/kontakt\/\">Nehmen Sie einfach Kontakt auf<\/a>.<\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"iso13485\">Design Review: Regulatorische Anforderungen<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Forderungen der ISO 13485 an die &#8222;Designbewertung&#8220;<\/h3>\n\n\n\n<p>Die ISO 13485\u00a0\u00fcbersetzt in Kapitel 7.3.5 \u00a0&#8222;Design and Development Review&#8220; als Entwicklungsbewertung. Die Norm verlangt diese Bewertungen &#8222;in geeigneten Phasen&#8220; mit dem Ziel, die F\u00e4higkeit zu beurteilen, ob die Design und Entwicklungsergebnisse die Anforderungen erf\u00fcllen und um Probleme zu erkennen sowie um notwendige\u00a0Ma\u00dfnahmen vorzuschlagen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Forderungen der FDA an das &#8222;Design Review&#8220;<\/h3>\n\n\n\n<p>Die FDA definiert ein &#8222;Design Review&#8220; als eine dokumentierte, vollst\u00e4ndige und systematische Untersuchung des Designs mit dem Ziel zu pr\u00fcfen, ob die Anforderungen an das Design ad\u00e4quat sind, ob das Design diese Anforderungen tats\u00e4chlich erf\u00fcllt, und um Probleme zu identifizieren. Der&nbsp;CFR part 820.30(e) formuliert die Anforderungen an das Design Review:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><cite>Each manufacturer shall establish and maintain procedures to ensure that formal documented reviews of the design results are planned and conducted at appropriate stages of the device&#8217;s design development.<\/cite><\/li>\n\n\n\n<li><cite>The procedures shall ensure that participants at each design review include representatives of all functions concerned with the design stage being reviewed and an individual(s) who does not have direct responsibility for the design stage being reviewed, as well as any specialists needed.<\/cite><\/li>\n\n\n\n<li><cite>The results of a design review, including identification of the design, the date, and the individual(s) performing the review, shall be documented in the design history file (the DHF).<\/cite><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"575\" height=\"403\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/06\/design-review-fda.gif\" alt=\"So illustriert die FDA Ihr Verst\u00e4ndnis dessen, was ein Design Review umfassen sollte.\" class=\"wp-image-10842\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Vergleich der&nbsp;Anforderungen der FDA und ISO 13485<\/h3>\n\n\n\n<p>Beide Regularien sehen als Ziele des Design Reviews:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Pr\u00fcfen, ob das Design die Anforderungen an das Produkt&nbsp;bzw. dessen Design erf\u00fcllt.<\/li>\n\n\n\n<li>Probleme identifizieren.<\/li>\n<\/ol>\n\n\n\n<p>Weiter fordern beide<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Reviews (Plural), also mehrere dieser Pr\u00fcfungen,<\/li>\n\n\n\n<li>die Beteiligung der notwendigen Vertreter<\/li>\n\n\n\n<li>die Design Reviews gem\u00e4\u00df eine dokumentierten Verfahrens durchzuf\u00fchren und die Ergebnisse ebenfalls zu dokumentieren.<\/li>\n<\/ol>\n\n\n\n<p>Beide Regularien sind somit nahezu deckungsgleich.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"plan\">Ein Design Review planen und durchf\u00fchren<\/h2>\n\n\n\n<p>Ein Design Review muss ein dokumentiertes Verfahren sein. Damit muss im QM-System festgelegt werden,<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>wann das Design Review stattfinden muss. Das kann z.B. zu bestimmten Zeitpunkten oder zum Ende bestimmter Phasen oder Meilenseine sein.<\/li>\n\n\n\n<li>welche&nbsp;Rollen an diesem Review teilnehmen. Wir empfehlen zumindest den Entwicklungsleiter, Qualit\u00e4tsmanager, Risikomanager, Produktmanager und Projektleiter.<\/li>\n\n\n\n<li>welche Aspekte beim Review zu pr\u00fcfen und<\/li>\n\n\n\n<li>wie die Ergebnisse zu dokumentieren sind.<\/li>\n<\/ul>\n\n\n\n<div class=\"jig_defbox\"><div class=\"jig_defbox-definition\"><div class=\"jig_defbox-icon-wrapper\"><\/div><span class=\"jig_defbox-header\" style=\"color:#919191\">Unterst\u00fctzung<\/span><\/div>\n<p>Wenn Sie Hilfe ben\u00f6tigen, eine ISO 13485-konforme Verfahrensanweisung (SOP) &nbsp;&#8222;Design Review&#8220; zu erstellen, wenn Sie Templates oder Checklisten ben\u00f6tigen oder Unterst\u00fctzung w\u00fcnschen, um <a href=\"https:\/\/www.johner-institut.de\/beratung\/iso-13485-und-qm-systeme\/qm-handbuch-erstellen\/\">Ihr QM-System mit&nbsp;wenigen Tagen unserer Hilfe vollst\u00e4ndig und auditsicher zu etablieren<\/a>, dann <a href=\"\/kontakt\/\">melden Sie sich bei uns<\/a>.<\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"audit\">Ein Design Review auditieren<\/h2>\n\n\n\n<p>Ein Auditor w\u00fcrde im Rahmen eines <a href=\"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/interne-audits-weiterbildung-zum-internen-auditor\/\">internen Audits<\/a> oder externen Audits beispielsweise&nbsp;folgende Aspekte pr\u00fcfen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bei welchen Meilensteinen oder zu welchen Zeitpunkten pr\u00fcft der Hersteller das Design?<\/li>\n\n\n\n<li>Wie erweitert&nbsp;sich der Schwerpunkt des Design Reviews, die sp\u00e4ter im Entwicklungsprozess stattfinden, auf die <a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/verifizierung-und-validierung-von-medizinprodukten\/\">Verifizierung und Validierung der Medizinprodukte<\/a>?<\/li>\n\n\n\n<li>Kann der Hersteller&nbsp;zeigen, auf welche Abweichungen oder Probleme er dabei gesto\u00dfen ist und welche Ma\u00dfnahmen ergriffen wurden?<\/li>\n\n\n\n<li>Welche Personen bzw. Rollen nahmen an den Reviews teil? Welche Spezialisten wurden ggf. hinzugezogen?<\/li>\n\n\n\n<li>Hat&nbsp;der Hersteller sowohl die Verfahrensanweisung als auch die Ergebnisse der Design Reviews sowie die getroffenen Ma\u00dfnahmen dokumentiert? Beziehen sich die Ergebnisse auf eine eindeutige Version eines Produkts? Ist die Verfahrensanweisung gelenkt?<\/li>\n<\/ul>\n\n\n\n<p>Unser Team besteht&nbsp;auch ISO 13485 Lead-Auditoren, die Ihnen bei Fragen gerne zur Verf\u00fcgung stehen. <a href=\"https:\/\/www.johner-institut.de\/beratung\/beratung-und-schulung\/kostenlose-beratung\/\">Auch kostenlos<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf die Frage, was ein Design Review sei, bekommt man h\u00e4ufig unterschiedliche Antworten &#8212; abh\u00e4ngig davon, ob man einen Entwickler oder&nbsp;einen Qualit\u00e4tsmanager fragt. Genau diese unterschiedlichen Sichten k\u00f6nnen im Audit zum Problem werden.<\/p>\n","protected":false},"author":131,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1091,1114],"tags":[1189,362],"ppma_author":[1259],"class_list":["post-10836","post","type-post","status-publish","format-standard","hentry","category-qualitaetsmanagement-iso-13485","category-systems-engineering","tag-prozesse-verfahren","tag-software-architektur","category-1091","category-1114","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Design Review ungleich Review des Designs!?<\/title>\n<meta name=\"description\" content=\"Ein Design Review entspricht nicht exakt einem Review des Designs. Sowohl die ISO 13485 und FDA fordern vergleichbare Design Reviews.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Design Review ungleich Review des Designs!?\" \/>\n<meta property=\"og:description\" content=\"Ein Design Review entspricht nicht exakt einem Review des Designs. Sowohl die ISO 13485 und FDA fordern vergleichbare Design Reviews.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/\" \/>\n<meta property=\"og:site_name\" content=\"Regulatorisches Wissen f\u00fcr Medizinprodukte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JohnerInstitut\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-05T04:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T15:23:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/06\/Design-Review-ISO-13485.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1434\" \/>\n\t<meta property=\"og:image:height\" content=\"757\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Claudia Schmitt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claudia Schmitt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/\"},\"author\":{\"name\":\"Claudia Schmitt\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/9917a825885704ffb65468eefc284c2c\"},\"headline\":\"Design Review ungleich Review des Designs!?\",\"datePublished\":\"2015-06-05T04:00:45+00:00\",\"dateModified\":\"2025-04-23T15:23:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/\"},\"wordCount\":864,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/Design-Review-ISO-13485.png\",\"keywords\":[\"Prozesse und Verfahren\",\"Software-Architektur (IEC-62304-konform)\"],\"articleSection\":[\"Qualit\u00e4tsmanagement &amp; ISO 13485\",\"Systems Engineering bei Medizinprodukten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/\",\"name\":\"Design Review ungleich Review des Designs!?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/Design-Review-ISO-13485.png\",\"datePublished\":\"2015-06-05T04:00:45+00:00\",\"dateModified\":\"2025-04-23T15:23:28+00:00\",\"description\":\"Ein Design Review entspricht nicht exakt einem Review des Designs. Sowohl die ISO 13485 und FDA fordern vergleichbare Design Reviews.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/Design-Review-ISO-13485.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/Design-Review-ISO-13485.png\",\"width\":1434,\"height\":757,\"caption\":\"Design Review: Was die ISO-13485 und FDA darunter verstehen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/qualitaetsmanagement-iso-13485\\\/design-review-ungleich-review-des-designs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Systems Engineering bei Medizinprodukten\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/category\\\/systems-engineering\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Design Review ungleich Review des Designs!?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"name\":\"Regulatorisches Wissen f\u00fcr Medizinprodukte\",\"description\":\"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\",\"name\":\"Johner Institut GmbH\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"width\":1213,\"height\":286,\"caption\":\"Johner Institut GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JohnerInstitut\\\/\",\"https:\\\/\\\/x.com\\\/christianjohner\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/JohnerInstitut\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/9917a825885704ffb65468eefc284c2c\",\"name\":\"Claudia Schmitt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Claudia_Schmitt_300x300.pngea5e86b34620bd37bb5697b88553ab6e\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Claudia_Schmitt_300x300.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Claudia_Schmitt_300x300.png\",\"caption\":\"Claudia Schmitt\"},\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/author\\\/claudiaschmitt\\\/\"}]}<\/script>\n<meta name=\"copyright\" content=\"Johner Institut GmbH\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Design Review ungleich Review des Designs!?","description":"Ein Design Review entspricht nicht exakt einem Review des Designs. Sowohl die ISO 13485 und FDA fordern vergleichbare Design Reviews.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/","og_locale":"de_DE","og_type":"article","og_title":"Design Review ungleich Review des Designs!?","og_description":"Ein Design Review entspricht nicht exakt einem Review des Designs. Sowohl die ISO 13485 und FDA fordern vergleichbare Design Reviews.","og_url":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/","og_site_name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","article_publisher":"https:\/\/www.facebook.com\/JohnerInstitut\/","article_published_time":"2015-06-05T04:00:45+00:00","article_modified_time":"2025-04-23T15:23:28+00:00","og_image":[{"width":1434,"height":757,"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/06\/Design-Review-ISO-13485.png","type":"image\/png"}],"author":"Claudia Schmitt","twitter_misc":{"Verfasst von":"Claudia Schmitt","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/#article","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/"},"author":{"name":"Claudia Schmitt","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/9917a825885704ffb65468eefc284c2c"},"headline":"Design Review ungleich Review des Designs!?","datePublished":"2015-06-05T04:00:45+00:00","dateModified":"2025-04-23T15:23:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/"},"wordCount":864,"commentCount":0,"publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/06\/Design-Review-ISO-13485.png","keywords":["Prozesse und Verfahren","Software-Architektur (IEC-62304-konform)"],"articleSection":["Qualit\u00e4tsmanagement &amp; ISO 13485","Systems Engineering bei Medizinprodukten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/","url":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/","name":"Design Review ungleich Review des Designs!?","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/#primaryimage"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/06\/Design-Review-ISO-13485.png","datePublished":"2015-06-05T04:00:45+00:00","dateModified":"2025-04-23T15:23:28+00:00","description":"Ein Design Review entspricht nicht exakt einem Review des Designs. Sowohl die ISO 13485 und FDA fordern vergleichbare Design Reviews.","breadcrumb":{"@id":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/#primaryimage","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/06\/Design-Review-ISO-13485.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/06\/Design-Review-ISO-13485.png","width":1434,"height":757,"caption":"Design Review: Was die ISO-13485 und FDA darunter verstehen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.johner-institut.de\/blog\/qualitaetsmanagement-iso-13485\/design-review-ungleich-review-des-designs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.johner-institut.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Systems Engineering bei Medizinprodukten","item":"https:\/\/www.johner-institut.de\/blog\/category\/systems-engineering\/"},{"@type":"ListItem","position":3,"name":"Design Review ungleich Review des Designs!?"}]},{"@type":"WebSite","@id":"https:\/\/www.johner-institut.de\/blog\/#website","url":"https:\/\/www.johner-institut.de\/blog\/","name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","description":"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen","publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.johner-institut.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.johner-institut.de\/blog\/#organization","name":"Johner Institut GmbH","url":"https:\/\/www.johner-institut.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","width":1213,"height":286,"caption":"Johner Institut GmbH"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JohnerInstitut\/","https:\/\/x.com\/christianjohner","https:\/\/www.youtube.com\/user\/JohnerInstitut"]},{"@type":"Person","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/9917a825885704ffb65468eefc284c2c","name":"Claudia Schmitt","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Claudia_Schmitt_300x300.pngea5e86b34620bd37bb5697b88553ab6e","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Claudia_Schmitt_300x300.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Claudia_Schmitt_300x300.png","caption":"Claudia Schmitt"},"url":"https:\/\/www.johner-institut.de\/blog\/author\/claudiaschmitt\/"}]}},"authors":[{"term_id":1259,"user_id":131,"is_guest":0,"slug":"claudiaschmitt","display_name":"Claudia Schmitt","avatar_url":{"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Claudia_Schmitt_300x300.png","url2x":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Claudia_Schmitt_300x300.png"},"author_category":"","first_name":"Claudia","last_name":"Schmitt","user_url":"","user_url_2":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/10836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/users\/131"}],"replies":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/comments?post=10836"}],"version-history":[{"count":5,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/10836\/revisions"}],"predecessor-version":[{"id":5381190,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/10836\/revisions\/5381190"}],"wp:attachment":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/media?parent=10836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/categories?post=10836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/tags?post=10836"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/ppma_author?post=10836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}