{"id":1176768,"date":"2018-04-17T08:00:50","date_gmt":"2018-04-17T07:00:50","guid":{"rendered":"https:\/\/www.johner-institut.de\/blog\/?p=1176768"},"modified":"2023-01-19T16:28:01","modified_gmt":"2023-01-19T15:28:01","slug":"eye-tracking","status":"publish","type":"post","link":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/","title":{"rendered":"Eye Tracking: 5 Gr\u00fcnde dagegen und 1 daf\u00fcr"},"content":{"rendered":"\n<p>Das Eye Tracking ist eine Methode im Usability Engineering, die den Blickverlauf von Personen erfasst und auswertet. Diese Ergebnisse erlauben Aussagen \u00fcber die <a href=\"https:\/\/www.johner-institut.de\/blog\/category\/iec-62366-usability\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gebrauchstauglichkeit<\/a> interaktiver Systeme wie Webseiten, physische Produkte und mobile Anwendungen.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">1. Wie Eye Tracking funktioniert<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">a) Cornea-Reflex-Methode<\/h3>\n\n\n\n<p>Die mobilen Eye Tracker \u00e4hneln einer Brille (s. Abb. 1), an der eine Lichtquelle (z.B. Infrarot) sowie zwei oder mehr Kameras angebracht sind.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Eye-Tracking.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Eye-Tracking-150x150.jpg\" alt=\"Eye Tracker\" class=\"wp-image-1176780\"\/><\/a><figcaption>Abb. 1: Eye Tracker, der eine Lichtquelle und kleine Kameras beinhaltet (zum Vergr\u00f6\u00dfern klicken)<\/figcaption><\/figure>\n\n\n\n<p>Die Lichtquelle blendet ein Muster auf die Hornhaut, welche dieses Muster reflektiert (Abb. 2).<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Puplille-Eye-Tracker.jpg\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"222\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Puplille-Eye-Tracker-300x222.jpg\" alt=\"Pupille reflektiert Muster des Eye Trackers\" class=\"wp-image-1176805\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Puplille-Eye-Tracker-300x222.jpg 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Puplille-Eye-Tracker-150x111.jpg 150w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Puplille-Eye-Tracker.jpg 383w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Abb. 2: Die Pupille reflektiert Muster des Eye Trackers<\/figcaption><\/figure>\n\n\n\n<p><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">Diese Reflektion nimmt eine Kamera auf, leitet das Signal an eine Software weiter, die daraus die Position des Auges berechnet (Cornea-Reflex-Methode)(Abb. 3)<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Eye-Tracking-Cornea-Reflektion.jpg\" data-rel=\"lightbox-image-2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"674\" height=\"233\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Eye-Tracking-Cornea-Reflektion.jpg\" alt=\"Eye Tracking nutzt die Cornea Reflection Methode\" class=\"wp-image-1176787\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Eye-Tracking-Cornea-Reflektion.jpg 674w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Eye-Tracking-Cornea-Reflektion-300x104.jpg 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Eye-Tracking-Cornea-Reflektion-150x52.jpg 150w\" sizes=\"auto, (max-width: 674px) 100vw, 674px\" \/><\/a><figcaption>Abb. 3: Aus dem Ort der Reflektion im Verh\u00e4ltnis zur Pupille kann man auf die Blickrichtung schlie\u00dfen<\/figcaption><\/figure>\n\n\n\n<p><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">Eine zweite Kamera, die Blickfeldkamera, nimmt den Sichtbereich des Probanden auf. Abbildung 4 zeigt das \u00fcberlagerte Signal.<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Eye-Tracker-Software.jpg\" data-rel=\"lightbox-image-3\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"453\" height=\"349\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Eye-Tracker-Software.jpg\" alt=\"Eye Tracker Software\" class=\"wp-image-1176799\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Eye-Tracker-Software.jpg 453w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Eye-Tracker-Software-300x231.jpg 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Eye-Tracker-Software-150x116.jpg 150w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/><\/a><figcaption>Abb. 4: Eine Software \u00fcberlagert die berechnete Blickrichtung und das Blickfeld des Anwenders<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">b) Datenaufbereitung<\/h3>\n\n\n\n<p>Die Software bereitet diese Daten weiter auf und stellt die Ergebnisse in Form von Videos, Heatmaps oder Blickpfade (\u201eGaze Plots\u201c, \u201eScanpath\u201c) dar (s. Abb. 5).<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Heatmap-Gazeplot.png\" data-rel=\"lightbox-image-4\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"548\" height=\"189\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Heatmap-Gazeplot.png\" alt=\"Heatmap Gazeplot\" class=\"wp-image-1176813\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Heatmap-Gazeplot.png 548w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Heatmap-Gazeplot-300x103.png 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Heatmap-Gazeplot-150x52.png 150w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><\/a><figcaption>Abb. 5: Als Ergebnis des Eyetrackig entstehen Heatmaps und eine Darstellung der Blickpfade (<a href=\"https:\/\/de.wikipedia.org\/wiki\/Eye-Tracking\" target=\"_blank\" rel=\"noopener noreferrer\">Quelle<\/a>)<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">c) Weiterf\u00fchrende Informationen<\/h3>\n\n\n\n<p>Ein Standardwerk stammt von Andrew Duchowski. Es tr\u00e4gt den Titel \u201e<em>Eye Tracking Methodology Theory and Practice<\/em>\u201d. Sie k\u00f6nnen das <a href=\"https:\/\/www.springer.com\/de\/book\/9781846286087\">Buch bei Springer<\/a> bestellen.<\/p>\n\n\n\n<div class=\"defbox\">\n<div class=\"definition\"><i class=\"fa fa-lightbulb-o\"><\/i> Tipp<\/div>\n<p>Alternativ f\u00fchrt eine Google-Suche nach dem Autor, dem Titel und gefolgt von \u201ePDF\u201c zu einem kostenlosen Download.<\/p>\n<\/div>\n\n\n\n<p>Ebenfalls nicht mehr ganz neu, aber immer noch relevant ist das <a href=\"https:\/\/www.nngroup.com\/books\/eyetracking-web-usability\/\">Buch von Jakob Nielsen und Kara Bernice<\/a> \u201c<em>Eyetracking Web Usability<\/em>\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. Bei welchen Fragestellungen Eye Tracking helfen kann<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">a) Eye Tracking zum Bewerten der Gebrauchstauglichkeit<\/h3>\n\n\n\n<p>Eye Tracking dient als Methode, um die Gebrauchstauglichkeit interaktiver Systeme zu bestimmen. Definitionsgem\u00e4\u00df muss eine solche Methode herausfinden, in welchem Ausma\u00df ein interaktives System die Nutzer dabei unterst\u00fctzt, die spezifizierten Nutzungsziele effektiv, effizient und zur Zufriedenstellung zu erreichen.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Usability-Effektivita\u0308t-Effizienz-Zufriedenheit.jpg\" data-rel=\"lightbox-image-5\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Usability-Effektivita\u0308t-Effizienz-Zufriedenheit-300x201.jpg\" alt=\"Usability: Die Pyramide aus Effektivita\u0308t, Effizienz und Zufriedenheit\" class=\"wp-image-1176819\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Usability-Effektivita\u0308t-Effizienz-Zufriedenheit-300x201.jpg 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Usability-Effektivita\u0308t-Effizienz-Zufriedenheit-150x101.jpg 150w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Usability-Effektivita\u0308t-Effizienz-Zufriedenheit.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Abb. 6: Die Gebrauchstauglichkeit ist gegeben, wenn Nutzer die Nutzungsziele effektiv, effizient und zur Zufriedenheit erreichen \u2013 in dieser Priorit\u00e4t.<\/figcaption><\/figure>\n\n\n\n<p>Das Eye Tracking ist allerdings nur teilweise geeignet, diese Aspekte Effektivit\u00e4t, Effizienz und Zufriedenstellung zu bewerten. Beispielsweise ist das Eye Tracking ungeeignet, um die Zufriedenstellung zu beurteilen.<\/p>\n\n\n\n<p>Daf\u00fcr kann das Eye Tracking hilfreich sein, um Ursachen f\u00fcr Usability Probleme zu identifizieren, also weshalb Nutzer die Nutzungsziele nicht, nicht ausreichend oder nicht ausreichend schnell erzielen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">b) Fragestellungen<\/h3>\n\n\n\n<p>Fragestellungen, zu denen das Eye Tracking Antworten liefern kann, sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Was nehmen die Nutzer wahr, was \u00fcbersehen sie?<\/li><li>Was ignorieren die Nutzer, z.B. wo scrollen sie nicht hin?<\/li><li>Weshalb ben\u00f6tigen Nutzer so viel Zeit? Wo halten sie sich wie lange auf?<\/li><li>In welcher Reihenfolge nehmen die Nutzer die Dinge wahr?<\/li><li>Wie homogen ist eine Nutzergruppe tats\u00e4chlich, wie sehr unterscheidet sich deren Wahrnehmung?<\/li><li>Wie unterscheiden sich zwei Produkte bzw. zwei Versionen eines Produkts bei der Nutzung? (A\/B-Testing, Vorher-Nachher-Vergleich)<\/li><li>Weshalb kommt es zu (bereits bekannten) Nutzungsfehlern? Was sind die Ursachen?<\/li><\/ul>\n\n\n\n<p>Bei Medizinprodukten l\u00e4sst sich das Eye Tracking einsetzen, um<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>&#8222;Beinahe-Fehler\u201c (\u201enear misses\u201c) zu finden,<\/li><li>verschiedene Entw\u00fcrfe schon w\u00e4hrend der Entwicklung zu \u00fcberpr\u00fcfen und zu vergleichen (formative Bewertung),<\/li><li>die Wirksamkeit von <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/risikominimierung\" target=\"_blank\" rel=\"noopener noreferrer\">risikominimierenden Ma\u00dfnahmen<\/a> an der Benutzerschnittstelle (z.B. Alarme, Hinweise) zu beurteilen und<\/li><li>das eigene Produkt mit Wettbewerbsprodukten zu vergleichen.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">c) Anwendungsf\u00e4lle<\/h3>\n\n\n\n<p>Typische Anwendungsf\u00e4lle des Eye Tracking sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Usability Testing\n<ul>\n<li>Produkte wie physische Produkte und Software (Apps, Webseiten, stand-alone Software)<\/li>\n<li>Trainings- und Begleitmaterialien z.B. <a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/gebrauchsanweisungen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gebrauchsanweisungen<\/a><\/li>\n<li>Verpackung<\/li>\n<\/ul>\n<\/li><li>Forschung z.B. Neurowissenschaft, Kognitionspsychologie<\/li><li>Werbung<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">3. Ablauf<\/h2>\n\n\n\n<p>Der Ablauf beim Eye Tracking weist viele Parallelen mit dem Ablauf bei <a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/usability-validierung\/\" target=\"_blank\" rel=\"noopener noreferrer\">Usability-Tests<\/a> auf. Auch hier sind die sorgf\u00e4ltige Planung und Vorbereitung die Voraussetzung f\u00fcr den Erfolg. Ein Unterschied besteht in der h\u00f6heren Anzahl an Probanden und der damit aufw\u00e4ndigeren Rekrutierung. Die zus\u00e4tzliche technische Ausstattung und das Kalibrieren bedeuten weitere Unterschiede.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Prozess-Eye-Tracking.jpg\" data-rel=\"lightbox-image-6\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"320\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Prozess-Eye-Tracking.jpg\" alt=\"Prozess beim Eye Tracking\" class=\"wp-image-1176824\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Prozess-Eye-Tracking.jpg 600w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Prozess-Eye-Tracking-300x160.jpg 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Prozess-Eye-Tracking-150x80.jpg 150w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption>Abb. 7: Typische Schritte beim Testen mit Eye Trackern<\/figcaption><\/figure>\n\n\n\n<div class=\"defbox\">\n<div class=\"definition\"><i class=\"fa fa-external-link\"><\/i> Weiterf\u00fchrende Informationen<\/div>\n<p>Lesen Sie hier mehr zur <a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/rekrutierung-von-probanden-fuer-usability-tests\/\" target=\"_blank\" rel=\"noopener noreferrer\">Rekrutierung von Probanden f\u00fcr Usability Tests<\/a>.<\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">4. Die 5 Gr\u00fcnde gegen das Testen mit Eye Trackern<\/h2>\n\n\n\n<p>Das Johner Institut empfiehlt Herstellern, die das Eye Tracking einsetzen m\u00f6chten, sich folgender Herausforderungen bewusst zu sein:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li><strong>Hoher Aufwand und Kosten<\/strong><br>Um aussagekr\u00e4ftige Daten zu erhalten, insbesondere belastbare Heatmaps, bedarf es vieler Probanden. Nielsen empfiehlt in seinem <a href=\"http:\/\/media.nngroup.com\/media\/reports\/free\/How_to_Conduct_Eyetracking_Studies.pdf\">Report zum Eye Tracking<\/a> 30 Benutzer. Da erfahrungsgem\u00e4\u00df nicht alle Messungen klappen und alle Teilnehmer geeignet sind, empfiehlt er sogar mit <strong>39 Probanden<\/strong> zu starten.<br>Die Aufw\u00e4nde f\u00fcr die Rekrutierung, Insentivierung und Durchf\u00fchrung sind entsprechend hoch. Dazu kommen die Kosten f\u00fcr die Eye Tracker, die Software und die Ausstattung zur Verwaltung der Aufzeichnung.<\/li><li><strong>Technische Herausforderungen<br><\/strong>Die Kalibrierung stellt regelm\u00e4\u00dfig eine Herausforderung dar. Bei Probanden, die Brillen oder Kontaktlinsen tragen oder die eine sehr aktive Mimik haben, sind die Messungen erschwert. Ung\u00fcnstige Lichtverh\u00e4ltnisse beeinflussen die Effizienz (und manchmal auch Effektivit\u00e4t) der Messung.<\/li><li><strong>Irref\u00fchrende Ergebnisse<br><\/strong>Die Ergebnisse verleiten gelegentlich zu falschen Schlussfolgerungen. Beispielsweise erscheint es, als w\u00fcrden die Probanden ein Navigationsmen\u00fc ignorieren. Tats\u00e4chlich haben sie dieses Men\u00fc auf einer anderen Seite l\u00e4ngst gesehen und ben\u00f6tigen es an dieser Stelle nicht mehr.<br>Weitere Artefakte entstehen durch die o.g. technischen Probleme wie falsche Kalibrierung, oder durch unterschiedliche Sitzpositionen und Blickrichtungen.<br>Offensichtlich beeinflusst auch die Aufgabenstellung die Ergebnisse. Die Bitte, nach etwas zu suchen, wird andere Ergebnisse produzieren als der Auftrag, eine Aufgabe zu erledigen, innerhalb derer eine solche Suche notwendig w\u00e4re.<\/li><li><strong>Beschr\u00e4nkte Aussagekraft<br><\/strong>Selbst wenn das Eye Tracking offenbart, dass ein Nutzer auf etwas blickt, sagt das weder etwas dar\u00fcber aus, ob er es wirklich wahrnimmt, noch ob er das Wahrgenommene auch versteht.<br>Die periphere Wahrnehmung erfasst das Eye Tracking gar nicht.<br>Heatmaps und Darstellungen der Blickpfade sind beeindruckend. Doch die Interpretation der Daten und die Schlussfolgerungen sind herausfordernd. So tun sich viele Hersteller schwer, aus diesen Ergebnissen konkrete \u00c4nderungen an der Nutzungsschnittstelle abzuleiten.<\/li><li><strong>Experten<br><\/strong>Mit dem Kauf eines Eye Trackers ist wenig erreicht. \u201eA fool with a tool is still a fool\u201c. Es bedarf viel Erfahrung, um Eye Tracking Studien zu planen und durchzuf\u00fchren sowie die Ergebnisse zu interpretieren und die richtigen Schlussfolgerungen zu ziehen. Hersteller sollten entweder eigene Mitarbeiter qualifizieren oder externe Experten nutzen.<br>Selbst diese Experten schalten einer Eye-Tracking-Studie meist eine Pilotierungsphase voraus, um das Studienprotokoll, die Technologie und Datenauswertung zu erproben.<\/li><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Fazit<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Vieles spricht dagegen<\/h3>\n\n\n\n<p>Bei so vielen Gr\u00fcnden, die gegen das Testen mit Eye Trackern sprechen, stellt sich die Frage, ob diese Methode \u00fcberhaupt genutzt werden sollte. Jakob Nielsen stellt genau diese Frage und beantwortet sie auch gleich selbst: \u201e<em>Should you use eyetacking in your usability studies? Probably not<\/em>\u201d.<\/p>\n\n\n\n<p>Wenn man die Methode doch nutzen m\u00f6chte, r\u00e4t er den meisten (\u201e<em>vast majority of companies in the world<\/em>\u201c) davon ab, es selbst zu tun, und daf\u00fcr auf Experten zu setzen.<\/p>\n\n\n\n<p>Das Eye Tracking ist wie bereits ausgef\u00fchrt keine Methode, die Aussagen zur Zufriedenheit der Nutzer erlaubt. Es ist auch keine Methode, um die Korrektheit und Vollst\u00e4ndigkeit der Arbeitsergebnisse (\u00e0 Effektivit\u00e4t) zu beurteilen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ein Grund spricht daf\u00fcr<\/h3>\n\n\n\n<p>Trotzdem nutzt das Johner Institut gelegentlich das Eye Tracking, um die <a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/formative-bewertung\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gebrauchstauglichkeit von Medizinprodukte formativ zu bewerten<\/a>. Daf\u00fcr gibt es einen Grund bzw. Anlass:<\/p>\n\n\n\n<p>Die anderen Testverfahren reichen nicht aus, um die Risiken zu identifizieren oder die Ursachen f\u00fcr <a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/user-errors-use-errors\/\" target=\"_blank\" rel=\"noopener noreferrer\">Nutzungsfehler<\/a> zu finden. Beispiele f\u00fcr solche Situationen sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Im Usability Lab lassen sich Situationen wie z.B. eine OP an einem Menschen oder Stresssituationen nicht ausreichend gut simulieren.<\/li><li>Probanden aus anderen Kulturen trauen sich nicht, beim \u201eThink Aloud\u201c Kritik am Produkt oder Verbesserungsvorschl\u00e4ge zu \u00e4u\u00dfern.<\/li><li>Es ist unklar, ob und wenn ja weshalb Anwender Informationen wie Warnungen \u00fcbersehen, obwohl diese nach Ansicht des Herstellers \u00fcberdeutlich dargestellt sind.<\/li><li>Man wei\u00df nicht, welche Teile einer <a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/gebrauchsanweisungen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gebrauchsanweisung<\/a> die Anwender \u00fcberhaupt lesen.<\/li><\/ul>\n\n\n\n<p>In anderen Worten:<\/p>\n\n\n\n<p><strong>Hersteller sollten das Eye Tracking nur als Erg\u00e4nzung f\u00fcr das klassische Usability Testing verwenden, niemals als Ersatz daf\u00fcr.<\/strong><\/p>\n\n\n\n<p>Einige Fragestellung lassen sich mit alternativen Methoden wie \u201eWebrecordern\u201c, welche die Mausbewegungen aufzeichnen, einfacher beantworten.<\/p>\n\n\n\n<p>Eines bleibt aber unbestritten: Die Ergebnisse wie Heatmaps und Blickpfade sind illustrativ, (scheinbar) leicht vermittelbar und beim Marketing hilfreich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Eye Tracking ist eine Methode im Usability Engineering, die den Blickverlauf von Personen erfasst und auswertet. Diese Ergebnisse erlauben Aussagen \u00fcber die Gebrauchstauglichkeit interaktiver Systeme wie Webseiten, physische Produkte und mobile Anwendungen.<\/p>\n","protected":false},"author":1,"featured_media":1176805,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1102],"tags":[839],"ppma_author":[1210],"class_list":["post-1176768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iec-62366-usability","tag-risikominimierung","category-1102","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eye Tracking: 5 Gr\u00fcnde dagegen und 1 daf\u00fcr<\/title>\n<meta name=\"description\" content=\"Das Eye Tracking ist eine beliebte Methode, um die Usability zu testen. Das Johner Institut warnt vor falschen Erwartungen und empfiehlt es nur bei bestimmten Fragestellungen [Liste mit 5 Fehlern]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eye Tracking: 5 Gr\u00fcnde dagegen und 1 daf\u00fcr\" \/>\n<meta property=\"og:description\" content=\"Das Eye Tracking ist eine beliebte Methode, um die Usability zu testen. Das Johner Institut warnt vor falschen Erwartungen und empfiehlt es nur bei bestimmten Fragestellungen [Liste mit 5 Fehlern]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/\" \/>\n<meta property=\"og:site_name\" content=\"Regulatorisches Wissen f\u00fcr Medizinprodukte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JohnerInstitut\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-17T07:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-19T15:28:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Puplille-Eye-Tracker.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"383\" \/>\n\t<meta property=\"og:image:height\" content=\"284\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Prof. Dr. Christian Johner\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prof. Dr. Christian Johner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/\"},\"author\":{\"name\":\"Prof. Dr. Christian Johner\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/77ee54cd54e987c0b5738d4cb4c80441\"},\"headline\":\"Eye Tracking: 5 Gr\u00fcnde dagegen und 1 daf\u00fcr\",\"datePublished\":\"2018-04-17T07:00:50+00:00\",\"dateModified\":\"2023-01-19T15:28:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/\"},\"wordCount\":1360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Puplille-Eye-Tracker.jpg\",\"keywords\":[\"Risikobeherrschung | Risikominimierung\"],\"articleSection\":[\"Usability &amp; IEC 62366-1\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/\",\"name\":\"Eye Tracking: 5 Gr\u00fcnde dagegen und 1 daf\u00fcr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Puplille-Eye-Tracker.jpg\",\"datePublished\":\"2018-04-17T07:00:50+00:00\",\"dateModified\":\"2023-01-19T15:28:01+00:00\",\"description\":\"Das Eye Tracking ist eine beliebte Methode, um die Usability zu testen. Das Johner Institut warnt vor falschen Erwartungen und empfiehlt es nur bei bestimmten Fragestellungen [Liste mit 5 Fehlern]\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Puplille-Eye-Tracker.jpg\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Puplille-Eye-Tracker.jpg\",\"width\":383,\"height\":284,\"caption\":\"Pupille reflektiert Muster des Eye Trackers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62366-usability\\\/eye-tracking\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Usability &amp; IEC 62366-1\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/category\\\/iec-62366-usability\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eye Tracking: 5 Gr\u00fcnde dagegen und 1 daf\u00fcr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"name\":\"Regulatorisches Wissen f\u00fcr Medizinprodukte\",\"description\":\"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\",\"name\":\"Johner Institut GmbH\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"width\":1213,\"height\":286,\"caption\":\"Johner Institut GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JohnerInstitut\\\/\",\"https:\\\/\\\/x.com\\\/christianjohner\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/JohnerInstitut\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/77ee54cd54e987c0b5738d4cb4c80441\",\"name\":\"Prof. Dr. Christian Johner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Christian_Johner.jpgab057afc2debeb41aaf55cce7e79e618\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Christian_Johner.jpg\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Christian_Johner.jpg\",\"caption\":\"Prof. Dr. Christian Johner\"},\"description\":\"Professor Johner ist Experte f\u00fcr die Entwicklung und Zulassung von Medizinprodukten, die Software enthalten oder Software sind. Als Auditor, als Mitglied eines Normen-Komitees, als Ausbilder benannter Stellen sowie als Autor mehrerer B\u00fccher und Leitf\u00e4den tr\u00e4gt der promovierte Physiker zur Weiterentwicklung der regulatorischen Landschaft bei. Davon zeugen auch Leitf\u00e4den, die er f\u00fcr die WHO und die Benannten Stellen entwickelt hat. Sein Unternehmen, das Johner Institut, unterst\u00fctzt Medizinproduktehersteller weltweit beim Aufbau von QM-Systemen, bei der Zulassung und Pr\u00fcfung ihrer Produkte sowie bei der digitalen Transformation regulatorischer Prozesse. Es bietet Weiterbildungen wie E-Learning und Seminare an und \u00fcbernimmt f\u00fcr Hersteller Prozesse wie die \u00dcberwachung der Regularien und der Produkte im Markt. Christian Johner lehrte an mehreren Universit\u00e4ten u.a. an der Hochschule Konstanz, der Universit\u00e4t St. Gallen, der Universit\u00e4t W\u00fcrzburg sowie der Stanford University v.a. Software-Architektur, Software-Qualit\u00e4tssicherung und medizinische Informatik.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/christianjohner\\\/\",\"https:\\\/\\\/x.com\\\/christianjohner\"],\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/author\\\/christian\\\/\"}]}<\/script>\n<meta name=\"copyright\" content=\"Johner Institut GmbH\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eye Tracking: 5 Gr\u00fcnde dagegen und 1 daf\u00fcr","description":"Das Eye Tracking ist eine beliebte Methode, um die Usability zu testen. Das Johner Institut warnt vor falschen Erwartungen und empfiehlt es nur bei bestimmten Fragestellungen [Liste mit 5 Fehlern]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/","og_locale":"de_DE","og_type":"article","og_title":"Eye Tracking: 5 Gr\u00fcnde dagegen und 1 daf\u00fcr","og_description":"Das Eye Tracking ist eine beliebte Methode, um die Usability zu testen. Das Johner Institut warnt vor falschen Erwartungen und empfiehlt es nur bei bestimmten Fragestellungen [Liste mit 5 Fehlern]","og_url":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/","og_site_name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","article_publisher":"https:\/\/www.facebook.com\/JohnerInstitut\/","article_published_time":"2018-04-17T07:00:50+00:00","article_modified_time":"2023-01-19T15:28:01+00:00","og_image":[{"width":383,"height":284,"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Puplille-Eye-Tracker.jpg","type":"image\/jpeg"}],"author":"Prof. Dr. Christian Johner","twitter_misc":{"Verfasst von":"Prof. Dr. Christian Johner","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/#article","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/"},"author":{"name":"Prof. Dr. Christian Johner","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/77ee54cd54e987c0b5738d4cb4c80441"},"headline":"Eye Tracking: 5 Gr\u00fcnde dagegen und 1 daf\u00fcr","datePublished":"2018-04-17T07:00:50+00:00","dateModified":"2023-01-19T15:28:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/"},"wordCount":1360,"commentCount":0,"publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Puplille-Eye-Tracker.jpg","keywords":["Risikobeherrschung | Risikominimierung"],"articleSection":["Usability &amp; IEC 62366-1"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/","url":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/","name":"Eye Tracking: 5 Gr\u00fcnde dagegen und 1 daf\u00fcr","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/#primaryimage"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Puplille-Eye-Tracker.jpg","datePublished":"2018-04-17T07:00:50+00:00","dateModified":"2023-01-19T15:28:01+00:00","description":"Das Eye Tracking ist eine beliebte Methode, um die Usability zu testen. Das Johner Institut warnt vor falschen Erwartungen und empfiehlt es nur bei bestimmten Fragestellungen [Liste mit 5 Fehlern]","breadcrumb":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/#primaryimage","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Puplille-Eye-Tracker.jpg","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Puplille-Eye-Tracker.jpg","width":383,"height":284,"caption":"Pupille reflektiert Muster des Eye Trackers"},{"@type":"BreadcrumbList","@id":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/eye-tracking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.johner-institut.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Usability &amp; IEC 62366-1","item":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62366-usability\/"},{"@type":"ListItem","position":3,"name":"Eye Tracking: 5 Gr\u00fcnde dagegen und 1 daf\u00fcr"}]},{"@type":"WebSite","@id":"https:\/\/www.johner-institut.de\/blog\/#website","url":"https:\/\/www.johner-institut.de\/blog\/","name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","description":"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen","publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.johner-institut.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.johner-institut.de\/blog\/#organization","name":"Johner Institut GmbH","url":"https:\/\/www.johner-institut.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","width":1213,"height":286,"caption":"Johner Institut GmbH"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JohnerInstitut\/","https:\/\/x.com\/christianjohner","https:\/\/www.youtube.com\/user\/JohnerInstitut"]},{"@type":"Person","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/77ee54cd54e987c0b5738d4cb4c80441","name":"Prof. Dr. Christian Johner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpgab057afc2debeb41aaf55cce7e79e618","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpg","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpg","caption":"Prof. Dr. Christian Johner"},"description":"Professor Johner ist Experte f\u00fcr die Entwicklung und Zulassung von Medizinprodukten, die Software enthalten oder Software sind. Als Auditor, als Mitglied eines Normen-Komitees, als Ausbilder benannter Stellen sowie als Autor mehrerer B\u00fccher und Leitf\u00e4den tr\u00e4gt der promovierte Physiker zur Weiterentwicklung der regulatorischen Landschaft bei. Davon zeugen auch Leitf\u00e4den, die er f\u00fcr die WHO und die Benannten Stellen entwickelt hat. Sein Unternehmen, das Johner Institut, unterst\u00fctzt Medizinproduktehersteller weltweit beim Aufbau von QM-Systemen, bei der Zulassung und Pr\u00fcfung ihrer Produkte sowie bei der digitalen Transformation regulatorischer Prozesse. Es bietet Weiterbildungen wie E-Learning und Seminare an und \u00fcbernimmt f\u00fcr Hersteller Prozesse wie die \u00dcberwachung der Regularien und der Produkte im Markt. Christian Johner lehrte an mehreren Universit\u00e4ten u.a. an der Hochschule Konstanz, der Universit\u00e4t St. Gallen, der Universit\u00e4t W\u00fcrzburg sowie der Stanford University v.a. Software-Architektur, Software-Qualit\u00e4tssicherung und medizinische Informatik.","sameAs":["https:\/\/www.linkedin.com\/in\/christianjohner\/","https:\/\/x.com\/christianjohner"],"url":"https:\/\/www.johner-institut.de\/blog\/author\/christian\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/04\/Puplille-Eye-Tracker.jpg","jetpack-related-posts":[{"id":12605,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/summative-evaluierung\/","url_meta":{"origin":1176768,"position":0},"title":"Summative Evaluierung: Auf diese Punkte m\u00fcssen Sie achten","author":"Dr. Philipp Schleer","date":"12. April 2024","format":false,"excerpt":"Der Begriff summative Evaluation l\u00e4sst sich mit \u201eabschlie\u00dfender Bewertung\u201c \u00fcbersetzen. Eine summative Evaluation pr\u00fcft am Ende der Entwicklungsphase, ob Anwender ein Produkt bzw. ein User Interface sicher bedienen k\u00f6nnen. Dieser Beitrag verschafft Ihnen einen \u00dcberblick \u00fcber die regulatorischen Anforderungen an die \u201csummative Bewertung\u201c (manchmal auch als \"summative assessment\" bezeichnet) und\u2026","rel":"","context":"In &quot;Usability &amp; IEC 62366-1&quot;","block_context":{"text":"Usability &amp; IEC 62366-1","link":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62366-usability\/"},"img":{"alt_text":"Summative Evaluierung","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/02\/Summative-Evaluierung.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/02\/Summative-Evaluierung.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/02\/Summative-Evaluierung.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/02\/Summative-Evaluierung.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1203570,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/personas\/","url_meta":{"origin":1176768,"position":1},"title":"&#8218;Personas&#8216;: die 5 h\u00e4ufigsten Fehler vermeiden","author":"Prof. Dr. Christian Johner","date":"8. Mai 2018","format":false,"excerpt":"Viele Firmen verwenden\u00a0Personas als Methode im Usability und Requirements Engineering. Eine Persona ist eine fiktive Person, die als repr\u00e4sentativer Vertreter einer Gruppe dient, typischerweise einer Gruppe potenzieller Benutzer eines Systems. Besonders in der agilen Software-Entwicklung sowie bei Marketing- und Design-Agenturen sind Personas beliebt. Doch die Methode wird h\u00e4ufig missverstanden und\u2026","rel":"","context":"In &quot;Usability &amp; IEC 62366-1&quot;","block_context":{"text":"Usability &amp; IEC 62366-1","link":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62366-usability\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/05\/Personas-Beispiel-klein.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/05\/Personas-Beispiel-klein.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/05\/Personas-Beispiel-klein.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1140923,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/heuristische-evaluation\/","url_meta":{"origin":1176768,"position":2},"title":"Heuristische Evaluation von Medizinprodukten","author":"Dr. Philipp Schleer","date":"26. M\u00e4rz 2019","format":false,"excerpt":"Die heuristische Evaluation ist ein Verfahren, mit dem Usability-Experten die Gebrauchstauglichkeit von Produkten anhand von Heuristiken (dazu gleich mehr) beurteilen. Dieser Artikel zeigt, wie Sie heuristische Evaluationen nutzen k\u00f6nnen, um die regulatorischen Anforderungen ans Usability Engineering sehr schnell und kosteng\u00fcnstig zu erf\u00fcllen. Er verr\u00e4t Ihnen auch, weshalb Sie die heuristische\u2026","rel":"","context":"In &quot;Usability &amp; IEC 62366-1&quot;","block_context":{"text":"Usability &amp; IEC 62366-1","link":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62366-usability\/"},"img":{"alt_text":"Heuristische Evaluation: Heuristiken versus Prinzipien","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/03\/Heuristische-Evaluation.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/03\/Heuristische-Evaluation.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/03\/Heuristische-Evaluation.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/03\/Heuristische-Evaluation.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6982,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/nutzerbefragung\/","url_meta":{"origin":1176768,"position":3},"title":"Nutzerbefragung zur Bewertung der Usability?","author":"Dr. Philipp Schleer","date":"14. Mai 2025","format":false,"excerpt":"Die Nutzerbefragung nutzen\u00a0viele Medizinproduktehersteller, um die Gebrauchstauglichkeit ihrer Produkte zu bewerten. Doch\u00a0als einzige Methode angewendet sind Nutzerbefragungen nicht geeignet, um die regulatorischen Anforderungen zu erf\u00fcllen. \u00a0 Qualitative\u00a0und quantitative\u00a0Nutzerbefragungen Man unterscheidet quantitative und qualitative Nutzerbefragungen. Beide verfolgen\u00a0unterschiedliche Ziele. Qualitative Nutzerbefragungen: Interviews Unter qualitativen Nutzerbefragungen versteht man Einzelinterviews, die das Ziel verfolgen,\u2026","rel":"","context":"In &quot;Usability &amp; IEC 62366-1&quot;","block_context":{"text":"Usability &amp; IEC 62366-1","link":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62366-usability\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":15872,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/formative-bewertung\/","url_meta":{"origin":1176768,"position":4},"title":"Formative Bewertung: Was die FDA und IEC 62366 verlangen","author":"Dr. Philipp Schleer","date":"13. Februar 2023","format":false,"excerpt":"Formative Bewertung, formatives Assessment und formative Evaluation sind synonyme und die eingedeutschten und nicht korrekt \u00fcbersetzten Versionen des englischen Begriffs \u201eformative evaluation\u201c. Die f\u00fcr das Usability Engineering relevanten Regularien fordern eine solche formative\u00a0Bewertungen. Lesen Sie in einem weiteren Artikel mehr zur summativen Bewertung. 1. Formative Bewertung: Definition und Abgrenzung a)\u2026","rel":"","context":"In &quot;Usability &amp; IEC 62366-1&quot;","block_context":{"text":"Usability &amp; IEC 62366-1","link":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62366-usability\/"},"img":{"alt_text":"Formative Bewertung \/ Evaluierung","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/07\/Formative-Bewertung-Evaluierung.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/07\/Formative-Bewertung-Evaluierung.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/07\/Formative-Bewertung-Evaluierung.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/07\/Formative-Bewertung-Evaluierung.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11277,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/user-experience\/","url_meta":{"origin":1176768,"position":5},"title":"User Experience ungleich Usability","author":"Dr. Philipp Schleer","date":"12. Mai 2025","format":false,"excerpt":"Viele Firmen verwechseln \"User Experience\" (Benutzungserlebnis) mit \"Usability\" (Gebrauchstauglichkeit), was zu Irritationen nicht nur bei Audits f\u00fchrt. Dieser Beitrag grenzt die beiden Begriffe voneinander ab und verr\u00e4t, wie sie beides pr\u00fcfen k\u00f6nnen. Definitionen Definition von \"User Experience\" (Benutzungserlebnis) Die ISO 9241-210:2011 definiert \"User Experience\" als Wahrnehmungen und Reaktionen einer Person,\u2026","rel":"","context":"In &quot;Usability &amp; IEC 62366-1&quot;","block_context":{"text":"Usability &amp; IEC 62366-1","link":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62366-usability\/"},"img":{"alt_text":"Die User Experience umfasst die Usability, geht aber dar\u00fcber hinaus","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/User-Experience-versus-Usability-1024x539.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/User-Experience-versus-Usability-1024x539.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/User-Experience-versus-Usability-1024x539.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pavawf-4W88","jetpack_sharing_enabled":true,"authors":[{"term_id":1210,"user_id":1,"is_guest":0,"slug":"christian","display_name":"Prof. Dr. Christian Johner","avatar_url":{"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpg","url2x":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":""}],"_links":{"self":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/1176768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/comments?post=1176768"}],"version-history":[{"count":7,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/1176768\/revisions"}],"predecessor-version":[{"id":3825170,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/1176768\/revisions\/3825170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/media\/1176805"}],"wp:attachment":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/media?parent=1176768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/categories?post=1176768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/tags?post=1176768"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/ppma_author?post=1176768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}