{"id":13041,"date":"2024-07-09T14:56:00","date_gmt":"2024-07-09T12:56:00","guid":{"rendered":"https:\/\/www.johner-institut.de\/blog\/?p=13041"},"modified":"2024-07-20T18:22:35","modified_gmt":"2024-07-20T16:22:35","slug":"regressionstest","status":"publish","type":"post","link":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/","title":{"rendered":"Regressionstest: Ihre Software-Versicherung"},"content":{"rendered":"\n<p>Unter einem Regressionstest verstehen die meisten Software-Tester die Wiederholung eines bestehenden Tests. Damit m\u00f6chten sie pr\u00fcfen, ob dieser Test nach einer Software-\u00c4nderung noch immer erfolgreich durchl\u00e4uft.<\/p>\n\n\n\n<div class=\"blog-column\">Lesen Sie in diesem Beitrag, was Sie bei einem Regressionstest von medizinscher Software beachten sollten.<\/div>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ziele\">1. Ziele von Regressionstests<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Ziel 1: \u201eAlter Code funktioniert noch\u201c<\/h3>\n\n\n\n<p>Normen wie die <a href=\"https:\/\/www.johner-institut.de\/blog\/category\/iec-62304-medizinische-software\/\">IEC 62304<\/a>\u00a0fordern eine Regressionspr\u00fcfung, um festzustellen, dass die \u00c4nderung einer SYSTEM-Komponente deren Funktionalit\u00e4t, Zuverl\u00e4ssigkeit und Leistungsf\u00e4higkeit nicht beeintr\u00e4chtigt und keine zus\u00e4tzlichen Defekte verursacht hat.<\/p>\n\n\n\n<p>Damit wird das Ziel eines Regressionstests aus Sicht der IEC 62304 klar: Durch eine Software-\u00c4nderung verursachte Fehler in bereits getestetem Code finden.<\/p>\n\n\n\n<p>Die <a href=\"https:\/\/www.johner-institut.de\/blog\/category\/fda\/\">FDA<\/a> formuliert das in ihrem Software Validation Guide fast identisch:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Regression testing is the rerunning of test cases that a program has previously executed correctly and comparing the current result to the previous result in order to detect unintended effects of a software change.<\/em><\/p>\n<cite>Quelle: <a href=\"https:\/\/www.fda.gov\/regulatory-information\/search-fda-guidance-documents\/general-principles-software-validation\">FDA Software-Validation Guidance<\/a><\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">Ziel 2: \u201eCode funktioniert zuverl\u00e4ssig\u201c<\/h3>\n\n\n\n<p>Ein zweites Ziel erw\u00e4hnt die IEC 62304 nicht: Ein Regressionstest kann auch pr\u00fcfen, ob sich eine Software dauerhaft gleich verh\u00e4lt, ohne dass man sie \u00e4ndert. Solche Pr\u00fcfungen empfehlen sich, wenn sich die Software nicht streng deterministisch verh\u00e4lt, z. B.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>bei Race-Conditions,<\/li>\n\n\n\n<li>bei \u00c4nderungen an der Laufzeitumgebung, beispielsweise der Hardware oder dem Betriebssystem<\/li>\n\n\n\n<li>oder bei der Abh\u00e4ngigkeit von (sich \u00e4ndernden) Daten.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"regularien\">2. Regressionstest: Regulatorische Anforderungen<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">a) Anforderungen der IEC 62304<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Regressionstest w\u00e4hrend der Integrationspr\u00fcfung<\/h4>\n\n\n\n<p>Die IEC 62304 fordert, Regressionspr\u00fcfungen\/Regressionstests im Rahmen der <a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/integrationstests-gemaess-iec-62304\/\">Integrationspr\u00fcfung\/Integrationstests<\/a>. Damit soll sichergestellt werden, dass bei der Integration neuer <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/software-komponente\">Komponenten<\/a> in einen bereits integrierten Teil von Komponenten keine Fehler eingef\u00fchrt werden. Welche Fehler das sein k\u00f6nnten, beschreibt die Norm nicht.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Regressionstest bei \u00c4nderungen am Software-System<\/h4>\n\n\n\n<p>Erwartungsgem\u00e4\u00df fordert die Norm eine Regressionspr\u00fcfung bei \u00c4nderungen am Software-System. Auch bei kleinen \u00c4nderungen, wie sie betont.<\/p>\n\n\n\n<p>Die Hersteller m\u00fcssen zudem begr\u00fcnden, wenn sie nach einer \u00c4nderung nicht alle Regressionstests erneut durchf\u00fchren. Lesen Sie weiter unten mehr zu diesem Punkt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">b) Anforderungen der FDA<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Regressionstest bei \u00c4nderungen an der Software<\/h4>\n\n\n\n<p>Die FDA betont, dass 79 % aller Software-Fehler bei der \u00c4nderung einer bereits freigegebenen Software eingef\u00fchrt werden. Entsprechend betont sie die Notwendigkeit von Regressionstests:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Whenever software is changed, a validation analysis should be conducted not just for validation of the individual change, but also to determine the extent and impact of that change on the entire software system. Based on this analysis, the software developer should then conduct an appropriate level of software regression testing to show that unchanged but vulnerable portions of the system have not been adversely affected. Design controls and appropriate regression testing provide the confidence that the software is validated after a software change.<\/p>\n<cite>FDA Software Validation Guidance<\/cite><\/blockquote>\n\n\n\n<p>\u00c4hnlich wie die IEC 62304 verlangt die FDA die Regressionstests sowie eine Analyse, welche Teile der Software nochmals zu pr\u00fcfen sind.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Regressionstest w\u00e4hrend der Integrationspr\u00fcfung<\/h4>\n\n\n\n<p>Analog zur IEC 62304 findet sich auch eine Forderung bez\u00fcglich der Integration:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Regression analysis and regression testing should also be employed when using integration methods to build a software product to ensure that newly integrated modules do not adversely impact the operation of previously integrated modules.<\/p>\n<cite>Quelle: IEC 62304<\/cite><\/blockquote>\n\n\n\n<h4 class=\"wp-block-heading\">M\u00f6glichst jeden Test als Regressionstest durchf\u00fchren<\/h4>\n\n\n\n<p>Ein besonderes Augenmerk legt die FDA auf das Konfigurationsmanagement und die F\u00e4higkeit von (allen) Tests, im Rahmen des Regressions-Testings wiederholt werden zu k\u00f6nnen:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Test procedures, test data, and test results should be documented in a manner permitting objective pass\/fail decisions to be reached. They should also be suitable for review and objective decision making subsequent to running the test, and they should be suitable for use in any subsequent regression testing.<\/p>\n<cite>Quelle: FDA<\/cite><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"teile\">3. Welcher Teil der Software muss Regressions-getestet werden?<\/h2>\n\n\n\n<p>Die kurze Antwort auf diese Frage lautet: Das gesamte Software-System mit allen Tests, es sei denn, Sie k\u00f6nnen einen kleineren Testumfang begr\u00fcnden.<\/p>\n\n\n\n<p>Es gibt somit zwei Stellschrauben, \u00fcber die Sie den Testumfang reduzieren k\u00f6nnen:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Die Gr\u00f6\u00dfe des Testobjekts (sprich ganzes Software-System oder nur Teile)<\/li>\n\n\n\n<li>Die Testziele, also auf welche Qualit\u00e4tseigenschaften Sie die Software hin \u00fcberpr\u00fcfen. Einen \u00dcberblick \u00fcber m\u00f6gliche Qualit\u00e4tseigenschaften verschafft Ihnen die <a aria-label=\"ISO 25010 (opens in a new tab)\" href=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/iso-9126-und-iso-25010\/\" target=\"_blank\" rel=\"noreferrer noopener\">ISO 25010<\/a>.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">Ad 1. Beschr\u00e4nkung der Gr\u00f6\u00dfe des Testobjekts<\/h3>\n\n\n\n<p>Wenn Sie bei einer \u00c4nderung an einem Teil eines Software-Systems nur eben diesen Teil einer Regressionspr\u00fcfung unterwerfen wollen, dann m\u00fcssen Sie darlegen, weshalb sich diese \u00c4nderung nicht auf andere Teile des Software-Systems auswirken kann.<\/p>\n\n\n\n<p>Diese Begr\u00fcndung wird Ihnen am besten anhand einer dokumentierten Software-Architektur gelingen. Diese sollte n\u00e4mlich aufzeigen:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Abh\u00e4ngigkeiten anderer Komponenten von der ge\u00e4nderten Komponente<\/li>\n\n\n\n<li><a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/software-schnittstellen-beschreibung-konform-iec-62304\/\">Schnittstellen<\/a>, \u00fcber die diese Abh\u00e4ngigkeiten realisiert sind<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">Ad 2. Beschr\u00e4nkung der Testziele<\/h3>\n\n\n\n<p>Besonders bei \u201enicht-funktionalen Anforderungen\u201c wie der Performanz oder der Portierbarkeit kann oft nicht ausschlie\u00dflich \u00fcber die (statische) Software-Architektur argumentiert werden. Allerdings sind die Begr\u00fcndungen offensichtlich. Beispiele:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Durch die \u00c4nderung eines Algorithmus wird die Portierbarkeit der Software wahrscheinlich nicht beeinflusst.<\/li>\n\n\n\n<li>Wenn im Rahmen eines Unit-Tests nachgewiesen werden kann, dass die Performanz einer Komponente unver\u00e4ndert ist, ist eine \u00c4nderung der Performanz des gesamten Systems unwahrscheinlich.<\/li>\n<\/ul>\n\n\n\n<p>Diese M\u00f6glichkeit, Regressionstests nach Art des Testziels auszuw\u00e4hlen bedingt jedoch, dass die Tests auch danach klassifiziert und aufgeteilt sind.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"tipps\">4. Regressionstest: Best Practices<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">a) Allgemeines Tipps<\/h3>\n\n\n\n<p>Regressionstests sind Kennzeichen einer professionellen Software-Entwicklung. Sie sind Ihre \u201eVersicherung\u201c, Ihre Leitplanken, v. a. bei Software-\u00c4nderungen.<\/p>\n\n\n\n<p>Falls Sie noch keine umfassenden Regressionstests durchf\u00fchren, dann starten Sie mit diesen Tipps:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Automatisieren Sie<\/strong>, was automatisiert werden kann.<br>Das ist eine anf\u00e4ngliche Investition, die sich rechnet. Wenn Sie Kapazit\u00e4tsprobleme haben, dann denken Sie \u00fcber eine\/n Werkstudenten\/studentin nach, der\/die im Rahmen seiner\/ihrer Arbeit eine Testinfrastruktur aufbaut. Keine Zeit in Regressionstests zu investieren ist so wie keine Zeit zum Sch\u00e4rfen seiner S\u00e4ge zu haben, weil das Holzs\u00e4gen so m\u00fchsam ist.<\/li>\n\n\n\n<li><strong>Erh\u00f6hen Sie den Anteil der Regressionstests<br><\/strong>F\u00fcr bestehenden Code werden die meisten&nbsp;keine Tests mehr \u201enach-schreiben\u201c wollen. Dann legen Sie fest, dass alle ge\u00e4nderten und alle neuen Code-Teile in einer Regressions-Suite eingeh\u00e4ngt werden m\u00fcssen. So erh\u00f6hen Sie im Lauf der Zeit kontinuierlich den Anteil des automatisiert getesteten Codes (s. Abb. 1).<\/li>\n\n\n\n<li><strong>Verbessern Sie Ihre Software-Architektur<br><\/strong>Die Aussage, dass sich ein Code nur schwer (z. B. nur mit Hardware) testen lie\u00dfe, ist ein deutliches Indiz daf\u00fcr, dass der Code suboptimal strukturiert ist. Ein Hardware-Abstraction-Layer, ein Architektur-Refactoring und mehr Ausbildung im Bereich des Software-Testings k\u00f6nnen Wunder bewirken.<\/li>\n\n\n\n<li><strong>Lassen Sie die Tests m\u00f6glichst h\u00e4ufig laufen<br><\/strong>Ein automatisierter Build mit einem Tool wie Hudson oder Maven hilft Ihnen, Fehler fr\u00fch zu finden. Wenn Sie diese eliminieren, k\u00f6nnen Sie einen unerwarteten Projektverzug kurz vor dem Release vermeiden.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"233\" src=\"https:\/\/cdn.johner-institut.de\/blog\/wp-content\/uploads\/2016\/05\/Regressionstest-300x233.png\" alt=\"Regressionstest: Anteil kontinuierliche erh\u00f6hen\" class=\"wp-image-13044\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/05\/Regressionstest-300x233.png 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/05\/Regressionstest-768x596.png 768w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/05\/Regressionstest-150x117.png 150w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/05\/Regressionstest.png 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption class=\"wp-element-caption\"><em><strong>Abb. 1:<\/strong> Erh\u00f6hung der Testabdeckung durch Testen von neuem und ge\u00e4ndertem Code<\/em><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">b) Testen von embedded Software<\/h3>\n\n\n\n<p>Manche Kunden vermuten: Wir k\u00f6nnen bei uns nicht automatisiert testen, weil wir sehr Hardware-nah programmieren. Au\u00dferdem verlangt die IEC 62304 das auch nicht.<\/p>\n\n\n\n<p>Sicher trifft es zu, dass die IEC 62304 keine Automatisierung verlangt. Es ist auch zutreffend, dass bei sehr Hardware-naher embedded Software die Hardware vorhanden sein muss, um diese Software zu testen. Dennoch:<span id=\"more-7436\"><\/span><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Zum einen sind automatisierte Testst\u00e4nde, die diese Hardware enthalten, keine neue Erfindung.<\/li>\n\n\n\n<li>Zum anderen muss die Entscheidung pro oder contra automatisiertes Testen nicht pauschal f\u00fcr die ganze Software getroffen werden.<\/li>\n<\/ol>\n\n\n\n<h4 class=\"wp-block-heading\">Wann embedded Software automatisiert getestet werden kann und soll<\/h4>\n\n\n\n<p>Eine einfache Regel z. B. f\u00fcr eine<span>\u00a0<\/span><strong>SOP-Software-Entwicklung<\/strong><span>\u00a0<\/span>k\u00f6nnte lauten: Alle Komponenten, die keinen Hardwarezugriff enthalten, m\u00fcssen automatisiert getestet werden. Dabei ist die Feststellung, ob Hardwarezugriff erfolgt, auf jeder Hierarchieebene zu treffen.<\/p>\n\n\n\n<figure class=\"wp-block-image alignnone\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/04\/Komponenten-Hierarchie-Hardware-embedded-Testen.png\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"286\" height=\"300\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/04\/Komponenten-Hierarchie-Hardware-embedded-Testen-286x300.png\" alt=\"Testen von embedded Software gelingt auch bei Regressionstests\" class=\"wp-image-9219\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/04\/Komponenten-Hierarchie-Hardware-embedded-Testen-286x300.png 286w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/04\/Komponenten-Hierarchie-Hardware-embedded-Testen.png 788w\" sizes=\"auto, (max-width: 286px) 100vw, 286px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong>Abb. 2<\/strong>: Testen von embedded Software gelingt auch bei Regressionstests<\/figcaption><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Abb. 2 zeigt, dass das System insgesamt (0. Bausteinebene) einen Hardwarezugriff hat, daher ist es rot und muss nicht komplett automatisiert getestet werden.<\/li>\n\n\n\n<li>Auf Bausteinebene 1 hat nur eine der vier Komponenten Hardwarezugriff, die anderen nicht (gr\u00fcn). Und von dieser einen Komponente mit Hardwarezugriff (rot) ist es auf Ebene 2 wiederum nur eine Komponente (rot).<\/li>\n<\/ul>\n\n\n\n<p>Wenn hingegen fast alle Komponenten Hardwarezugriff h\u00e4tten, dann stellt sich die Frage nach der G\u00fcte der Architektur. Hat man ein Hardware-Abstraction-Layer (HAL) vergessen? Sind Funktionalit\u00e4ten gar redundant implementiert? Genau diese \u00dcbersicht und dieses Verst\u00e4ndnis verschafft ein Komponentendiagramm.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Infrastruktur zum Testen von embedded Software<\/h4>\n\n\n\n<p>Manchmal ist es schwierig, direkt die externe Hardware-Schnittstelle zu testen, weil eine entsprechende Testinfrastruktur fehlt oder\/und das Protokoll sehr aufwendig ist. Daher k\u00f6nnte eine weitere Regel lauten, dass in diesen F\u00e4llen das extern anzuschlie\u00dfende System (hellblau in Abb. 2) als Testtreiber genutzt werden darf. Ein wirklicher Komponententest im Sinne der IEC 62304 ist das zwar nicht mehr, aber immerhin besser, als ganz auf diesen Test zu verzichten.<\/p>\n\n\n\n<p>Besser w\u00e4re es f\u00fcr embedded Software, eine Testinfrastruktur zu erstellen, die die Protokolle aller internen und externen Schnittstellen beherrscht. Dieser initiale Aufwand rechnet sich dann, wenn mehrere Versionen eines Produkts (einer Komponente) entwickelt werden sollen und daher<span>\u00a0<\/span>Regressionstests<span>\u00a0<\/span>(auch im Sinn der IEC 62304) gefordert sind.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">c) Testen von KI-basierter Software<\/h3>\n\n\n\n<p>Die Aussage, dass sich KI-basierte Software, insbesondere Software, die neuronale Netzwerke verwendet wie Large Language Models, wegen ihrer &#8222;probabilistischen Natur&#8220; schlecht mit Regressionstests testen l\u00e4sst, sollte in mehrfacher Hinsicht hinterfragt werden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die Wahl des jeweils n\u00e4chsten Tokens erfolgt zwar auf Basis einer Wahrscheinlichkeit. Das bedeutet aber noch nicht zwingend, dass sich die Outputs bei gleichen Inputs einer Wahrscheinlichkeitsverteilung folgend \u00e4ndern. Schlie\u00dflich \u00e4ndern sich die &#8222;weights and biases&#8220; der neuronalen Netzwerke nicht.<\/li>\n\n\n\n<li>Wenn die Outputs so unvorhersehbar sind, dass sie nicht einer Spezifikation gen\u00fcgen, ist zu \u00fcberpr\u00fcfen, ob das Medizinprodukt \u00fcberhaupt &#8222;zugelassen&#8220; werden darf. Falls hingegen die Outputs den Vorgaben einer Spezifikation gen\u00fcgen, dann muss das auch dauerhaft gew\u00e4hrleistet sein. Genau das sollen und k\u00f6nnen Regressionstests verifizieren.<\/li>\n\n\n\n<li>Hersteller m\u00fcssen in der Lage sein, solch eine Spezifikation zu erstellen. Diese Spezifikationen m\u00fcssen ggf. auch die Wahrscheinlichkeit bestimmen (ggf. abh\u00e4ngig von Input\/Feature), mit denen die Modelle korrekte Vorhersagen treffen. Regressionstests m\u00fcssen daher auch diese Wahrscheinlichkeiten pr\u00fcfen, was wiederum voraussetzen kann, dass diese Tests mehrfach durchlaufen werden.<\/li>\n<\/ul>\n\n\n\n<p>Bei KI-basierten Modellen sind Regressionstests insbesondere bei Software- und Modell-Updates notwendig, weil selbst kleine \u00c4nderungen des Modells (z. B. nach einem weiteren Training) gro\u00dfe Auswirkungen nach sich ziehen k\u00f6nnen.<\/p>\n\n\n\n<p>Mit Phantomen (z. B. mit den R\u00f6ntgenphantomen der Firma <a href=\"https:\/\/phantomx.de\/\">PhantomX<\/a>) lassen sich diese Regressionstests von Produkten bzw. Modellen zur Bildanalyse reproduzierbar durchf\u00fchren.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>\u00c4nderungshistorie<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>2024-07-09: Abschnitt 4.c) erg\u00e4nzt. Redaktionelle \u00c4nderungen<\/li>\n\n\n\n<li>2019-01-31: Erste Version des Artikels ver\u00f6ffentlicht<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Unter einem Regressionstest verstehen die meisten Software-Tester die Wiederholung eines bestehenden Tests. Damit m\u00f6chten sie pr\u00fcfen, ob dieser Test nach einer Software-\u00c4nderung noch immer erfolgreich durchl\u00e4uft. Lesen Sie in diesem Beitrag, was Sie bei einem Regressionstest von medizinscher Software beachten sollten.<\/p>\n","protected":false},"author":113,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[184],"tags":[364],"ppma_author":[1206],"class_list":["post-13041","post","type-post","status-publish","format-standard","hentry","category-iec-62304-medizinische-software","tag-software-testing","category-184","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Regressionstest: Forderungen &amp; Testautomatisierung<\/title>\n<meta name=\"description\" content=\"Ein Regressionstest ist auch f\u00fcr Medizinprodukte-Software vorgeschrieben, um zu pr\u00fcfen, dass Software-\u00c4nderungen keine unerwarteten Nebeneffekte haben.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regressionstest: Forderungen &amp; Testautomatisierung\" \/>\n<meta property=\"og:description\" content=\"Ein Regressionstest ist auch f\u00fcr Medizinprodukte-Software vorgeschrieben, um zu pr\u00fcfen, dass Software-\u00c4nderungen keine unerwarteten Nebeneffekte haben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/\" \/>\n<meta property=\"og:site_name\" content=\"Regulatorisches Wissen f\u00fcr Medizinprodukte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JohnerInstitut\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-09T12:56:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-20T16:22:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.johner-institut.de\/blog\/wp-content\/uploads\/2016\/05\/Regressionstest-300x233.png\" \/>\n<meta name=\"author\" content=\"Janos Hackenbeck\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Janos Hackenbeck\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/\"},\"author\":{\"name\":\"Janos Hackenbeck\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/a8092bff9934d179ff93433b4a7e9f21\"},\"headline\":\"Regressionstest: Ihre Software-Versicherung\",\"datePublished\":\"2024-07-09T12:56:00+00:00\",\"dateModified\":\"2024-07-20T16:22:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/\"},\"wordCount\":1740,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Regressionstest-300x233.png\",\"keywords\":[\"Software-Testing: Die Forderungen der IEC 62304 und FDA erf\u00fcllen\"],\"articleSection\":[\"Software &amp; IEC 62304\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/\",\"name\":\"Regressionstest: Forderungen & Testautomatisierung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Regressionstest-300x233.png\",\"datePublished\":\"2024-07-09T12:56:00+00:00\",\"dateModified\":\"2024-07-20T16:22:35+00:00\",\"description\":\"Ein Regressionstest ist auch f\u00fcr Medizinprodukte-Software vorgeschrieben, um zu pr\u00fcfen, dass Software-\u00c4nderungen keine unerwarteten Nebeneffekte haben.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Regressionstest-300x233.png\",\"contentUrl\":\"https:\\\/\\\/cdn.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Regressionstest-300x233.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/regressionstest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Software &amp; IEC 62304\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/category\\\/iec-62304-medizinische-software\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Regressionstest: Ihre Software-Versicherung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"name\":\"Regulatorisches Wissen f\u00fcr Medizinprodukte\",\"description\":\"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\",\"name\":\"Johner Institut GmbH\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"width\":1213,\"height\":286,\"caption\":\"Johner Institut GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JohnerInstitut\\\/\",\"https:\\\/\\\/x.com\\\/christianjohner\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/JohnerInstitut\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/a8092bff9934d179ff93433b4a7e9f21\",\"name\":\"Janos Hackenbeck\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Janos-Hackenbeck_300x300.pnga589e3e444c74132e654890732437603\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Janos-Hackenbeck_300x300.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Janos-Hackenbeck_300x300.png\",\"caption\":\"Janos Hackenbeck\"},\"description\":\"Janos Hackenbeck ist studierter Medizinphysiker. Durch langj\u00e4hrige Erfahrung in der Qualit\u00e4tssicherung von Software und beim Aufbau von Softwareprojekten unter IEC 62304 und ISO 13485 ist er Experte f\u00fcr Medizinproduktesoftware. Vom Standort Berlin aus unterst\u00fctzt er Kunden des Johner Instituts mit Schwerpunkt auf IVD-Software.\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/author\\\/janos-hackenbeck\\\/\"}]}<\/script>\n<meta name=\"copyright\" content=\"Johner Institut GmbH\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regressionstest: Forderungen & Testautomatisierung","description":"Ein Regressionstest ist auch f\u00fcr Medizinprodukte-Software vorgeschrieben, um zu pr\u00fcfen, dass Software-\u00c4nderungen keine unerwarteten Nebeneffekte haben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/","og_locale":"de_DE","og_type":"article","og_title":"Regressionstest: Forderungen & Testautomatisierung","og_description":"Ein Regressionstest ist auch f\u00fcr Medizinprodukte-Software vorgeschrieben, um zu pr\u00fcfen, dass Software-\u00c4nderungen keine unerwarteten Nebeneffekte haben.","og_url":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/","og_site_name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","article_publisher":"https:\/\/www.facebook.com\/JohnerInstitut\/","article_published_time":"2024-07-09T12:56:00+00:00","article_modified_time":"2024-07-20T16:22:35+00:00","og_image":[{"url":"https:\/\/cdn.johner-institut.de\/blog\/wp-content\/uploads\/2016\/05\/Regressionstest-300x233.png","type":"","width":"","height":""}],"author":"Janos Hackenbeck","twitter_misc":{"Verfasst von":"Janos Hackenbeck","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/#article","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/"},"author":{"name":"Janos Hackenbeck","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/a8092bff9934d179ff93433b4a7e9f21"},"headline":"Regressionstest: Ihre Software-Versicherung","datePublished":"2024-07-09T12:56:00+00:00","dateModified":"2024-07-20T16:22:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/"},"wordCount":1740,"commentCount":0,"publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.johner-institut.de\/blog\/wp-content\/uploads\/2016\/05\/Regressionstest-300x233.png","keywords":["Software-Testing: Die Forderungen der IEC 62304 und FDA erf\u00fcllen"],"articleSection":["Software &amp; IEC 62304"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/","url":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/","name":"Regressionstest: Forderungen & Testautomatisierung","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/#primaryimage"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.johner-institut.de\/blog\/wp-content\/uploads\/2016\/05\/Regressionstest-300x233.png","datePublished":"2024-07-09T12:56:00+00:00","dateModified":"2024-07-20T16:22:35+00:00","description":"Ein Regressionstest ist auch f\u00fcr Medizinprodukte-Software vorgeschrieben, um zu pr\u00fcfen, dass Software-\u00c4nderungen keine unerwarteten Nebeneffekte haben.","breadcrumb":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/#primaryimage","url":"https:\/\/cdn.johner-institut.de\/blog\/wp-content\/uploads\/2016\/05\/Regressionstest-300x233.png","contentUrl":"https:\/\/cdn.johner-institut.de\/blog\/wp-content\/uploads\/2016\/05\/Regressionstest-300x233.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/regressionstest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.johner-institut.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Software &amp; IEC 62304","item":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62304-medizinische-software\/"},{"@type":"ListItem","position":3,"name":"Regressionstest: Ihre Software-Versicherung"}]},{"@type":"WebSite","@id":"https:\/\/www.johner-institut.de\/blog\/#website","url":"https:\/\/www.johner-institut.de\/blog\/","name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","description":"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen","publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.johner-institut.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.johner-institut.de\/blog\/#organization","name":"Johner Institut GmbH","url":"https:\/\/www.johner-institut.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","width":1213,"height":286,"caption":"Johner Institut GmbH"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JohnerInstitut\/","https:\/\/x.com\/christianjohner","https:\/\/www.youtube.com\/user\/JohnerInstitut"]},{"@type":"Person","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/a8092bff9934d179ff93433b4a7e9f21","name":"Janos Hackenbeck","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Janos-Hackenbeck_300x300.pnga589e3e444c74132e654890732437603","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Janos-Hackenbeck_300x300.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Janos-Hackenbeck_300x300.png","caption":"Janos Hackenbeck"},"description":"Janos Hackenbeck ist studierter Medizinphysiker. Durch langj\u00e4hrige Erfahrung in der Qualit\u00e4tssicherung von Software und beim Aufbau von Softwareprojekten unter IEC 62304 und ISO 13485 ist er Experte f\u00fcr Medizinproduktesoftware. Vom Standort Berlin aus unterst\u00fctzt er Kunden des Johner Instituts mit Schwerpunkt auf IVD-Software.","url":"https:\/\/www.johner-institut.de\/blog\/author\/janos-hackenbeck\/"}]}},"authors":[{"term_id":1206,"user_id":113,"is_guest":0,"slug":"janos-hackenbeck","display_name":"Janos Hackenbeck","avatar_url":{"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Janos-Hackenbeck_300x300.png","url2x":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Janos-Hackenbeck_300x300.png"},"author_category":"","first_name":"Janos","last_name":"Hackenbeck","user_url":"","user_url_2":"","job_title":"","description":"Janos Hackenbeck ist studierter Medizinphysiker. Durch langj\u00e4hrige Erfahrung in der Qualit\u00e4tssicherung von Software und beim Aufbau von Softwareprojekten unter IEC 62304 und ISO 13485 ist er Experte f\u00fcr Medizinproduktesoftware. \r\nVom Standort Berlin aus unterst\u00fctzt er Kunden des Johner Instituts mit Schwerpunkt auf IVD-Software."}],"_links":{"self":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/13041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/users\/113"}],"replies":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/comments?post=13041"}],"version-history":[{"count":13,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/13041\/revisions"}],"predecessor-version":[{"id":5379091,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/13041\/revisions\/5379091"}],"wp:attachment":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/media?parent=13041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/categories?post=13041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/tags?post=13041"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/ppma_author?post=13041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}