{"id":3207883,"date":"2020-02-18T09:00:00","date_gmt":"2020-02-18T08:00:00","guid":{"rendered":"https:\/\/www.johner-institut.de\/blog\/?p=3207883"},"modified":"2025-03-31T16:49:06","modified_gmt":"2025-03-31T14:49:06","slug":"anforderungen-der-mdr-an-die-usability","status":"publish","type":"post","link":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/","title":{"rendered":"Anforderungen der MDR an die Usability"},"content":{"rendered":"\n<p>Hersteller m\u00fcssen die <strong>Anforderungen der MDR an die Gebrauchstauglichkeit (Usability)<\/strong> f\u00fcr ausnahmslos alle Medizinprodukte nachweisen. <\/p>\n\n\n\n<p>F\u00fcr einige Produkte gelten \u00dcbergangsfristen. Doch die Hersteller sind gut beraten, sich gleich mit den Unterschieden zwischen den Anforderungen der MDD und der MDR an die Usability vertraut zu machen. Nur so k\u00f6nnen Sie die&nbsp;<strong>Transition auf die MDR problemlos bew\u00e4ltigen<\/strong>&nbsp;sowie&nbsp;<strong>regulatorischen \u00c4rger und Aufw\u00e4nde vermeiden<\/strong>, z.B. f\u00fcr unn\u00f6tige Usability-Tests.<\/p>\n\n\n\n<p>Eine <strong>kostenlose Checkliste<\/strong> hilft, auch bei \u201eLegacy-Produkten\u201c schnell Klarheit zu erreichen und notwendige Ma\u00dfnahmen zu identifizieren.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\" id=\"mdd\">1. R\u00fcckblick: Die Anforderungen der MDD an die Gebrauchstauglichkeit<\/h2>\n\n\n\n<p>Bereits die urspr\u00fcngliche Version der <a rel=\"noreferrer noopener\" aria-label=\"Medizinprodukterichtlinie MDD (93\/42\/EWG) (opens in a new tab)\" href=\"https:\/\/www.johner-institut.de\/blog\/tag\/mdd\/\" target=\"_blank\">Medizinprodukterichtlinie MDD (93\/42\/EWG)<\/a> hatte erste Anforderungen an die Gebrauchstauglichkeit formuliert. Beispielsweise mussten <em>\u201eMe\u00dfskalen, Bedienungs- und Anzeigeeinrichtungen [&#8230;] ergonomischen Grunds\u00e4tzen entsprechen\u201c<\/em>.<\/p>\n\n\n\n<p>Die \u00c4nderungsrichtlinie 2007\/47\/EC erg\u00e4nzte die MDD um die explizite, <a rel=\"noreferrer noopener\" aria-label=\"grundlegende Anforderung (opens in a new tab)\" href=\"https:\/\/www.johner-institut.de\/blog\/tag\/grundlegende-anforderungen\/\" target=\"_blank\">grundlegende Anforderung<\/a>, dass Risiken durch mangelnde Gebrauchstauglichkeit minimiert werden m\u00fcssen. Sie unterschied bereits Risiken, die sich ergeben durch<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>die <em>\u201eergonomischen Merkmale des Produkts\u201c<\/em>,<\/li>\n\n\n\n<li>die <em>\u201eUmgebungsbedingungen, in denen das Produkt eingesetzt werden soll\u201c<\/em> sowie<\/li>\n\n\n\n<li>die <em>\u201etechnischen Kenntnisse, [&#8230;] Erfahrung [&#8230;] sowie gegebenenfalls [&#8230;] medizinischen und physischen Voraussetzungen der vorgesehenen Anwender\u201c<\/em>.<\/li>\n<\/ul>\n\n\n\n<p>Parallel mit dieser \u00c4nderung harmonisierte die EU die Norm EN IEC 62366:2006, die fortan den Stand der Technik repr\u00e4sentierte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"mdr\">2. Anforderungen der MDR an die Usability im Detail<\/h2>\n\n\n\n<p>Eine Suche in der <a href=\"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/medical-device-regulation-mdr-medizinprodukteverordnung\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"EU-Medizinprodukteverordnung MDR (opens in a new tab)\">EU-Medizinprodukteverordnung MDR<\/a> nach den Begriffen \u201eGebrauchstauglichkeit\u201c bzw. \u201eUsability\u201c f\u00fchrt zu erstaunlich wenigen Treffern. Dennoch enth\u00e4lt die EU-Verordnung zahlreiche Anforderungen an die Gebrauchstauglichkeit.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">a) Artikel 5 und Anhang I, Absatz 1: Produkt muss f\u00fcr Zweckbestimmung geeignet sein<\/h3>\n\n\n\n<p>Der Artikel 5 und der erste Absatz des Anhangs I (grundlegende Sicherheits- und Leistungsanforderungen) der MDR stellen sehr \u00e4hnliche Anforderungen:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Ein Produkt muss unter Ber\u00fccksichtigung seiner Zweckbestimmung den in Anhang I festgelegten f\u00fcr das Produkt geltenden grundlegenden Sicherheits- und Leistungsanforderungen gen\u00fcgen.<\/em><\/p>\n<cite><a href=\"https:\/\/mdr-selector.johner-institut.de\/mdr_de.html#artikel-5\" target=\"_blank\" rel=\"noreferrer noopener\" label=\"MDR, Artikel 5 (opens in a new tab)\">MDR, Artikel 5<\/a><\/cite><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Die Produkte erzielen die von ihrem Hersteller vorgesehene Leistung und werden so ausgelegt und hergestellt, dass sie sich unter normalen Verwendungsbedingungen f\u00fcr ihre Zweckbestimmung eignen.<\/em><\/p>\n<cite><a href=\"https:\/\/mdr-selector.johner-institut.de\/mdr_de.html#annex-I\" target=\"_blank\" rel=\"noreferrer noopener\" label=\"MDR, Anhang I, Absatz 1 (opens in a new tab)\">MDR, Anhang I, Absatz 1<\/a><\/cite><\/blockquote>\n\n\n\n<p>Beide beziehen sich auf die <a rel=\"noreferrer noopener\" aria-label=\"Zweckbestimmung (opens in a new tab)\" href=\"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/zweckbestimmung\/\" target=\"_blank\">Zweckbestimmung<\/a>. In dieser Zweckbestimmung sollten Sie nicht nur den vorgesehenen medizinischen Zweck festlegen, sondern auch die vorgesehenen Anwender und die vorgesehene Nutzungsumgebung. Die IEC 62366-1 nennt dies \u201eUse Specification\u201c.<\/p>\n\n\n\n<div class=\"defbox\">\n    <div class=\"definition\">\n        <i class=\"fa fa-external-link\"><\/i> Weiterf\u00fchrende Informationen\n    <\/div>\n    <p>Lesen Sie hier mehr dazu,<a href=\"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/zweckbestimmung\/\"> was eine Zweckbestimmung enthalten sollte<\/a>.<\/p>\n<\/div>\n\n\n\n<p>Folglich k\u00f6nnen Hersteller, die diese Zweckbestimmung und damit die vorgesehenen Nutzer und die vorgesehene Nutzungsumgebung nicht pr\u00e4zise spezifiziert haben, kaum nachweisen, dass sie die Anforderungen der MDR an die Gebrauchstauglichkeit erf\u00fcllen.<\/p>\n\n\n\n<p>Zu genau diesem Nachweis sind Sie aber durch den ersten Absatz des Anhangs I verpflichtet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">b) Anhang I, Absatz 3: Analyse von vorhersehbaren Fehlanwendungen<\/h3>\n\n\n\n<p>Der dritte Absatz des Anhangs I zu den grundlegenden Sicherheits- und Leistungsanforderungen enth\u00e4lt noch spezifischere Anforderungen an die Usability: <\/p>\n\n\n\n<p>Er verlangt von den Herstellern ein Risikomanagement zu betreiben. Dabei m\u00fcssen sie <em>\u201edie Risiken, einsch\u00e4tzen und bewerten, die mit der bestimmungsgem\u00e4\u00dfen Verwendung verbunden sind und die bei einer <strong>vern\u00fcnftigerweise vorhersehbaren Fehlanwendung<\/strong> auftreten\u201c<\/em>.<\/p>\n\n\n\n<p>Solch eine Risikoanalyse muss dem Stand der Technik entsprechen. Eine reine Spekulation w\u00fcrde folglich nicht gen\u00fcgen. Vielmehr w\u00fcrde man erwarten:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sorgf\u00e4ltige Recherche und Auswertung von vorhersehbaren <strong>Fehlanwendungen bei vergleichbaren Produkten<\/strong>, z.B. in Beh\u00f6rdendatenbanken und den eigenen Post-Market-Daten<\/li>\n\n\n\n<li>Auflistung aller<strong> <a rel=\"noreferrer noopener\" aria-label=\"Use Scenarios (opens in a new tab)\" href=\"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/use-case-benutzungsszenario\/\" target=\"_blank\">Use Scenarios<\/a><\/strong> mit anschlie\u00dfender <strong>Task-Analyse<\/strong><\/li>\n\n\n\n<li>Beobachtung von Anwendern mit zugelassenen Produkten oder im Rahmen von formativen und <strong>summativen Bewertungen<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Die Ergebnisse dieser Analysen erwarten ein Auditor oder eine Beh\u00f6rde in der Risikomanagementakte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">c) Anhang I, Absatz 5: Die Ma\u00dfnahmen zum Ausschluss oder zur Verringerung von Use Errors<\/h3>\n\n\n\n<p>Den Absatz 5 des Anhangs I haben die Autoren der MDR fast buchstabengleich aus der MDD \u00fcbernommen:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Beim Ausschluss oder bei der Verringerung der durch Anwendungsfehler bedingten Risiken m\u00fcssen die Hersteller<br>a) die Risiken aufgrund ergonomischer Merkmale des Produkts und der Umgebung, in der das Produkt verwendet werden soll, so weit wie m\u00f6glich verringern (auf die Sicherheit des Patienten ausgerichtete Produktauslegung) sowie<br>b) die technischen Kenntnisse, die Erfahrung, die Aus- und Weiterbildung, gegebenenfalls die Anwendungsumgebung sowie die gesundheitliche und k\u00f6rperliche Verfassung der vorgesehenen Anwender ber\u00fccksichtigen (auf Laien, Fachleute, Behinderte oder sonstige Anwender ausgerichtete Produktauslegung).<\/em><\/p>\n<cite>MDR, Anhang I, Absatz 5<\/cite><\/blockquote>\n\n\n\n<p>W\u00e4hrend Absatz 3 die <strong>Analyse<\/strong> von Usability-Risiken forderte, fordert der Absatz 5 deren <strong>Ausschluss<\/strong> oder zumindest <strong>Verringerung<\/strong>.<\/p>\n\n\n\n<p>Damit zwingt die MDR die Hersteller, f\u00fcr alle identifizierten Risiken mit Bezug zur Gebrauchstauglichkeit Ma\u00dfnahmen festzulegen. Laut Absatz 4 m\u00fcssen die Hersteller zuerst inh\u00e4rente Sicherheit anstreben, dann die Schutzma\u00dfnahmen und erst danach die Sicherheitsinformationen in den Blick nehmen.<\/p>\n\n\n\n<p>Beispiele f\u00fcr diese Ma\u00dfnahmen sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Inh\u00e4rente Sicherheit<\/strong>: Ein Schalter, der nicht existiert, kann nicht falsch bedient werden.<\/li>\n\n\n\n<li><strong>Schutzma\u00dfnahme<\/strong>: Ein Schalter, der durch eine Klappe vor versehentlichem Dr\u00fccken gesch\u00fctzt ist.<\/li>\n\n\n\n<li><strong>Sicherheitsinformation<\/strong>: Eine Warnung z.B. in der Gebrauchsanweisung vor den Folgen eines irrt\u00fcmlich falsch gedr\u00fcckten Schalters.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">d) Anhang I, Absatz 14.1: Spezifische Risiken durch Verbindungen mit anderen Produkten<\/h3>\n\n\n\n<p>Der 14. Absatz des Anhangs I fordert die Beherrschung von Risiken, die durch die Interaktion des Produkts mit seiner Umwelt entstehen k\u00f6nnen. Auch diese Risiken haben teilweise einen Bezug zur Usability:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Wenn ein Produkt zur Verwendung in Kombination mit anderen Produkten oder Ausr\u00fcstungen bestimmt ist, muss die Kombination einschlie\u00dflich der Verbindungen sicher sein und darf die vorgesehene Leistung der Produkte nicht beeintr\u00e4chtigen. Jede Einschr\u00e4nkung der Anwendung im Zusammenhang mit solchen Kombinationen wird auf der Kennzeichnung und\/oder in der Gebrauchsanweisung angegeben. Vom Anwender zu bedienende Verbindungen, wie etwa die \u00dcbertragung von Fl\u00fcssigkeit oder Gas oder elektrische oder mechanische Verbindungen, werden so ausgelegt und hergestellt, dass alle m\u00f6glichen Risiken, wie etwa fehlerhafte Verbindungen, so gering wie m\u00f6glich gehalten werden.<\/em><\/p>\n<cite>MDR, Anhang I, Absatz 14.1<\/cite><\/blockquote>\n\n\n\n<p>Diese Anforderung der MDR an die Gebrauchstauglichkeit sollte bereits erf\u00fcllt sein, wenn der Hersteller alle Use Scenarios  ber\u00fccksichtigt hat, auch die des Kombinieren und Verbinden des Produkts mit anderen Produkten. Als Ma\u00dfnahmen fordert die MDR auch hier m\u00f6glichst die inh\u00e4rente Sicherheit vor fehlerhaften Verbindungen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">e) Anhang I, Absatz 14.2: Spezifische Risiken durch mangelnde ergonomische Merkmale<\/h3>\n\n\n\n<p>Der Absatz 14.2 geht auf eine weitere Form von Risiken ein: Im Gegensatz zu Absatz 14.1 sind nicht die Risiken zu beherrschen, die sich durch eine Fehlanwendung ergeben, sondern durch den <strong>Entwurf des Produkts<\/strong>. Die MDR spricht von <em><strong>\u201eergonomischen Merkmalen\u201c<\/strong><\/em>:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Die Produkte werden so ausgelegt und hergestellt, dass folgende Risiken ausgeschlossen oder so weit wie m\u00f6glich reduziert werden:<br>a) Verletzungsrisiken im Zusammenhang mit den physikalischen Eigenschaften einschlie\u00dflich des Verh\u00e4ltnisses Volumen\/Druck, der Abmessungen und gegebenenfalls der ergonomischen Merkmale des Produkts;<\/em><\/p>\n<cite>MDR, Anhang I, Absatz 14.2<\/cite><\/blockquote>\n\n\n\n<p>Ein Beispiel w\u00e4re eine Dialysemaschine auf Rollen. Aufgrund des Gewichts w\u00e4re ein rollendes Dialyseger\u00e4t nur schwer zu stoppen und k\u00f6nnte zu Quetschungen von F\u00fc\u00dfen oder den H\u00e4nden f\u00fchren. Genau solche Risiken m\u00fcssen Hersteller minimieren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">f) Anhang I, Absatz 14.6: Ergonomie von Anzeigen<\/h3>\n\n\n\n<p>Auch im Absatz 14.6 des Anhangs I stellt die MDR Anforderungen an die Gebrauchstauglichkeit.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Mess-, Kontroll- oder Anzeigeeinrichtungen werden so ausgelegt und hergestellt, dass sie mit Blick auf die Zweckbestimmung, die vorgesehenen Anwender und die Umgebungsbedingungen, unter denen die Produkte verwendet werden sollen, ergonomischen Grunds\u00e4tzen entsprechen.<\/em><\/p>\n<cite>MDR, Anhang I, Absatz 14.6<\/cite><\/blockquote>\n\n\n\n<p>Was ergonomische Grunds\u00e4tze sind, f\u00fchrt die MDR nicht aus. Viele Hersteller entwickeln daher eigene Styleguides und laufen dadurch Gefahr, das Rad immer wieder neu zu erfinden. <\/p>\n\n\n\n<div class=\"defbox\">\n    <div class=\"definition\">\n        <i class=\"fa fa-lightbulb-o\"><\/i> Tipp\n    <\/div>\n    <p>Das Johner Institut empfiehlt, auf die Vorgaben durch die Normenfamilie ISO 9241 zur\u00fcckzugreifen. Diese Normen beschreiben, wie User Interfaces konkret zu gestalten sind: von Men\u00fcs \u00fcber Webseiten bis hin zu Kommandozeilen.<\/p>\n<\/div>\n\n\n\n<p>Beachten Sie: Die Auswirkungen auf die Gestaltung von User Interfaces muss die Nutzungsumgebung (z.B. Helligkeit, Abstand zum Produkt) ebenso ber\u00fccksichtigen wie die Nutzer selbst (ggf. k\u00f6rperliche Einschr\u00e4nkungen).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">g) Anhang I, Absatz 21.3: Verst\u00e4ndlichkeit von Anzeigen<\/h3>\n\n\n\n<p>Neben der Ergonomie fordert die MDR in Absatz 21.3 des Anhangs I auch die Verst\u00e4ndlichkeit von Anzeigen:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Die Funktion von Bedienungs- und Anzeigeeinrichtungen wird auf den Produkten deutlich angegeben. Sind die Anweisungen f\u00fcr die Anwendung des Produkts auf diesem selbst angebracht oder werden die Betriebs- oder Regelungsparameter visuell angezeigt, so m\u00fcssen diese Angaben f\u00fcr den Anwender und gegebenenfalls den Patienten verst\u00e4ndlich sein.<\/em><\/p>\n<cite>MDR, Anhang I, Absatz 23.1<\/cite><\/blockquote>\n\n\n\n<p>Um diese Anforderung der MDR an die Usability zu erf\u00fcllen, m\u00fcssen die Hersteller die Anwender und Patienten pr\u00e4zise charakterisieren. Ob eine Anzeige verst\u00e4ndlich ist, h\u00e4ngt schlie\u00dflich von Vorwissen und Erfahrungshintergrund der spezifischen Personen ab.<\/p>\n\n\n\n<p>Ob diese Anzeigen als Teil des User Interfaces wirklich verst\u00e4ndlich sind, l\u00e4sst sich nur durch empirische Daten belegen. Diese k\u00f6nnen Hersteller beispielsweise sammeln durch Befragungen, durch teilnehmende Beobachtungen und durch die Auswertung von Post-Market-Daten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">h) Anhang I, Absatz 22: Laien<\/h3>\n\n\n\n<p>Neu in dieser Form sind die konkreten und umfangreichen Anforderungen der MDR an die sichere Anwendung durch Laien in Absatz 22 des Anhangs I. Sie definiert sogar den Begriff:<\/p>\n\n\n\n<div class=\"defbox\">\n    <div class=\"definition\">\n        <i class=\"fa fa-exclamation-circle\"><\/i> Definition: <dfn>Laie<\/dfn>\n    <\/div>\n    <dd>\u201e\u201eLaie\u201c bezeichnet eine Person, die nicht \u00fcber eine formale Ausbildung in dem einschl\u00e4gigen Bereich des Gesundheitswesens oder dem medizinischen Fachgebiet verf\u00fcgt;\u201c<\/dd>\n    <div class=\"defsource\">MDR, Kapitel 1, Artikel 2<\/div>\n<\/div>\n\n\n\n<p>Weil die Anforderungen zu umfangreich sind, hier eine Zusammenfassung:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die Hersteller m\u00fcssen die <em>\u201ezu erwartenden Schwankungen in der Verfahrensweise und der Umgebung der Laien\u201c<\/em> ber\u00fccksichtigen.<\/li>\n\n\n\n<li>In jedem Fall sind die Risiken zu minimieren. Die Laien m\u00fcssen das Produkt <em>\u201ein allen Bedienphasen sicher und fehlerfrei\u201c<\/em> anwenden k\u00f6nnen.<\/li>\n\n\n\n<li>Dazu ist ggf. eine <em>\u201eangemessene Schulung und\/oder Aufkl\u00e4rung\u201c<\/em> notwendig.<\/li>\n\n\n\n<li>Anweisungen und Angaben m\u00fcssen f\u00fcr diese Zielgruppe <em>\u201eleicht verst\u00e4ndlich und anwendbar\u201c<\/em> sein.<\/li>\n\n\n\n<li>Quasi als risikominimierende Ma\u00dfnahme schreibt die MDR vor, dass die Laien selbst kontrollieren k\u00f6nnen sollen, ob das Produkt bestimmungsgem\u00e4\u00df arbeitet, und dass das Produkt warnt, wenn kein g\u00fcltiges Ergebnis erzielt wurde.<\/li>\n<\/ul>\n\n\n\n<p>Diese Anforderungen wirken sich direkt auf das Produktdesign aus, ebenso auf die Gestaltung von Schulungen und auf die notwendigen Nachweise, z.B. in Form von Usability-Tests.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">i) Anhang I, Artikel 23: Gebrauchstaugliche Gebrauchsanweisung<\/h3>\n\n\n\n<p>Die MDR beschr\u00e4nkt ihre Forderungen nicht auf das Produkt selbst. Auch die Gebrauchsanweisung und weiteren Begleitmaterialien m\u00fcssen laut Artikel 23 des Anhangs I gebrauchstauglich sein.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Medium, Format, Inhalt, Lesbarkeit und Anbringungsstelle der Kennzeichnung und der Gebrauchsanweisung eignen sich f\u00fcr das jeweilige Produkt, seine Zweckbestimmung und die technischen Kenntnisse, die Erfahrung, Ausbildung oder Schulung der vorgesehenen Anwender. Insbesondere ist die Gebrauchsanweisung so zu verfassen, dass sie von dem vorgesehenen Anwender ohne Schwierigkeiten verstanden wird, und gegebenenfalls mit Zeichnungen und Schaubildern zu erg\u00e4nzen. <\/em><\/p>\n<cite>MDR, Anhang I, Artikel 23.1 a)<\/cite><\/blockquote>\n\n\n\n<p>Bei der Umsetzung dieser Anforderungen sind die Hersteller nicht ganz frei. So verpflichtet sie die MDR, \u201einternational anerkannte Symbole\u201c zu verwenden und ggf. zu erl\u00e4utern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">j) Anhang II: Technische Dokumentation<\/h3>\n\n\n\n<p>Selbst der Anhang II enth\u00e4lt einen direkten Bezug zur Usability. Denn er legt den Inhalt der technischen Dokumentation fest. Dazu z\u00e4hlen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Festlegung der vorgesehenen Anwender<\/li>\n\n\n\n<li>Beschreibung, mit welchen anderen Produkten das Produkt kombiniert \/ verbunden werden soll<\/li>\n\n\n\n<li>Tests und Pr\u00fcfergebnisse<\/li>\n<\/ul>\n\n\n\n<p>Bei Software m\u00fcssen diese Tests sogar <em>\u201ein einer simulierten oder tats\u00e4chlichen Anwenderumgebung\u201c<\/em> erfolgt sein. <\/p>\n\n\n\n<p>Soll das Produkt mit anderen verbunden werden, bedarf es eines <em>\u201eNachweises, dass das erstere Produkt bei Anschluss an ein anderes Produkt im Hinblick auf die vom Hersteller angegebenen Merkmale die grundlegenden Sicherheits- und Leistungsanforderungen erf\u00fcllt\u201c<\/em>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">k) Artikel 83 Absatz 3 und Anhang III Abschnitt 1.1: Post-Market Surveillance<\/h3>\n\n\n\n<p>Das einzige Mal erw\u00e4hnt die MDR den Begriff \u201eGebrauchstauglichkeit\u201c (bzw. im Englischen \u201eUsability\u201c) im Kontext der UDI (hier nicht relevant) und der <a rel=\"noreferrer noopener\" aria-label=\"Post-Market Surveillance (opens in a new tab)\" href=\"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/post-market-surveillance\/\" target=\"_blank\">Post-Market Surveillance<\/a>.<\/p>\n\n\n\n<p>Die MDR erwartet von den Herstellern, dass ein System die <em>\u201ezur \u00dcberwachung nach dem Inverkehrbringen gesammelten Daten insbesondere zu folgenden Zwecken verwendet\u201c<\/em>:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>f) Ermittlung von M\u00f6glichkeiten zur Verbesserung der Gebrauchstauglichkeit, der Leistung und der Sicherheit des Produkts;<\/em><\/p>\n<cite>MDR, Artikel 83, Absatz 3<\/cite><\/blockquote>\n\n\n\n<p>Im Anhang III f\u00fchrt die MDR dann aus, welche Informationen zu sammeln und auszuwerten sind:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>&#8211; Informationen \u00fcber schwerwiegende Vorkommnisse, einschlie\u00dflich Informationen aus den Sicherheitsberichten, und Sicherheitskorrekturma\u00dfnahmen im Feld,<br>&#8211; Aufzeichnungen \u00fcber nicht schwerwiegende Vorkommnisse und Daten zu etwaigen unerw\u00fcnschten Nebenwirkungen,<br>&#8211; Informationen \u00fcber die Meldung von Trends,<br>&#8211; einschl\u00e4gige Fachliteratur oder technische Literatur, Datenbanken und\/oder Register,<br>&#8211; von Anwendern, H\u00e4ndlern und Importeuren \u00fcbermittelte Informationen, einschlie\u00dflich R\u00fcckmeldungen und Beschwerden und<br>&#8211; \u00f6ffentlich zug\u00e4ngliche Informationen \u00fcber \u00e4hnliche Medizinprodukte.<\/em><\/p>\n<cite><a href=\"https:\/\/mdr-selector.johner-institut.de\/mdr_de.html#annex-III\" target=\"_blank\" rel=\"noreferrer noopener\" label=\"MDR, Anhang III (opens in a new tab)\">MDR, Anhang III<\/a><\/cite><\/blockquote>\n\n\n\n<p>F\u00fcr Hersteller bedeutet das konkret die Umsetzung folgender Schritte: <\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Pr\u00fcfen, ob alle geforderten <strong>Informationen gesammelt und bewertet<\/strong> werden. Das muss die entsprechende Verfahrensanweisung auch beschreiben.<\/li>\n\n\n\n<li>Gew\u00e4hrleisten, dass diese Informationen auch auf <strong>Hinweise zur Verbesserung der Gebrauchstauglichkeit<\/strong> bewertet werden. Idealerweise k\u00f6nnen Hersteller das anhand von Beispielen demonstrieren.<\/li>\n\n\n\n<li>Sicherstellen, dass die <strong>Usability-Experten und Risikomanager<\/strong> in diesem Prozess <strong>eingebunden<\/strong> werden.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"hersteller\">3. Was Hersteller konkret tun sollten<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">a) Hersteller neuer Produkte<\/h3>\n\n\n\n<p>Hersteller, die neue Produkte entwickeln, folgen der <a href=\"https:\/\/www.johner-institut.de\/blog\/iec-62366-usability\/iec-62366-1-2015\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"IEC 62366-1 (opens in a new tab)\">IEC 62366-1<\/a>. Diese Norm beschreibt den Stand der Technik.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">b) Hersteller  von &#8222;Legacy-Produkten&#8220;<\/h3>\n\n\n\n<p>Hingegen sollten Hersteller von Produkten, die bereits entwickelt wurden und entweder neu zugelassen werden m\u00fcssen oder die von den <a href=\"https:\/\/www.johner-institut.de\/blog\/johner-institut\/uebergangsfristen-mdr\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"\u00dcbergangsfristen (opens in a new tab)\">\u00dcbergangsfristen<\/a> profitieren, die Konformit\u00e4t der Produkte nochmals bewerten.<\/p>\n\n\n\n<p>Das bedingt nicht notwendigerweise ein aufw\u00e4ndiges Konformit\u00e4tsbewertungsverfahren. Bereits die <strong>Checkliste des Johner Instituts<\/strong> (s.u.) hilft dabei, schnell erste Klarheit zu erreichen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">c) Alle Hersteller<\/h3>\n\n\n\n<p>Unabdingbar ist die Pflicht, die Post-Market-Daten systematisch zu sammeln und auf Hinweise zur Verbesserung der Gebrauchstauglichkeit zu bewerten. Dazu bedarf es geeigneter Prozesse, Werkzeuge und Experten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">d) Zusammenfassung<\/h3>\n\n\n\n<p>Zusammenfassend empfiehlt das Johner Institut somit folgende Schritte:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>F\u00fcr Produkte, die unter der MDR erstmalig in Verkehr gebracht werden, die <strong>IEC 62366-1 stringent befolgen<\/strong>.<\/li>\n\n\n\n<li>F\u00fcr alle anderen Produkte die unten genannte <strong>Checkliste durchgehen<\/strong>, <strong>Gaps identifizieren<\/strong> und entsprechende <strong>Ma\u00dfnahmen<\/strong> zum Schlie\u00dfen dieser Gaps <strong>durchf\u00fchren<\/strong>. Bei Ressourcenknappheit auf externe Unterst\u00fctzung zugreifen.<\/li>\n\n\n\n<li>F\u00fcr alle Produkte ein wirksames <strong>System zur Post-Market Surveillance etablieren<\/strong>.<\/li>\n<\/ol>\n\n\n\n<div class=\"defbox\">\n        <div class=\"definition\">\n            <i class=\"fa fa-exclamation-triangle\"><\/i> Vorsicht!\n        <\/div>\n        <p>Achtung: Auch Hersteller von Produkten, die von den \u00dcbergangfristen profitieren, d\u00fcrfen sich nicht zur\u00fccklehnen in der Annahme, dass die Konformit\u00e4t mit der MDD gegeben und damit ausreichend bewiesen ist, weil sie konform mit der (alten) IEC 62366 sind. Der Stand der Technik und das Risikomanagement zwingen die Hersteller de facto, die &#8222;neue&#8220; IEC 62366-1 zu beachten und damit implizit auch die MDR-Anforderungen zu erf\u00fcllen.<\/p>\n    <\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"checkliste\">4. Checkliste und weitere Unterst\u00fctzung durch das Johner Institut<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">a) Checkliste<\/h3>\n\n\n\n<p>Das Johner Institut hat eine Checkliste erarbeitet, mit der sich Hersteller einen schnellen \u00dcberblick dar\u00fcber verschaffen k\u00f6nnen, ob ihre Produkte und Prozesse dem Stand der Technik und den Anforderungen der MDR entsprechen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/02\/Checkliste-MDR-Usability-klein.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"590\" height=\"540\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/02\/Checkliste-MDR-Usability-klein.jpg\" alt=\"Screenshot der Checkliste zu den Anforderungen der MDR an die Gebrauchstauglichkeit (Usability)\" class=\"wp-image-5379925\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/02\/Checkliste-MDR-Usability-klein.jpg 590w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/02\/Checkliste-MDR-Usability-klein-300x275.jpg 300w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/a><figcaption class=\"wp-element-caption\">Abb. 1: Screenshot der Checkliste zu den Anforderungen der MDR an die Gebrauchstauglichkeit (Usability)<\/figcaption><\/figure>\n\n\n\n<p>Die kostenlose Checkliste k\u00f6nnen Sie hier herunterladen:<\/p>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-adddd6b4-9487-436a-b41b-b4ed18d7de06\" href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/02\/Checkliste-MDR-Usability_V2a.pdf\">Checkliste-MDR-Usability<\/a><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/02\/Checkliste-MDR-Usability_V2a.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-adddd6b4-9487-436a-b41b-b4ed18d7de06\">Herunterladen<\/a><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">b) Gaps identifizieren, Ma\u00dfnahmen festlegen<\/h3>\n\n\n\n<p>Die Usability-Expertinnen und -Experten des Johner Instituts helfen Ihnen dabei, Abweichungen schnell zu identifizieren und die richtigen Ma\u00dfnahmen festzulegen, um diese Gaps zu schlie\u00dfen.<\/p>\n\n\n\n<p>Aufgaben, bei denen Sie das Johner Institut unterst\u00fctzen kann, sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Review bestehender Gebrauchstauglichkeitsakten auf Konformit\u00e4t mit der IEC 62366-1<\/li>\n\n\n\n<li>\u00dcberpr\u00fcfen der Risikomanagementakte auf Vollst\u00e4ndigkeit und Konformit\u00e4t mit der MDR und ISO 14971<\/li>\n\n\n\n<li>Analyse von Prozessbeschreibungen, z.B. f\u00fcr die Post-Market Surveillance<\/li>\n\n\n\n<li>Pr\u00fcfung von <a rel=\"noreferrer noopener\" aria-label=\"Gebrauchsanweisungen (opens in a new tab)\" href=\"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/gebrauchsanweisungen\/\" target=\"_blank\">Gebrauchsanweisungen<\/a> auf Verst\u00e4ndlichkeit sowie auf Gesetzes- und Normenkonformit\u00e4t<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">c) Ma\u00dfnahmen schnell und m\u00f6glichst unaufw\u00e4ndig umsetzen<\/h3>\n\n\n\n<p>Die Expertinnen und Experten des Johner Instituts legen den Fokus darauf, jede Form unn\u00f6tiger Arbeit zu vermeiden und risikobasiert zu arbeiten. Sie verfolgen mit Ihnen gemeinsam das Ziel, die Sicherheit der Patienten zu gew\u00e4hrleisten sowie den Erfolg Ihrer Firma bei Audits sicherzustellen.<\/p>\n\n\n\n<p>Aufgaben, bei denen Sie das Johner Institut unterst\u00fctzen kann, sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Use Specification<\/strong> \u00fcberarbeiten und sch\u00e4rfen (um unn\u00f6tige Usability Tests zu vermeiden)<\/li>\n\n\n\n<li>Fehlende <strong>Use Scenarios<\/strong> beschreiben und auf Sicherheitsrelevanz bewerten<\/li>\n\n\n\n<li><strong>Verbesserungen des User Interfaces<\/strong> vorschlagen<\/li>\n\n\n\n<li><strong>Gebrauchsanweisungen<\/strong> erg\u00e4nzen (bzw. erstellen), um MDR-Konformit\u00e4t zu erreichen<\/li>\n\n\n\n<li><strong>Formative und summative Evaluationen<\/strong> durchf\u00fchren<\/li>\n\n\n\n<li>Ihren <strong>Post-Market-Prozess<\/strong> definieren und bei der Auswertung der Daten unterst\u00fctzen<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-group has-white-color has-ji-banner-gradient-background has-text-color has-background is-layout-constrained wp-container-core-group-is-layout-301020a0 wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/MicrosoftTeams-image-22-1.png\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/MicrosoftTeams-image-22-1-1024x1024.png\" alt=\"\" class=\"wp-image-5371837\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/MicrosoftTeams-image-22-1-1024x1024.png 1024w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/MicrosoftTeams-image-22-1-300x300.png 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/MicrosoftTeams-image-22-1-150x150.png 150w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/MicrosoftTeams-image-22-1-768x768.png 768w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/MicrosoftTeams-image-22-1-1536x1536.png 1536w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/MicrosoftTeams-image-22-1-2048x2048.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<h3 class=\"wp-block-heading has-white-color has-text-color\">Der Schl\u00fcssel zur erfolgreichen Erstellung einer gesetzeskonformen Gebrauchstauglichkeitsakte<\/h3>\n\n\n\n<p>Lernen Sie, wie Sie eine gesetzeskonforme Gebrauchstauglichkeitsakte mit allen notwendigen Dokumenten erstellen. Als Auditgarant-Mitglied haben Sie Zugriff auf unsere umfassende Sammlung an Vorlagen, die Ihnen Zeit und M\u00fche sparen werden. Unsere praxisorientierten Lerninhalte erm\u00f6glichen es Ihnen, Ihre Gebrauchstauglichkeitsakte schnell und einfach zu erstellen, ohne dabei Kompromisse bei der Qualit\u00e4t einzugehen.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-d445cf74 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-white-red\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.johner-institut.de\/digitale-dienstleistungen\/auditgarant\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mehr erfahren<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fazit\">5. Fazit und Zusammenfassung<\/h2>\n\n\n\n<p>Der erste Blick in die MDR t\u00e4uscht: Aus der Tatsache, dass die MDR den Begriff \u201eUsability\u201c kaum erw\u00e4hnt, darf man nicht schlie\u00dfen, dass die Gebrauchstauglichkeit der EU-Verordnung kein Anliegen sei. Das Gegenteil ist der Fall. Wie oben dargelegt, stellt sie umfangreiche Anforderungen an die Usability.<\/p>\n\n\n\n<p>Leider verwendet die MDR Begrifflichkeiten wie \u201eErgonomie\u201c etwas ungl\u00fccklich (\u00e4hnlich wie die DiGAV) und greift nicht auf bew\u00e4hrte Definitionen zur\u00fcck.<\/p>\n\n\n\n<p>Auch Hersteller von Produkten, die noch mit MDD-Zertifikaten in den Verkehr gebracht werden, d\u00fcrfen sich nicht zur\u00fccklehnen. Die Forderung nach dem Stand der Technik stellt auch die MDD. Die MDR und die IEC 62366-1 formulieren diesen Stand der Technik expliziter.<\/p>\n\n\n\n<p>Das Johner Institut empfiehlt den Herstellern, <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>sich mit der kostenlosen Checkliste eine rasche \u00dcbersicht zu verschaffen und <\/li>\n\n\n\n<li>sich von der Wirksamkeit und Konformit\u00e4t des Systems zur Post-Market Surveillance zu \u00fcberzeugen. Denn daf\u00fcr gibt es keine(!) \u00dcbergangsfristen.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Hersteller m\u00fcssen die Anforderungen der MDR an die Gebrauchstauglichkeit (Usability) f\u00fcr ausnahmslos alle Medizinprodukte nachweisen. F\u00fcr einige Produkte gelten \u00dcbergangsfristen. Doch die Hersteller sind gut beraten, sich gleich mit den Unterschieden zwischen den Anforderungen der MDD und der MDR an die Usability vertraut zu machen. Nur so k\u00f6nnen Sie die&nbsp;Transition auf die MDR problemlos bew\u00e4ltigen&nbsp;sowie&nbsp;regulatorischen&hellip;<\/p>\n","protected":false},"author":71,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1108,1102],"tags":[1065,265],"ppma_author":[1265],"class_list":["post-3207883","post","type-post","status-publish","format-standard","hentry","category-regulatory-affairs","category-iec-62366-usability","tag-grundlegende-anforderungen","tag-mdd","category-1108","category-1102","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anforderungen der MDR an die Usability | Mit kostenloser Checkliste<\/title>\n<meta name=\"description\" content=\"Die MDR stellt umfangreiche Anforderungen an die Usability, die z.T. ohne \u00dcbergangsfristen alle(!) Hersteller betreffen. ***Mit kostenloser Checkliste***\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anforderungen der MDR an die Usability | Mit kostenloser Checkliste\" \/>\n<meta property=\"og:description\" content=\"Die MDR stellt umfangreiche Anforderungen an die Usability, die z.T. ohne \u00dcbergangsfristen alle(!) Hersteller betreffen. ***Mit kostenloser Checkliste***\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/\" \/>\n<meta property=\"og:site_name\" content=\"Regulatorisches Wissen f\u00fcr Medizinprodukte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JohnerInstitut\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-18T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-31T14:49:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/02\/Checkliste-MDR-Usability-klein.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"590\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr. Philipp Schleer\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Philipp Schleer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/\"},\"author\":{\"name\":\"Dr. Philipp Schleer\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/167041ac9fced451b3f018b7842cf015\"},\"headline\":\"Anforderungen der MDR an die Usability\",\"datePublished\":\"2020-02-18T08:00:00+00:00\",\"dateModified\":\"2025-03-31T14:49:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/\"},\"wordCount\":2815,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Checkliste-MDR-Usability-klein.jpg\",\"keywords\":[\"Grundlegende Sicherheits- und Leistungsanforderungen\",\"Medizinprodukte-Richtlinie 93\\\/42\\\/EWG (Medical Device Directive MDD)\"],\"articleSection\":[\"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte\",\"Usability &amp; IEC 62366-1\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/\",\"name\":\"Anforderungen der MDR an die Usability | Mit kostenloser Checkliste\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Checkliste-MDR-Usability-klein.jpg\",\"datePublished\":\"2020-02-18T08:00:00+00:00\",\"dateModified\":\"2025-03-31T14:49:06+00:00\",\"description\":\"Die MDR stellt umfangreiche Anforderungen an die Usability, die z.T. ohne \u00dcbergangsfristen alle(!) Hersteller betreffen. ***Mit kostenloser Checkliste***\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Checkliste-MDR-Usability-klein.jpg\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Checkliste-MDR-Usability-klein.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/anforderungen-der-mdr-an-die-usability\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/category\\\/regulatory-affairs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anforderungen der MDR an die Usability\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"name\":\"Regulatorisches Wissen f\u00fcr Medizinprodukte\",\"description\":\"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\",\"name\":\"Johner Institut GmbH\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"width\":1213,\"height\":286,\"caption\":\"Johner Institut GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JohnerInstitut\\\/\",\"https:\\\/\\\/x.com\\\/christianjohner\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/JohnerInstitut\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/167041ac9fced451b3f018b7842cf015\",\"name\":\"Dr. Philipp Schleer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Portrait_1-750x750-Philipp_Schleer.jpgd83e70e1ca634d6dfa6e6775e8c19413\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Portrait_1-750x750-Philipp_Schleer.jpg\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Portrait_1-750x750-Philipp_Schleer.jpg\",\"caption\":\"Dr. Philipp Schleer\"},\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/author\\\/philipp-schleer\\\/\"}]}<\/script>\n<meta name=\"copyright\" content=\"Johner Institut GmbH\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anforderungen der MDR an die Usability | Mit kostenloser Checkliste","description":"Die MDR stellt umfangreiche Anforderungen an die Usability, die z.T. ohne \u00dcbergangsfristen alle(!) Hersteller betreffen. ***Mit kostenloser Checkliste***","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/","og_locale":"de_DE","og_type":"article","og_title":"Anforderungen der MDR an die Usability | Mit kostenloser Checkliste","og_description":"Die MDR stellt umfangreiche Anforderungen an die Usability, die z.T. ohne \u00dcbergangsfristen alle(!) Hersteller betreffen. ***Mit kostenloser Checkliste***","og_url":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/","og_site_name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","article_publisher":"https:\/\/www.facebook.com\/JohnerInstitut\/","article_published_time":"2020-02-18T08:00:00+00:00","article_modified_time":"2025-03-31T14:49:06+00:00","og_image":[{"width":590,"height":540,"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/02\/Checkliste-MDR-Usability-klein.jpg","type":"image\/jpeg"}],"author":"Dr. Philipp Schleer","twitter_misc":{"Verfasst von":"Dr. Philipp Schleer","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/#article","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/"},"author":{"name":"Dr. Philipp Schleer","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/167041ac9fced451b3f018b7842cf015"},"headline":"Anforderungen der MDR an die Usability","datePublished":"2020-02-18T08:00:00+00:00","dateModified":"2025-03-31T14:49:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/"},"wordCount":2815,"commentCount":4,"publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/02\/Checkliste-MDR-Usability-klein.jpg","keywords":["Grundlegende Sicherheits- und Leistungsanforderungen","Medizinprodukte-Richtlinie 93\/42\/EWG (Medical Device Directive MDD)"],"articleSection":["Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte","Usability &amp; IEC 62366-1"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/","url":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/","name":"Anforderungen der MDR an die Usability | Mit kostenloser Checkliste","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/#primaryimage"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/02\/Checkliste-MDR-Usability-klein.jpg","datePublished":"2020-02-18T08:00:00+00:00","dateModified":"2025-03-31T14:49:06+00:00","description":"Die MDR stellt umfangreiche Anforderungen an die Usability, die z.T. ohne \u00dcbergangsfristen alle(!) Hersteller betreffen. ***Mit kostenloser Checkliste***","breadcrumb":{"@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/#primaryimage","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/02\/Checkliste-MDR-Usability-klein.jpg","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/02\/Checkliste-MDR-Usability-klein.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/anforderungen-der-mdr-an-die-usability\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.johner-institut.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte","item":"https:\/\/www.johner-institut.de\/blog\/category\/regulatory-affairs\/"},{"@type":"ListItem","position":3,"name":"Anforderungen der MDR an die Usability"}]},{"@type":"WebSite","@id":"https:\/\/www.johner-institut.de\/blog\/#website","url":"https:\/\/www.johner-institut.de\/blog\/","name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","description":"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen","publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.johner-institut.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.johner-institut.de\/blog\/#organization","name":"Johner Institut GmbH","url":"https:\/\/www.johner-institut.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","width":1213,"height":286,"caption":"Johner Institut GmbH"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JohnerInstitut\/","https:\/\/x.com\/christianjohner","https:\/\/www.youtube.com\/user\/JohnerInstitut"]},{"@type":"Person","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/167041ac9fced451b3f018b7842cf015","name":"Dr. Philipp Schleer","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/10\/Portrait_1-750x750-Philipp_Schleer.jpgd83e70e1ca634d6dfa6e6775e8c19413","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/10\/Portrait_1-750x750-Philipp_Schleer.jpg","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/10\/Portrait_1-750x750-Philipp_Schleer.jpg","caption":"Dr. Philipp Schleer"},"url":"https:\/\/www.johner-institut.de\/blog\/author\/philipp-schleer\/"}]}},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":10161,"url":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/medical-device-regulation-mdr-medizinprodukteverordnung\/","url_meta":{"origin":3207883,"position":0},"title":"Medical Device Regulation MDR \u2013 Medizinprodukteverordnung  (2017\/745) Stand 2024","author":"Dr. Manuela Reinhold","date":"4. Februar 2025","format":false,"excerpt":"Die europ\u00e4ische\u00a0Medical Device Regulation\u00a0MDR (EU-Medizinprodukteverordnung) m\u00fcssen Hersteller beachten, die Medizinprodukte in der EU in den Verkehr bringen wollen. Diese Verordnung (EU) 2017\/745 \u00fcber Medizinprodukte, so der offizielle Titel, stellt auch Anforderungen an Benannte Stellen, H\u00e4ndler, Importeure und Gesundheitseinrichtungen wie Krankenh\u00e4user. Tipps zur MDR \u2026 \u2026 f\u00fcr Anf\u00e4nger Falls Sie ganz\u2026","rel":"","context":"In &quot;Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte&quot;","block_context":{"text":"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte","link":"https:\/\/www.johner-institut.de\/blog\/category\/regulatory-affairs\/"},"img":{"alt_text":"MDR: Kapitel\u00fcbersicht","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/06\/MDR-Kapitel.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/06\/MDR-Kapitel.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/06\/MDR-Kapitel.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2016\/06\/MDR-Kapitel.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5371621,"url":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/unterschiede-zwischen-mdr-und-mdd\/","url_meta":{"origin":3207883,"position":1},"title":"Unterschiede zwischen MDR und MDD","author":"Prof. Dr. Christian Johner","date":"20. April 2023","format":false,"excerpt":"Die Unterschiede zwischen der MDR und MDD sind gro\u00df. Dieser Artikel stellt diese Unterschiede vor. Damit verschafft er Herstellern, die ihre Produkte noch unter einer EU-Richtlinie (insbesondere MDD) in den Markt gebracht haben, einen \u00dcberblick \u00fcber die zu schlie\u00dfenden \u201eGaps\u201c. 1. Wie es zu den Unterschieden zwischen MDR und MDD\u2026","rel":"","context":"In &quot;Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte&quot;","block_context":{"text":"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte","link":"https:\/\/www.johner-institut.de\/blog\/category\/regulatory-affairs\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/EU-Regulations-EU-Directives.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/EU-Regulations-EU-Directives.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/EU-Regulations-EU-Directives.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/EU-Regulations-EU-Directives.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/EU-Regulations-EU-Directives.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/EU-Regulations-EU-Directives.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":3079705,"url":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/mdr-ivdr-gesundheitseinrichtungen\/","url_meta":{"origin":3207883,"position":2},"title":"Auswirkungen der MDR und IVDR auf Gesundheitseinrichtungen wie Kliniken und andere Betreiber","author":"Ulrich Hafen","date":"31. Mai 2023","format":false,"excerpt":"MDR und IVDR stellen auf Hunderten Seiten Anforderungen, v. a. an die Hersteller von Medizinprodukten und IVD. Doch einige dieser Anforderungen betreffen auch die sogenannten Gesundheitseinrichtungen, also Kliniken, Krankenh\u00e4user und medizinische Labore. Das Verst\u00e4ndnis dieser Anforderungen hilft den Betreibern, regulatorische Probleme zu vermeiden, und den Herstellern, im Markt erfolgreich zu\u2026","rel":"","context":"In &quot;Gesundheitswesen &amp; Health IT&quot;","block_context":{"text":"Gesundheitswesen &amp; Health IT","link":"https:\/\/www.johner-institut.de\/blog\/category\/gesundheitswesen\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4673828,"url":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/legacy-devices\/","url_meta":{"origin":3207883,"position":3},"title":"Was Hersteller \u00fcber Legacy Devices wissen m\u00fcssen","author":"Prof. Dr. Christian Johner","date":"23. September 2024","format":false,"excerpt":"Gesetzgeber \u00e4ndern kontinuierlich die Regelwerke f\u00fcr Medizinprodukte. So ist das in Europa mit den EU-Verordnungen 2017\/745 (MDR) und 2017\/746 (IVDR) geschehen. Dadurch kommen Fragen zum Umgang mit Legacy Devices auf. Das sind Medizinprodukte, die Hersteller nach den alten Regelungen legal auf den Markt gebracht haben und weiterhin bringen, die aber\u2026","rel":"","context":"In &quot;Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte&quot;","block_context":{"text":"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte","link":"https:\/\/www.johner-institut.de\/blog\/category\/regulatory-affairs\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":968796,"url":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/systeme-und-behandlungseinheiten\/","url_meta":{"origin":3207883,"position":4},"title":"Systeme und Behandlungseinheiten","author":"Mario Klessascheck","date":"6. August 2024","format":false,"excerpt":"Die europ\u00e4ische Gesetzgebung definiert Systeme und Behandlungseinheiten (\u201esystems and procedure packs\u201c) und unterscheidet verschiedene Konstellationen. Die regulatorischen Anforderungen an die Hersteller h\u00e4ngen stark von diesen Konstellationen ab. Lesen Sie in diesem Artikel, was die Gesetzgeber unter Systemen und Behandlungseinheiten verstehen, was die wichtigsten gesetzlichen Anforderungen an die Hersteller sind und\u2026","rel":"","context":"In &quot;Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte&quot;","block_context":{"text":"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte","link":"https:\/\/www.johner-institut.de\/blog\/category\/regulatory-affairs\/"},"img":{"alt_text":"Systeme und Behandlungseinheiten (Venn Diagramm)","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2017\/10\/systeme-und-behandlungseinheiten.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2017\/10\/systeme-und-behandlungseinheiten.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2017\/10\/systeme-und-behandlungseinheiten.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2405010,"url":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/medizinprodukte-der-klasse-1\/","url_meta":{"origin":3207883,"position":5},"title":"Medizinprodukte der Klasse 1","author":"Markus Gerhart","date":"28. M\u00e4rz 2025","format":false,"excerpt":"Die Medical Device Coordination Group (MDCG) hat ein Guidance Document entworfen, das beschreibt, wie Hersteller ihre Medizinprodukte der Klasse 1 MDR-konform in den Verkehr bringen sollen. Das Dokument tr\u00e4gt den Titel Guidance Notes for Manufacturers of Class I Medical Devices. Dieser Artikel fasst dieses Dokument zusammen und gibt Herstellern dieser\u2026","rel":"","context":"In &quot;Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte&quot;","block_context":{"text":"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte","link":"https:\/\/www.johner-institut.de\/blog\/category\/regulatory-affairs\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2019\/06\/Medizinprodukt-Klasse-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2019\/06\/Medizinprodukt-Klasse-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2019\/06\/Medizinprodukt-Klasse-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2019\/06\/Medizinprodukt-Klasse-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2019\/06\/Medizinprodukt-Klasse-1.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2019\/06\/Medizinprodukt-Klasse-1.png?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pavawf-dsw3","jetpack_sharing_enabled":true,"authors":[{"term_id":1265,"user_id":71,"is_guest":0,"slug":"philipp-schleer","display_name":"Dr. Philipp Schleer","avatar_url":{"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/10\/Portrait_1-750x750-Philipp_Schleer.jpg","url2x":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/10\/Portrait_1-750x750-Philipp_Schleer.jpg"},"author_category":"","first_name":"Dr. Philipp","last_name":"Schleer","user_url":"","user_url_2":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/3207883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/comments?post=3207883"}],"version-history":[{"count":26,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/3207883\/revisions"}],"predecessor-version":[{"id":5380407,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/3207883\/revisions\/5380407"}],"wp:attachment":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/media?parent=3207883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/categories?post=3207883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/tags?post=3207883"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/ppma_author?post=3207883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}