{"id":4583377,"date":"2024-04-19T20:09:10","date_gmt":"2024-04-19T18:09:10","guid":{"rendered":"https:\/\/www.johner-institut.de\/blog\/?p=4583377"},"modified":"2024-10-20T15:48:03","modified_gmt":"2024-10-20T13:48:03","slug":"telematikinfrastruktur","status":"publish","type":"post","link":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/","title":{"rendered":"Telematikinfrastruktur: 5 Anforderungen, die Software-Hersteller beachten m\u00fcssen"},"content":{"rendered":"\n<p>Die <strong>Telematikinfrastruktur (TI)<\/strong> ist eine Plattform bzw. ein Netzwerk, \u00fcber das in Deutschland Gesundheitsdaten sicher ausgetauscht werden und auf der Gesundheitsanwendungen wie die elektronische Patientenakte und das e-Rezept betrieben werden sollen.<\/p>\n\n\n\n<p>Dieser Beitrag hilft <strong>Herstellern medizinischer Software<\/strong> zu verstehen, wann sie welche gesetzlichen und technischen Anforderungen im Kontext dieser Telematikinfrastruktur erf\u00fcllen m\u00fcssen. <\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 aria-label=\"1. Anforderungen an Hersteller\" id=\"1-zusammenfassung-anforderungen-durch-die-telematikinfrastruktur\">1. Zusammenfassung: Anforderungen der Telematikinfrastruktur an die Hersteller<\/h2>\n\n\n\n<div class=\"jig_defbox\"><div class=\"jig_defbox-definition\"><div class=\"jig_defbox-icon-wrapper\" style=\"fill:#919191\"><svg viewBox=\"0 0 576 512\" width=\"24\" height=\"24\" class=\"dashicons\" aria-hidden=\"true\"><path d=\"M569.5,440c18.5,32-4.7,72-41.6,72H48.1c-36.9,0-60-40.1-41.6-72L246.4,24c18.5-32,64.7-32,83.2,0L569.5,440 L569.5,440z M288,354c-25.4,0-46,20.6-46,46s20.6,46,46,46s46-20.6,46-46S313.4,354,288,354z M244.3,188.7l7.4,136 c0.3,6.4,5.6,11.3,12,11.3h48.5c6.4,0,11.6-5,12-11.3l7.4-136c0.4-6.9-5.1-12.7-12-12.7h-63.4C249.4,176,244,181.8,244.3,188.7 L244.3,188.7z\"><\/path><\/svg><\/div><span class=\"jig_defbox-header\" style=\"color:#919191\">Hinweis<\/span><\/div>\n<p>Dieses Kapitel fasst die Anforderungen zusammen. Die Details und die Erkl\u00e4rung der Begriffe folgen in den weiteren Kapiteln.<\/p>\n<\/div>\n\n\n\n<p>Gesetze f\u00fchren direkt oder indirekt (\u00fcber die Betreiber) zu Anforderungen, die f\u00fcr Hersteller medizinischer Software relevant sind:<\/p>\n\n\n\n<ol style=\"list-style-type:1\" class=\"wp-block-list\">\n<li><strong>Anforderungen an gesetzlich definierte Schnittstellen nach ISiK<\/strong><br>Falls ihre Produkte zu den \u201ebest\u00e4tigungsrelevanten Systemen\u201c z\u00e4hlen, m\u00fcssen sie eine Schnittstelle implementieren und dabei z. B. die Spezifikation des ISiK-Basismoduls beachten. Dazu weiter unten mehr.<\/li>\n\n\n\n<li><strong>Anforderungen an strukturierte Datens\u00e4tze bez\u00fcglich MIO<\/strong><br>Falls die Hersteller Daten in die elektronische Patientenakte (ePA) schreiben oder darauf zugreifen wollen, m\u00fcssen deren Produkte ebenfalls medizinische Informationsobjekte (MIO) austauschen k\u00f6nnen.<\/li>\n\n\n\n<li><strong>Anforderungen an \u201eInformationstechnische Systeme im Gesundheitswesen\u201c<\/strong><br>Hersteller sonstiger IT-Systeme wie DIGA, Krankenhaus- und Praxisverwaltungssysteme sind nicht mehr frei in der Wahl der Interoperabilit\u00e4tsstandards. Diese gibt die gematik vor.<\/li>\n\n\n\n<li><strong>Anforderungen an Implantate und Hilfsmittel<\/strong><br>Produkte, die im Kontext der Implantate oder als Hilfsmittel Daten \u00fcbertragen, m\u00fcssen unter bestimmten Voraussetzungen auch standardisierte Schnittstellen f\u00fcr Digitale Gesundheitsanwendungen anbieten.<\/li>\n\n\n\n<li><strong>Anforderungen an Kommunikationsstandards im Kontext KIM und TIM<\/strong><br>Nicht durch das Gesetz, sondern durch die Kunden (Krankenh\u00e4user, niedergelassene \u00c4rzte) getrieben, sollten Hersteller die Kommunikation durch KIM und TIM erm\u00f6glichen.<\/li>\n<\/ol>\n\n\n\n<div class=\"jig_defbox\"><div class=\"jig_defbox-definition\"><div class=\"jig_defbox-icon-wrapper\" style=\"fill:#919191\"><svg viewBox=\"0 0 48 48\" width=\"24\" height=\"24\" class=\"dashicons\" aria-hidden=\"true\"><g><path d=\"M20,19.5h16v-3H20V19.5z M20,25.5h16v-3H20V25.5z M20,31.5h10v-3H20V31.5z M14.1,20c0.6,0,1-0.2,1.4-0.6 c0.4-0.4,0.6-0.9,0.6-1.4s-0.2-1-0.6-1.4c-0.4-0.4-0.9-0.6-1.4-0.6c-0.6,0-1,0.2-1.4,0.6c-0.4,0.4-0.6,0.9-0.6,1.4 c0,0.6,0.2,1,0.6,1.4C13,19.9,13.5,20,14.1,20z M14.1,26c0.6,0,1-0.2,1.4-0.6c0.4-0.4,0.6-0.9,0.6-1.4c0-0.6-0.2-1-0.6-1.4 S14.6,22,14.1,22c-0.6,0-1,0.2-1.4,0.6s-0.6,0.9-0.6,1.4c0,0.6,0.2,1,0.6,1.4S13.5,26,14.1,26z M14.1,32c0.6,0,1-0.2,1.4-0.6 c0.4-0.4,0.6-0.9,0.6-1.4c0-0.6-0.2-1-0.6-1.4c-0.4-0.4-0.9-0.6-1.4-0.6c-0.6,0-1,0.2-1.4,0.6s-0.6,0.9-0.6,1.4 c0,0.6,0.2,1,0.6,1.4S13.5,32,14.1,32z M7,40c-1.7,0-3-1.4-3-3V11c0-0.8,0.3-1.5,0.9-2.1C5.5,8.3,6.2,8,7,8h34 c0.8,0,1.5,0.3,2.1,0.9C43.7,9.5,44,10.2,44,11v26c0,0.8-0.3,1.5-0.9,2.1C42.5,39.7,41.8,40,41,40L7,40z M7,37h34V11H7V37z M7,11\"><\/path><\/g><\/svg><\/div><span class=\"jig_defbox-header\" style=\"color:#919191\">Weiterf\u00fchrende Informationen<\/span><\/div>\n<p>Ein weiterer Artikel verschafft Ihnen <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/interoperabilitat\/\">eine Einf\u00fchrung ins Thema Interoperabilit\u00e4t<\/a>.<\/p>\n<\/div>\n\n\n\n<h2 aria-label=\"2. \u00dcbersicht\" id=\"2-ubersicht-uber-die-telematikinfrastruktur\">2. \u00dcbersicht \u00fcber die Telematikinfrastruktur&nbsp;<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-ziele\">a) Ziele<\/h3>\n\n\n\n<p>Einer der ersten Treiber der Telematikinfrastruktur war der Wunsch, Fehlbehandlungen sowie unerw\u00fcnschte Neben- und Wechselwirkungen von Medikamenten zu minimieren. <\/p>\n\n\n\n<p>Aktuell verfolgt die TI einen eher normierenden Ansatz zur Digitalisierung im Gesundheitswesen. Sie soll das digitale Gesundheitswesen technisch ins 21. Jahrhundert bringen und so zur Verbesserung der Gesundheitsversorgung beitragen.<\/p>\n\n\n\n<p>Die Telematikinfrastruktur soll die notwendigen Voraussetzungen schaffen, um<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>einen sicheren Datenaustausch zu gew\u00e4hrleisten (IT-Security),<\/li>\n\n\n\n<li>den Datenschutz zu erm\u00f6glichen (Data Protection, Confidentiality),<\/li>\n\n\n\n<li>die Verf\u00fcgbarkeit der Daten sicherzustellen (Availability),<\/li>\n\n\n\n<li>die Interoperabilit\u00e4t der Systeme zu gew\u00e4hrleisten (Interoperability),<\/li>\n\n\n\n<li>die Aufw\u00e4nde und Kosten zu senken (Efficiency).<\/li>\n<\/ul>\n\n\n\n<p>Diese Voraussetzungen sollen dazu beitragen, dass<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Innovationen erfolgen, z. B. im Bereich der IT-Systeme, bei medizinischen Dienstleistungen oder bei der Gestaltung medizinischer Prozesse,<\/li>\n\n\n\n<li>die Effizienz im Gesundheitswesen steigt, und zwar sowohl bei der Entwicklung als auch bei der Nutzung dieser Produkte und Dienstleistungen, und<\/li>\n\n\n\n<li>die Forschung Zugang zu den notwendigen Daten erh\u00e4lt.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"b-aufbau\">b) Aufbau<\/h3>\n\n\n\n<p>Die Telematikinfrastruktur wird vereinfacht als Datenautobahn f\u00fcr das Gesundheitswesen bezeichnet (z. B.&nbsp;<a href=\"https:\/\/www.kbv.de\/html\/telematikinfrastruktur.php\">von der KBV<\/a>). Diese Infrastruktur besteht aus Hardware und Software, die gemeinsame Regeln befolgen m\u00fcssen, z. B. zur Interoperabilit\u00e4t.&nbsp;<\/p>\n\n\n\n<p>Zur Hardware z\u00e4hlen:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sogenannte Konnektoren (spezielle Router)<\/li>\n\n\n\n<li>Karten zum Authentifizieren: elektronische Gesundheitskarte (eGK), elektronischer Heilberufeausweis (eHBA) und Karten zum Identifizieren von Institutionen wie Krankenh\u00e4usern (SMC)<\/li>\n\n\n\n<li>Kartenleseger\u00e4te<\/li>\n\n\n\n<li>Computer zum Betreiben von Diensten<\/li>\n<\/ul>\n\n\n\n<p>Die Software realisiert die Dienste:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Zentrale Dienste: Verzeichnisdienste, PKI-Dienste, VPN-Zugangsdienste, \u2026<\/li>\n\n\n\n<li>Mehrwertdienste (Dritter), also Anwendungen wie die elektronische Patientenakte (ePA), das elektronische Rezept (eRezept) und die elektronische Arbeitsunf\u00e4higkeitsbescheinigung (eAU)<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small.png\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"337\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small.png\" alt=\"\u00dcbersicht \u00fcber die Telematikinfrastruktur TI\" class=\"wp-image-4600091\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small.png 1000w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small-300x101.png 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small-768x259.png 768w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small-200x67.png 200w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small-400x135.png 400w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small-600x202.png 600w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small-800x270.png 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption class=\"wp-element-caption\">Abb. 1: \u00dcbersicht \u00fcber die Telematikinfrastruktur TI (zum Vergr\u00f6\u00dfern klicken)<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"c-grundsatz-der-patientenhoheit\">c) Grundsatz der Patientenhoheit<\/h3>\n\n\n\n<p>Nach den gesetzlichen Anforderungen (SGB) soll die Telematikinfrastruktur Behandlungsdaten von Patienten zu den einzelnen Leistungserbringern \u00fcbermitteln. Dazu wurden und werden Datenspeicher aufgebaut \u2013 zun\u00e4chst nur f\u00fcr gesetzlich Versicherte, inzwischen aber auch f\u00fcr die meisten privat krankenversicherten B\u00fcrger.<\/p>\n\n\n\n<p>Auch wenn diese Daten nicht beim Patienten abgespeichert sind, ist es dennoch ein Grundsatz, dass nur dieser dar\u00fcber entscheiden darf, wer welche Daten erheben oder verarbeiten darf.<\/p>\n\n\n\n<div class=\"jig_defbox\"><div class=\"jig_defbox-definition\"><div class=\"jig_defbox-icon-wrapper\" style=\"fill:#919191\"><svg viewBox=\"0 0 512 512\" width=\"24\" height=\"24\" class=\"dashicons\" aria-hidden=\"true\"><g><path d=\"M430.9,177.6c-0.3-96-78.1-174.1-174-174.9c-0.1,0-0.2,0-0.4,0c-0.2,0-0.4,0-0.5,0c-0.2,0-0.4,0-0.5,0 c-0.1,0-0.2,0-0.4,0c-95.9,0.8-173.7,78.9-174,174.9c-0.4,7.3-1.9,60.3,36.6,109.2c29.5,37.6,49.4,74.7,55,85.9v63.5 c0,0,0,0.1,0,0.1c0,0.5,0,0.9,0.1,1.4c0,0.3,0.1,0.6,0.1,0.9c0,0.1,0,0.2,0,0.2c0.4,2.7,1.4,5.2,3,7.4l33.7,55.1 c3.1,5.1,8.7,8.2,14.7,8.2h61.8c6,0,11.5-3.1,14.7-8.2l33.7-55.1c1.5-2.1,2.6-4.6,3-7.4c0-0.1,0-0.2,0-0.2c0-0.3,0.1-0.6,0.1-0.9 c0-0.5,0.1-0.9,0.1-1.4c0,0,0-0.1,0-0.1v-60.3c1.2-2.4,22.3-45.5,56.7-89.2C432.8,237.8,431.3,184.9,430.9,177.6z M303.3,418.8 h-96.2v-33.1h96.2V418.8z M276.4,475h-42.5l-13.3-21.6h69L276.4,475z M311.6,351.4H200.4c-8.6-16.3-28-50.6-55.7-85.9 c-32-40.6-29.3-85.7-29.3-86c0-0.4,0.1-0.9,0.1-1.3c0-77.6,63-140.8,140.5-141.1c77.5,0.3,140.5,63.5,140.5,141.1 c0,0.4,0,0.9,0.1,1.3c0,0.4,3.1,44.9-29.3,86C339.5,300.8,320.2,335.1,311.6,351.4z\"><\/path><path d=\"M257.8,64.4c-62,0-112.5,50.5-112.5,112.5c0,9.5,7.7,17.2,17.2,17.2s17.2-7.7,17.2-17.2 c0-43.1,35-78.1,78.1-78.1c9.5,0,17.2-7.7,17.2-17.2S267.3,64.4,257.8,64.4z\"><\/path><\/g><\/svg><\/div><span class=\"jig_defbox-header\" style=\"color:#919191\">Beachten Sie auch den Podcast zur Telematik-Infrastruktur!<\/span><\/div>\n<p>Seit \u00fcber einer Dekade verspricht die Telematik-Infrastruktur, das Gesundheitswesen leistungsf\u00e4higer zu machen, die Vorsorge und die Behandlung von Patienten zu verbessern. Doch welche Versprechen sind wirklich eingel\u00f6st worden? Wie weit hat die Telematik-Infrastruktur wirklich Einzug in den Alltag von Kliniken und Praxen gefunden?<\/p>\n\n\n\n<p>Christian Johner geht in seinem Gespr\u00e4ch mit Nick Seidel genau diesen Fragen nach. Nick Seidel ist ein Experte f\u00fcr das Thema Interoperabilit\u00e4t und auch an der Weiterentwicklung von ISiK beteiligt. <\/p>\n\n\n\n<p>Diese und weitere Podcast-Episoden finden Sie auch&nbsp;<a href=\"https:\/\/www.johner-institut.de\/podcast\/medical-device-insights\/\">hier<\/a>.<\/p>\n<\/div>\n\n\n\t\t\t<style type=\"text\/css\">#pp-podcast-977 a, .pp-modal-window .modal-977 a, .pp-modal-window .aux-modal-977 a, #pp-podcast-977 .ppjs__more { color: #dc1a22; } #pp-podcast-977:not(.modern) .ppjs__audio .ppjs__button.ppjs__playpause-button button *, #pp-podcast-977:not(.modern) .ppjs__audio .ppjs__button.ppjs__playpause-button button:hover *, #pp-podcast-977:not(.modern) .ppjs__audio .ppjs__button.ppjs__playpause-button button:focus *, .pp-modal-window .modal-977 .ppjs__audio .ppjs__button.ppjs__playpause-button button *, .pp-modal-window .modal-977 .ppjs__audio .ppjs__button.ppjs__playpause-button button:hover *, .pp-modal-window .modal-977 .ppjs__audio .ppjs__button.ppjs__playpause-button button:focus *, .pp-modal-window .aux-modal-977 .pod-entry__play *, .pp-modal-window .aux-modal-977 .pod-entry__play:hover * { color: #dc1a22 !important; } #pp-podcast-977.postview .episode-list__load-more, .pp-modal-window .aux-modal-977 .episode-list__load-more, #pp-podcast-977:not(.modern) .ppjs__time-handle-content, .modal-977 .ppjs__time-handle-content { border-color: #dc1a22 !important; } #pp-podcast-977:not(.modern) .ppjs__audio-time-rail, #pp-podcast-977.lv3 .pod-entry__play, #pp-podcast-977.lv4 .pod-entry__play, #pp-podcast-977.gv2 .pod-entry__play, #pp-podcast-977.modern.wide-player .ppjs__audio .ppjs__button.ppjs__playpause-button button, #pp-podcast-977.modern.wide-player .ppjs__audio .ppjs__button.ppjs__playpause-button button:hover, #pp-podcast-977.modern.wide-player .ppjs__audio .ppjs__button.ppjs__playpause-button button:focus, .pp-modal-window .modal-977 button.episode-list__load-more, .pp-modal-window .modal-977 .ppjs__audio-time-rail, .pp-modal-window .modal-977 button.pp-modal-close { background-color: #dc1a22 !important; } #pp-podcast-977 .hasCover .ppjs__audio .ppjs__button.ppjs__playpause-button button { background-color: rgba(0, 0, 0, 0.5) !important; } .pp-modal-window .modal-977 button.episode-list__load-more:hover, .pp-modal-window .modal-977 button.episode-list__load-more:focus, .pp-modal-window .aux-modal-977 button.episode-list__load-more:hover, .pp-modal-window .aux-modal-977 button.episode-list__load-more:focus { background-color: rgba( 220,26,34, 0.7 ) !important; } #pp-podcast-977 .ppjs__button.toggled-on, .pp-modal-window .modal-977 .ppjs__button.toggled-on, #pp-podcast-977.playerview .pod-entry.activeEpisode, .pp-modal-window .modal-977.playerview .pod-entry.activeEpisode { background-color: rgba( 220,26,34, 0.1 ); } #pp-podcast-977.postview .episode-list__load-more { background-color: transparent !important; } #pp-podcast-977.modern:not(.wide-player) .ppjs__audio .ppjs__button.ppjs__playpause-button button *, #pp-podcast-977.modern:not(.wide-player) .ppjs__audio .ppjs__button.ppjs__playpause-button button:hover *, #pp-podcast-977.modern:not(.wide-player) .ppjs__audio .ppjs__button.ppjs__playpause-button button:focus * { color: #dc1a22 !important; } #pp-podcast-977.modern:not(.wide-player) .ppjs__time-handle-content { border-color: #dc1a22 !important; } #pp-podcast-977.modern:not(.wide-player) .ppjs__audio-time-rail { background-color: #dc1a22 !important; } #pp-podcast-977, .modal-977, .aux-modal-977 { --pp-accent-color: #dc1a22; } #pp-podcast-977 .ppjs__script-button { display: none; }<\/style>\n\t\t\t<div id=\"pp-podcast-977\" class=\"pp-podcast single-episode has-header header-hidden playerview media-audio hide-download hide-description hide-content\"  data-teaser=\"\" data-elength=\"18\" data-eunit=\"\" data-ppsdata=\"{&quot;ppe-977-1&quot;:{&quot;title&quot;:&quot;2022-01: Telematik-Infrastruktur &#8211; raus aus der Zeitschleife?&quot;,&quot;author&quot;:&quot;Nick Seidel, Prof. Dr. Christian Johner&quot;,&quot;date&quot;:&quot;18. Januar 2022&quot;,&quot;link&quot;:&quot;https:\\\/\\\/johner-institut.podigee.io\\\/42-telematikinfrastruktur&quot;,&quot;src&quot;:&quot;https:\\\/\\\/audio.podigee-cdn.net\\\/640033-m-29f3f04ce3c2cadca0df1433a5175c00.mp3?source=feed&quot;,&quot;mediatype&quot;:&quot;audio&quot;,&quot;season&quot;:0,&quot;categories&quot;:[],&quot;duration&quot;:&quot;21:14&quot;,&quot;episodetype&quot;:&quot;full&quot;,&quot;timestamp&quot;:1642473300,&quot;key&quot;:&quot;d797aded9d749392c01ca092695842b1&quot;},&quot;load_info&quot;:{&quot;loaded&quot;:1,&quot;displayed&quot;:1,&quot;offset&quot;:0,&quot;maxItems&quot;:1,&quot;src&quot;:&quot;5a329de0e539499bf1ed92d7abcc9adb&quot;,&quot;step&quot;:1,&quot;sortby&quot;:&quot;sort_date_desc&quot;,&quot;filterby&quot;:&quot;telematik&quot;,&quot;fixed&quot;:&quot;&quot;,&quot;args&quot;:{&quot;imgurl&quot;:&quot;https:\\\/\\\/images.podigee-cdn.net\\\/0x,sqvWI5fZv_m3DhwUGGW8fZRSSgFarfP0F8a2nNIFtktA=\\\/https:\\\/\\\/main.podigee-cdn.net\\\/uploads\\\/u17081\\\/b9425c6a-8ecc-48cf-888c-a2351bacd246.jpg&quot;,&quot;imgset&quot;:&quot;&quot;,&quot;display&quot;:&quot;&quot;,&quot;hddesc&quot;:1,&quot;hdfeat&quot;:1,&quot;oricov&quot;:&quot;https:\\\/\\\/images.podigee-cdn.net\\\/0x,sqvWI5fZv_m3DhwUGGW8fZRSSgFarfP0F8a2nNIFtktA=\\\/https:\\\/\\\/main.podigee-cdn.net\\\/uploads\\\/u17081\\\/b9425c6a-8ecc-48cf-888c-a2351bacd246.jpg&quot;,&quot;elength&quot;:18}},&quot;rdata&quot;:{&quot;permalink&quot;:&quot;https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/4583377&quot;,&quot;fprint&quot;:&quot;5a329de0e539499bf1ed92d7abcc9adb&quot;,&quot;from&quot;:&quot;feedurl&quot;,&quot;elen&quot;:18,&quot;eunit&quot;:&quot;&quot;,&quot;teaser&quot;:&quot;&quot;,&quot;title&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;&quot;}}\"><div class=\"pp-podcast__wrapper\"><div class=\"pp-podcast__info pod-info\"><div class=\"pod-info__header pod-header\"><div class=\"pod-header__image\"><div class=\"pod-header__image-wrapper\"><img decoding=\"async\" class=\"podcast-cover-image\" src=\"https:\/\/images.podigee-cdn.net\/0x,sqvWI5fZv_m3DhwUGGW8fZRSSgFarfP0F8a2nNIFtktA=\/https:\/\/main.podigee-cdn.net\/uploads\/u17081\/b9425c6a-8ecc-48cf-888c-a2351bacd246.jpg\" srcset=\"\" sizes=\"(max-width: 640px) 100vw, 25vw\" alt=\"\"><\/div><span class=\"pod-header__image-style\" style=\"display: block; width: 100%; padding-top: 100%\"><\/div><\/div><\/div><div class=\"pp-podcast__content pod-content\"><div class=\"pp-podcast__single\"><div class=\"pp-podcast__player\"><div class=\"pp-player-episode\"><audio id=\"pp-podcast-977-player\" preload=\"none\" class=\"pp-podcast-episode\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/audio.podigee-cdn.net\/640033-m-29f3f04ce3c2cadca0df1433a5175c00.mp3?source=feed\" \/><\/audio><\/div><\/div><div class=\"pod-content__episode episode-single\"><button class=\"episode-single__close\" aria-expanded=\"false\" aria-label=\"Close Single Episode\"><span class=\"btn-icon-wrap\"><svg class=\"icon icon-pp-x\" aria-hidden=\"true\" role=\"img\" focusable=\"false\"><use href=\"#icon-pp-x\" xlink:href=\"#icon-pp-x\"><\/use><\/svg><\/span><\/button><div class=\"episode-single__wrapper\"><div class=\"episode-single__header\"><div class=\"episode-single__title\">2022-01: Telematik-Infrastruktur &#8211; raus aus der Zeitschleife?<\/div><div class=\"episode-single__author\"><span class=\"byname\">by<\/span><span class=\"single-author\">Nick Seidel, Prof. Dr. Christian Johner<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pod-content__launcher pod-launch\"><button class=\"pod-launch__button pod-launch__info pod-button\" aria-expanded=\"false\"><span class=\"ppjs__offscreen\">Show Podcast Information<\/span><span class=\"btn-icon-wrap\"><svg class=\"icon icon-pp-podcast\" aria-hidden=\"true\" role=\"img\" focusable=\"false\"><use href=\"#icon-pp-podcast\" xlink:href=\"#icon-pp-podcast\"><\/use><\/svg><svg class=\"icon icon-pp-x\" aria-hidden=\"true\" role=\"img\" focusable=\"false\"><use href=\"#icon-pp-x\" xlink:href=\"#icon-pp-x\"><\/use><\/svg><\/span><\/button><\/div><\/div>\n\n\n<h2 aria-label=\"3. Begriffe (ePA, KIM, MIO, \u2026)\" id=\"3-begrifflichkeiten-im-kontext-der-telematikinfrastruktur\">3. Begrifflichkeiten im Kontext der Telematikinfrastruktur<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-dienste-und-anwendungen\">a) Dienste und Anwendungen<\/h3>\n\n\n\n<p>Eine Infrastruktur hat nur dann einen Wert, wenn sie die relevanten \u201eUse Cases\u201c unterst\u00fctzt. F\u00fcr die Telematik sind unter anderem die folgenden (Mehrwert-)Dienste vorgesehen, die die KBV als \u201eAnwendungen\u201c bezeichnet:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>eRezept<\/strong>: Damit sollen verschreibungspflichte Medikamente verordnet und von den Apotheken abgegeben werden k\u00f6nnen.<\/li>\n\n\n\n<li><strong>Elektronische Patientenakte (ePA)<\/strong>: Dieses zentrale Element soll Daten aller Gesundheitsdienstleister (Krankenh\u00e4user, niedergelassene \u00c4rztinnen und \u00c4rzte, Therapeuten) umfassen, um so den (intersektoralen) Datenaustausch zu f\u00f6rdern.<\/li>\n\n\n\n<li><strong>Elektronische Arbeitsunf\u00e4higkeitsbescheinigung (eAU)<\/strong>: Damit sollen die gelben Zettel der Vergangenheit angeh\u00f6ren. \u00c4rztinnen und \u00c4rzte k\u00f6nnen diese Bescheinigungen direkt digital an Krankenkassen und Arbeitgeber \u00fcbermitteln.<\/li>\n\n\n\n<li><strong>Notfalldatenmanagement (NFDM)<\/strong>: Auf der elektronischen Gesundheitskarte (eGK) sollen die Daten gespeichert werden, die \u00c4rztinnen und \u00c4rzte in einem Notfall ben\u00f6tigen. Beispiele sind Diagnosen und Medikamente.<\/li>\n\n\n\n<li><strong>Elektronischer Medikationsplan<\/strong>: Ebenfalls auf der eGK sollen alle Medikationsdaten gespeichert werden, damit alle Beteiligten den \u00dcberblick bewahren und z. B. Medikamentenwechselwirkungen und Doppelmedikationen erkennen k\u00f6nnen.<\/li>\n<\/ul>\n\n\n\n<p>Eine vollst\u00e4ndige \u00dcbersicht der \u201eAnwendungen\u201c finden Sie auf den <a href=\"https:\/\/www.kbv.de\/html\/it-anwendungen.php\">Seiten der KBV<\/a> und der <a href=\"https:\/\/www.gematik.de\/anwendungen\">gematik<\/a>.<\/p>\n\n\n\n<p>Dass diese Dienste verf\u00fcgbar gehalten werden, ist nicht Aufgabe der gematik, sondern die ihrer Betreiber. Das sind kommerzielle Firmen wie ITSG, IBM und RISE. \u00dcber diese Verf\u00fcgbarkeit gab es Klagen; auch die gematik berichtete \u00fcber St\u00f6rungen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"kim\">KIM<\/h4>\n\n\n\n<p>Die gematik z\u00e4hlt auch die Kommunikationsdienste KIM und TIM zu den Anwendungen.<\/p>\n\n\n\n<p>Das Akronym KIM steht f\u00fcr <strong>Kommunikation im Medizinwesen<\/strong>. Es soll dem Austausch strukturierter und unstrukturierter medizinischer Informationen wie Labordaten, Arztbriefen (eArztbrief) und eAUs dienen. <\/p>\n\n\n\n<p>KIM ist ein sicherer E-Mail-Dienst \u00fcber die Telematikinfrastruktur. Dazu nutzt es bew\u00e4hrte Protokolle wie http, SMTP und POP. Die Telematikinfrastruktur stellt einen Verzeichnisdienst bereit, quasi ein Adressbuch m\u00f6glicher Empf\u00e4nger.<\/p>\n\n\n\n<p>Von \u201enormaler\u201c E-Mail unterscheidet sich KIM in einigen Punkten:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Alle E-Mails sind durch die TI verschl\u00fcsselt und signiert.<\/li>\n\n\n\n<li>Der Dienst unterst\u00fctzt derzeit nicht das Protokoll IMAP. Damit ist die Synchronisation von E-Mails auf mehreren Endger\u00e4ten nicht m\u00f6glich.<\/li>\n\n\n\n<li>Nur an die TI angeschlossene Clients k\u00f6nnen KIM-Nachrichten senden und empfangen. Das schlie\u00dft Mobiltelefone derzeit aus.<\/li>\n\n\n\n<li>Die Vergabe von E-Mail-Adressen erfolgt zentral durch den jeweiligen Anbieter und ist an die Institution gebunden.<\/li>\n\n\n\n<li>Die E-Mails sollen auch dem automatisierten Austausch zwischen Systemen dienen. Beispielsweise kann ein Praxisverwaltungssystem ohne den \u00fcblichen E-Mail-Client eine KIM-Nachricht mit einer elektronischen Arbeitsunf\u00e4higkeitsbescheinigungen verschicken.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"tim\">TIM<\/h4>\n\n\n\n<p>TIM steht f\u00fcr <strong>Telematikinfrastruktur-Messenger<\/strong>. Er soll eine sichere und legale Alternative zu WhatsApp &amp; Co. bieten. Die gematik hat daf\u00fcr die Schnittstellen spezifiziert.<\/p>\n\n\n\n<p>TIM eignet sich f\u00fcr den kurzen und schnellen Informationsaustausch: die R\u00fcckfrage zu einem Rezept, den Hinweis f\u00fcr einen Patienten, eine Nachricht an mehrere Kollegen (\u201eBroadcast\u201c).<\/p>\n\n\n\n<p>Der Messenger erlaubt derzeit nur den Versand von unstrukturierten Informationen, konkret Textnachrichten sowie Bild- und Ton\u00fcbertragung. Er setzt auf das <a href=\"https:\/\/de.wikipedia.org\/wiki\/Representational_State_Transfer\" target=\"_blank\" rel=\"noreferrer noopener\">REST<\/a>-basierte <a href=\"https:\/\/de.wikipedia.org\/wiki\/Matrix_(Kommunikationsprotokoll)\">Matrix-Protokoll<\/a>, das neben dem Instant-Messaging auch Bildgespr\u00e4che von zwei oder mehr Nutzern erlauben w\u00fcrde. Das soll in einer <a href=\"https:\/\/fachportal.gematik.de\/anwendungen\/ti-messenger\">weiteren Ausbaustufe<\/a> f\u00fcr Videochats zwischen \u00c4rzt:innen und Patient:innen genutzt werden.<\/p>\n\n\n\n<p>Im Gegensatz zu KIM kann der Messenger auf Smartphones betrieben werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"b-mio\">b) MIO<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"ubersicht\">\u00dcbersicht<\/h4>\n\n\n\n<p>Die <strong>medizinischen Informationsobjekte<\/strong> (MIO) gleichen Legosteinen, aus denen sich komplexere Informationsgebilde wie die elektronische Patientenakte aufbauen lassen. Derzeit sind oder werden die folgenden MIOs spezifiziert:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Impfpass<\/li>\n\n\n\n<li>Krankenhaus-Entlassbrief<\/li>\n\n\n\n<li>Mutterpass<\/li>\n\n\n\n<li>Patientenkurzakte<\/li>\n\n\n\n<li>Untersuchungsheft (f\u00fcr Kinder)<\/li>\n\n\n\n<li>Zahn\u00e4rztliches Bonusheft<\/li>\n\n\n\n<li>Telemedizinisches Monitoring<\/li>\n<\/ul>\n\n\n\n<p>Die KBV hat eine <a href=\"https:\/\/mio.kbv.de\/site\/mio\">\u00dcbersichtsseite zu den MIOs<\/a> erstellt. Von der gematik stammen die Spezifikation sowie die <a href=\"https:\/\/fachportal.gematik.de\/fileadmin\/Fachportal\/Anwendungen\/MIO\/gemInfo_MIO-Baukasten_V1.0.0.pdf\">Anleitung zur Umsetzung von MIOs in der ePA<\/a>.<\/p>\n\n\n\n<div class=\"jig_defbox\"><div class=\"jig_defbox-definition\"><div class=\"jig_defbox-icon-wrapper\" style=\"fill:#919191\"><svg viewBox=\"0 0 48 48\" width=\"24\" height=\"24\" class=\"dashicons\" aria-hidden=\"true\"><g><path d=\"M20,19.5h16v-3H20V19.5z M20,25.5h16v-3H20V25.5z M20,31.5h10v-3H20V31.5z M14.1,20c0.6,0,1-0.2,1.4-0.6 c0.4-0.4,0.6-0.9,0.6-1.4s-0.2-1-0.6-1.4c-0.4-0.4-0.9-0.6-1.4-0.6c-0.6,0-1,0.2-1.4,0.6c-0.4,0.4-0.6,0.9-0.6,1.4 c0,0.6,0.2,1,0.6,1.4C13,19.9,13.5,20,14.1,20z M14.1,26c0.6,0,1-0.2,1.4-0.6c0.4-0.4,0.6-0.9,0.6-1.4c0-0.6-0.2-1-0.6-1.4 S14.6,22,14.1,22c-0.6,0-1,0.2-1.4,0.6s-0.6,0.9-0.6,1.4c0,0.6,0.2,1,0.6,1.4S13.5,26,14.1,26z M14.1,32c0.6,0,1-0.2,1.4-0.6 c0.4-0.4,0.6-0.9,0.6-1.4c0-0.6-0.2-1-0.6-1.4c-0.4-0.4-0.9-0.6-1.4-0.6c-0.6,0-1,0.2-1.4,0.6s-0.6,0.9-0.6,1.4 c0,0.6,0.2,1,0.6,1.4S13.5,32,14.1,32z M7,40c-1.7,0-3-1.4-3-3V11c0-0.8,0.3-1.5,0.9-2.1C5.5,8.3,6.2,8,7,8h34 c0.8,0,1.5,0.3,2.1,0.9C43.7,9.5,44,10.2,44,11v26c0,0.8-0.3,1.5-0.9,2.1C42.5,39.7,41.8,40,41,40L7,40z M7,37h34V11H7V37z M7,11\"><\/path><\/g><\/svg><\/div><span class=\"jig_defbox-header\" style=\"color:#919191\">Weiterf\u00fchrende Informationen<\/span><\/div>\n<p>Sie erfahren auf <a href=\"https:\/\/simplifier.net\/im1x0\/\">https:\/\/simplifier.net\/im1x0\/<\/a> mehr zur Spezifikation.<\/p>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"beispiel-impfpass\">Beispiel: Impfpass<\/h4>\n\n\n\n<p>M\u00f6chte ein Hersteller in der ePA die Impfinformationen abspeichern, muss er das <a href=\"https:\/\/mio.kbv.de\/pages\/viewpage.action?pageId=74556694&amp;preview=\/74556694\/76513878\/MIO-Festlegung-Impfpass%20v%201.1.0.pdf\">MIO Impfpass gem\u00e4\u00df der Spezifikation der KBV<\/a> nutzen. Diese <a href=\"https:\/\/simplifier.net\/im1x0\/~resources?fhirVersion=R4&amp;sortBy=RankScore_desc\">Spezifikation setzt auf FHIR<\/a>.<\/p>\n\n\n\n<p>Sie beschreibt die zu verwendenden FHIR-Ressourcen, z. B. <a href=\"https:\/\/simplifier.net\/im1x0\/kbvprmiovaccinationrecordprime\">KBV_PR_MIO_Vaccination_Bundle_Entry<\/a>. Sie legt die Attribute mit Kardinalit\u00e4ten und Datentypen fest.<\/p>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-fhir.png\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"196\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-fhir-300x196.png\" alt=\"Abbildung der FHIR Ressource \u201eKBV_PR_MIO_Vaccination_Bundle_Entry\u201d\" class=\"wp-image-4583519\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-fhir-300x196.png 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-fhir-768x502.png 768w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-fhir-200x131.png 200w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-fhir-400x262.png 400w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-fhir-600x392.png 600w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-fhir-800x523.png 800w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-fhir.png 945w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption class=\"wp-element-caption\">Abb. 2: FHIR Ressource \u201eKBV_PR_MIO_Vaccination_Bundle_Entry\u201d (zum Vergr\u00f6\u00dfern klicken)<\/figcaption><\/figure>\n\n\n\n<p>Beispielsweise muss die Impfung (\u201eImmunization\u201c) genau einen Patienten referenzieren und sowohl die Charge (\u201elotNumber\u201c) als auch den Impfstatus (z. B. \u201ecompleted\u201c) angeben.<\/p>\n\n\n\n<p>Die Charge und das Impfdatum sind&nbsp;<strong>MIO-Elemente<\/strong>&nbsp;des&nbsp;<strong>MIO-Modells<\/strong>&nbsp;\u201eelektronische Impfdokumentation\u201c (\u201eImmunization\u201c).&nbsp;<\/p>\n\n\n\n<p>Eine konkrete Impfdokumentation f\u00fcr einen spezifischen Patienten bildet ein&nbsp;<strong>MIO-Dokument<\/strong>&nbsp;(XML-Format). Im Gegensatz zum elektronischen Kinderuntersuchungsheft enth\u00e4lt das MIO-Dokument f\u00fcr die Impfdokumentation keine&nbsp;<strong>MIO-Teildokumente<\/strong>. Der Satz der konkreten Werte f\u00fcr ein (Teil-)Dokument bildet einen&nbsp;<strong>MIO-Eintrag<\/strong>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-mio.png\" data-rel=\"lightbox-image-2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"164\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-mio-300x164.png\" alt=\"Grafik, die das MIO-Modell der KBV darstellt.\" class=\"wp-image-4583528\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-mio-300x164.png 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-mio-768x419.png 768w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-mio-200x109.png 200w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-mio-400x218.png 400w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-mio-600x328.png 600w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-mio-800x437.png 800w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/telematik-mio.png 945w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption class=\"wp-element-caption\">Abb. 3: Das MIO-Modell der KBV (<a href=\"file:\/\/\/Users\/christianjohner\/Nextcloud\/01_Knowledgebase\/Healthcare-IT%20(original)\/gemInfo_MIO-Baukasten_V1.0.1.pdf\">Quelle<\/a>) (zum Vergr\u00f6\u00dfern klicken)<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"c-isik\">c) ISiK<\/h3>\n\n\n\n<p>F\u00fcr die <strong>Informationstechnischen Systeme in Krankenh\u00e4usern<\/strong> (ISiK) Stufe 1 legt die gematik ebenfalls eine Schnittstellenspezifikation vor. Diese <a href=\"https:\/\/simplifier.net\/isik-basis-v4\" target=\"_blank\" rel=\"noreferrer noopener\">ISiK-Spezifikation<\/a> definiert auf Basis von FHIR-Profilen Datenobjekte wie <a href=\"https:\/\/simplifier.net\/medizininformatikinitiative-modulperson\" target=\"_blank\" rel=\"noreferrer noopener\">Patient<\/a> und <a href=\"https:\/\/simplifier.net\/medizininformatikinitiative-moduldiagnosen\" target=\"_blank\" rel=\"noreferrer noopener\">Diagnose<\/a>.<\/p>\n\n\n\n<p>Damit m\u00fcssen konforme Systeme \u00fcbliche Funktionalit\u00e4ten anbieten wie:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Patienten suchen, z. B. anhand von Attributen wie Name, Adresse, Geburtsdatum<\/li>\n\n\n\n<li>Die Diagnosen eines Patienten abfragen (mit Code, Datum usw.) <\/li>\n\n\n\n<li>Den aktuellen Fall anhand einer Fallnummer finden (weiter unten mehr)<\/li>\n<\/ul>\n\n\n\n<p>Das wiederum dient<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>dem Austausch von Daten zwischen den Systemen innerhalb eines Krankenhauses (zwischen Prim\u00e4rsystemen, zwischen Prim\u00e4r- und Subsystemen und ab Stufe 2 \u201esogar\u201c mit Apps),<\/li>\n\n\n\n<li>der Integration von Anwendungen au\u00dferhalb des Krankenhauses in die Krankenhaussysteme und<\/li>\n\n\n\n<li>der Anbindung von Medizin-\/Messger\u00e4ten.<\/li>\n<\/ul>\n\n\n\n<p>Die gematik nutzt eigene Profile und nicht die der KBV bzw. <a href=\"https:\/\/www.medizininformatik-initiative.de\/\">Medizininformatik-Initiative<\/a>. Die Begr\u00fcndung finden Sie auf <a href=\"https:\/\/simplifier.net\/guide\/isik-basis-v4\/ImplementationGuide-markdown-Motivation?version=current\" target=\"_blank\" rel=\"noreferrer noopener\">dieser Seite<\/a> ganz unten.<\/p>\n\n\n\n<div class=\"jig_defbox\"><div class=\"jig_defbox-definition\"><div class=\"jig_defbox-icon-wrapper\" style=\"fill:#919191\"><svg viewBox=\"0 0 576 512\" width=\"24\" height=\"24\" class=\"dashicons\" aria-hidden=\"true\"><path d=\"M569.5,440c18.5,32-4.7,72-41.6,72H48.1c-36.9,0-60-40.1-41.6-72L246.4,24c18.5-32,64.7-32,83.2,0L569.5,440 L569.5,440z M288,354c-25.4,0-46,20.6-46,46s20.6,46,46,46s46-20.6,46-46S313.4,354,288,354z M244.3,188.7l7.4,136 c0.3,6.4,5.6,11.3,12,11.3h48.5c6.4,0,11.6-5,12-11.3l7.4-136c0.4-6.9-5.1-12.7-12-12.7h-63.4C249.4,176,244,181.8,244.3,188.7 L244.3,188.7z\"><\/path><\/svg><\/div><span class=\"jig_defbox-header\" style=\"color:#919191\">Achtung<\/span><\/div>\n<p>Welche Systeme als \u201ebest\u00e4tigungsrelevant\u201c z\u00e4hlen und welchen Pflichten diese unterliegen, h\u00e4ngt vom Zeitpunkt und damit der Stufe sowie von den Daten ab:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/simplifier.net\/ISIP\/I-markdown-UebergreifendeFestlegungen-BestaetigungsrelevanteSysteme\">Stufe 1<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/simplifier.net\/isik-dokumentenaustausch-v3\">Stufe2 Dokumentenaustausch<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/simplifier.net\/ISIP\/I-markdown-UebergreifendeFestlegungen-BestaetigungsrelevanteSysteme\">Stufe 2 Vitalparameter<\/a><\/li>\n<\/ul>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">d) ISiP<\/h3>\n\n\n\n<p>Neben dem ISiK befasst sich die gematik auch mit dem ISiP (Informationssystem f\u00fcr Pflegeleistungserbringer). Das ISiP soll Arbeitsabl\u00e4ufe in Pflegeeinrichtungen sowie die Archivierung und \u00dcbertragung der Stamm- und Pflegedaten digital unterst\u00fctzen. Die gematik entwickelt hierf\u00fcr standardisierte Schnittstellen zur Anbindung von ambulanten und klinischen Anwendungen und Datenbanksysteme.<\/p>\n\n\n\n<p>Diese Informationssysteme werden von den Profilen des ISiK abgeleitet. Daher gelten Kompatibilit\u00e4tsbetrachtungen des ISiK ebenfalls f\u00fcr das ISiP. Auch Hersteller von ISiP-Systemen kommen daher nicht mehr um eine FHIR Schnittstelle herum.<\/p>\n\n\n\n<div class=\"jig_defbox\"><div class=\"jig_defbox-definition\"><div class=\"jig_defbox-icon-wrapper\" style=\"fill:#919191\"><svg viewBox=\"0 0 48 48\" width=\"24\" height=\"24\" class=\"dashicons\" aria-hidden=\"true\"><g><path d=\"M20,19.5h16v-3H20V19.5z M20,25.5h16v-3H20V25.5z M20,31.5h10v-3H20V31.5z M14.1,20c0.6,0,1-0.2,1.4-0.6 c0.4-0.4,0.6-0.9,0.6-1.4s-0.2-1-0.6-1.4c-0.4-0.4-0.9-0.6-1.4-0.6c-0.6,0-1,0.2-1.4,0.6c-0.4,0.4-0.6,0.9-0.6,1.4 c0,0.6,0.2,1,0.6,1.4C13,19.9,13.5,20,14.1,20z M14.1,26c0.6,0,1-0.2,1.4-0.6c0.4-0.4,0.6-0.9,0.6-1.4c0-0.6-0.2-1-0.6-1.4 S14.6,22,14.1,22c-0.6,0-1,0.2-1.4,0.6s-0.6,0.9-0.6,1.4c0,0.6,0.2,1,0.6,1.4S13.5,26,14.1,26z M14.1,32c0.6,0,1-0.2,1.4-0.6 c0.4-0.4,0.6-0.9,0.6-1.4c0-0.6-0.2-1-0.6-1.4c-0.4-0.4-0.9-0.6-1.4-0.6c-0.6,0-1,0.2-1.4,0.6s-0.6,0.9-0.6,1.4 c0,0.6,0.2,1,0.6,1.4S13.5,32,14.1,32z M7,40c-1.7,0-3-1.4-3-3V11c0-0.8,0.3-1.5,0.9-2.1C5.5,8.3,6.2,8,7,8h34 c0.8,0,1.5,0.3,2.1,0.9C43.7,9.5,44,10.2,44,11v26c0,0.8-0.3,1.5-0.9,2.1C42.5,39.7,41.8,40,41,40L7,40z M7,37h34V11H7V37z M7,11\"><\/path><\/g><\/svg><\/div><span class=\"jig_defbox-header\" style=\"color:#919191\">Weiterf\u00fchrende Informationen<\/span><\/div>\n<p><a href=\"https:\/\/github.com\/gematik\/ISiP\/blob\/972f116113d6a4e1137f698bcad04ca288181bdb\/ImplementationGuide\/markdown\/UebergreifendeFestlegungen\/BestaetigungsrelevanteSysteme.md\">Best\u00e4tigungsrelevante Systeme ISiP<\/a><br><a href=\"https:\/\/github.com\/gematik\/ISiP\" target=\"_blank\" rel=\"noreferrer noopener\">Implementierungsleitfaden ISiP<\/a><\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"4-gesetzliche-anforderungen\">4. Gesetzliche Anforderungen<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-355-sgb-v-anforderungen-u-a-an-die-epa-und-damit-an-die-mios\">a) \u00a7 355 SGB V: Anforderungen u. a. an die ePA und damit an die MIOs<\/h3>\n\n\n\n<p>Der erste Absatz des&nbsp;<a href=\"http:\/\/www.gesetze-im-internet.de\/sgb_5\/__355.html\">\u00a7 355 SGB V<\/a>&nbsp;erm\u00e4chtigt die KBV, die Schnittstellen f\u00fcr die ePA (und damit f\u00fcr die MIOs), f\u00fcr den elektronischen Medikationsplan und die elektronischen Notfalldaten festzulegen.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"b-371-sgv-v-anforderungen-an-systeme-zur-verarbeitung-personenbezogener-daten\">b) \u00a7 371 SGV V: Anforderungen an Systeme zur Verarbeitung personenbezogener Daten<\/h3>\n\n\n\n<p>\u00a7&nbsp;<a href=\"http:\/\/www.gesetze-im-internet.de\/sgb_5\/__371.html\">371 SGB V<\/a>&nbsp;er\u00f6ffnet den Reigen an Gesetzen mit&nbsp;<em>\u201eAnforderungen an Schnittstellen in informationstechnischen Systemen\u201c<\/em>. Er beschr\u00e4nkt sich nicht auf klinische Systeme. Vielmehr ist er f\u00fcr alle Systeme relevant, die personenbezogene Daten in der vertrags\u00e4rztlichen Versorgung (bei Niedergelassenen), in Krankenh\u00e4usern sowie bei der pflegerischen Versorgung verarbeiten.<\/p>\n\n\n\n<p><a href=\"http:\/\/www.gesetze-im-internet.de\/sgb_5\/__371.html\">\u00a7 371 SGB V<\/a> fordert standardisierte Schnittstellen, um auf die Systeme zugreifen k\u00f6nnen, f\u00fcr die Medikationsverordnung sowie f\u00fcr ambulante und klinische \u201eAnwendungs- und Datenbanksysteme\u201c (sprich: Arztpraxisverwaltungs- und Krankenhaus-Informationssysteme).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"c-372-sgb-v-anforderungen-an-die-praxisverwaltungssysteme\">c) \u00a7 372 SGB V: Anforderungen an die Praxisverwaltungssysteme<\/h3>\n\n\n\n<p>Vergleichbar mit dem folgenden \u00a7 373 SGB V f\u00fcr Krankenh\u00e4user trifft der&nbsp;<a href=\"http:\/\/www.gesetze-im-internet.de\/sgb_5\/__372.html\">\u00a7 372 SGB V<\/a>&nbsp;<em>\u201eFestlegungen zu den offenen und standardisierten Schnittstellen f\u00fcr informationstechnische Systeme in der vertrags\u00e4rztlichen und vertragszahn\u00e4rztlichen Versorgung\u201c<\/em>.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"d-373-sgb-v-anforderungen-an-die-isik\">d) \u00a7 373 SGB V: Anforderungen an die ISiK<\/h3>\n\n\n\n<p><a href=\"http:\/\/www.gesetze-im-internet.de\/sgb_5\/__373.html\">\u00a7 373 SGB V<\/a>&nbsp;bildet die gesetzliche Grundlage f\u00fcr die ISiK. Er ist \u00fcberschrieben mit&nbsp;<em>\u201eFestlegungen zu den offenen und standardisierten Schnittstellen f\u00fcr informationstechnische Systeme in Krankenh\u00e4usern und in der pflegerischen Versorgung\u201c<\/em>.<\/p>\n\n\n\n<p>Die \u201ebest\u00e4tigungsrelevanten Systeme\u201c sind momentan die Prim\u00e4rsysteme in den Krankenh\u00e4usern. Die Deutsche Krankenhausgesellschaft kann weitere Subsysteme bestimmen.&nbsp;<\/p>\n\n\n\n<p>Weitere Hinweise zu den best\u00e4tigungsrelevanten Systemen, z. B. zu Kommunikationsservern, finden sich im&nbsp;<a href=\"https:\/\/simplifier.net\/guide\/isik-basis-v4\/ImplementationGuide-markdown-Einfuehrung?version=current\" target=\"_blank\" rel=\"noreferrer noopener\">Implementierungsleitfaden des ISiK-Basismoduls<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"e-374-a-sgb-v-anforderungen-an-einige-hilfsmittel-und-implantate\">e) \u00a7 374 a SGB V: Anforderungen an einige Hilfsmittel und Implantate<\/h3>\n\n\n\n<p><a href=\"http:\/\/www.gesetze-im-internet.de\/sgb_5\/__374a.html\">\u00a7374 a SGB V<\/a>&nbsp;tr\u00e4gt den Titel&nbsp;<em>\u201eIntegration offener und standardisierter Schnittstellen in Hilfsmitteln und Implantaten\u201c<\/em>. Er fordert, f\u00fcr bestimmte Produkte Datenschnittstellen auch f\u00fcr Drittanbieter (Anbieter von DIGAs) zu \u00f6ffnen.<\/p>\n\n\n\n<p>Dieser Artikel ist nicht unumstritten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"f-gigv\">f) GIGV<\/h3>\n\n\n\n<p>Die IOP-Governance-Verordnung erm\u00e4chtigt die gematik, die Interoperabilit\u00e4tsstandards zu vereinheitlichen. Denn die einzelnen Interoperabilit\u00e4tsstandards erlauben viele Freiheiten. Um die Programmierung zu erleichtern, kann die gematik die Standards also \u201estandardisieren\u201c. Die von ihrem Expertengremium publizierten Standards werden f\u00fcr die Hersteller verpflichtend.&nbsp;<\/p>\n\n\n\n<p>F\u00fcr die o. g. Anwendungsf\u00e4lle sind diese Standards bereits bestimmt.<\/p>\n\n\n\n<div class=\"jig_defbox\"><div class=\"jig_defbox-definition\"><div class=\"jig_defbox-icon-wrapper\" style=\"fill:#919191\"><svg viewBox=\"0 0 48 48\" width=\"24\" height=\"24\" class=\"dashicons\" aria-hidden=\"true\"><g><path d=\"M20,19.5h16v-3H20V19.5z M20,25.5h16v-3H20V25.5z M20,31.5h10v-3H20V31.5z M14.1,20c0.6,0,1-0.2,1.4-0.6 c0.4-0.4,0.6-0.9,0.6-1.4s-0.2-1-0.6-1.4c-0.4-0.4-0.9-0.6-1.4-0.6c-0.6,0-1,0.2-1.4,0.6c-0.4,0.4-0.6,0.9-0.6,1.4 c0,0.6,0.2,1,0.6,1.4C13,19.9,13.5,20,14.1,20z M14.1,26c0.6,0,1-0.2,1.4-0.6c0.4-0.4,0.6-0.9,0.6-1.4c0-0.6-0.2-1-0.6-1.4 S14.6,22,14.1,22c-0.6,0-1,0.2-1.4,0.6s-0.6,0.9-0.6,1.4c0,0.6,0.2,1,0.6,1.4S13.5,26,14.1,26z M14.1,32c0.6,0,1-0.2,1.4-0.6 c0.4-0.4,0.6-0.9,0.6-1.4c0-0.6-0.2-1-0.6-1.4c-0.4-0.4-0.9-0.6-1.4-0.6c-0.6,0-1,0.2-1.4,0.6s-0.6,0.9-0.6,1.4 c0,0.6,0.2,1,0.6,1.4S13.5,32,14.1,32z M7,40c-1.7,0-3-1.4-3-3V11c0-0.8,0.3-1.5,0.9-2.1C5.5,8.3,6.2,8,7,8h34 c0.8,0,1.5,0.3,2.1,0.9C43.7,9.5,44,10.2,44,11v26c0,0.8-0.3,1.5-0.9,2.1C42.5,39.7,41.8,40,41,40L7,40z M7,37h34V11H7V37z M7,11\"><\/path><\/g><\/svg><\/div><span class=\"jig_defbox-header\" style=\"color:#919191\">Weiterf\u00fchrende Informationen<\/span><\/div>\n<p>Lesen Sie&nbsp;<a href=\"https:\/\/www.johner-institut.de\/blog\/gesundheitswesen\/iop-governance-verordnung-gigv\/\">hier mehr zur IOP-Governance-Verordnung<\/a>, um \u00fcber deren Gremien zu erfahren.<\/p>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"g-khzg\">g) KHZG<\/h3>\n\n\n\n<p>Das&nbsp;<a href=\"https:\/\/www.buzer.de\/Krankenhauszukunftsgesetz.htm\">Krankenhauszukunftsgesetz KHZG<\/a>&nbsp;ist in dieser Liste in doppelter Hinsicht eine Besonderheit.&nbsp;<\/p>\n\n\n\n<p>Zum einen ist es ein Gesetz, das viele Gesetze \u00e4ndert, insbesondere das Krankenhausfinanzierungsgesetz und mehrere Sozialgesetzb\u00fccher.<\/p>\n\n\n\n<p>Zum anderen ist es ein Gesetz, das die Hersteller nur indirekt betrifft. Denn das Gesetz legt F\u00f6rdertatbest\u00e4nde fest. Das sind Projekte, f\u00fcr die die Krankenh\u00e4user F\u00f6rdergelder enthalten. Viele dieser F\u00f6rdertatbest\u00e4nde dienen der besseren Digitalisierung der Krankenh\u00e4user:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Anpassung der technischen bzw. informationstechnischen Ausstattung der Notaufnahme eines Krankenhauses an den jeweils aktuellen Stand der Technik<\/li>\n\n\n\n<li>Patientenportale wie das digitale Aufnahmemanagement, Behandlungsmanagement, Entlass- und \u00dcberleitungsmanagement<\/li>\n\n\n\n<li>Digitale Pflege- und Behandlungsdokumentation<\/li>\n\n\n\n<li>Einrichtung von teil- oder vollautomatisierten klinischen Entscheidungsunterst\u00fctzungssystemen<\/li>\n\n\n\n<li>Digitales Medikationsmanagement<\/li>\n\n\n\n<li>Digitale Leistungsanforderung<\/li>\n\n\n\n<li>Informationstechnische, kommunikationstechnische und robotikbasierte Anlagen, Systeme oder Verfahren und telemedizinische Netzwerke<\/li>\n<\/ul>\n\n\n\n<p>Um diese F\u00f6rdergelder zu erlangen, haben die meisten Krankenh\u00e4user ein oder mehrere Projekte beantragt bzw. initiiert. Sie kommen aber nur in den Genuss der F\u00f6rdergelder, wenn die Systeme die o. g. gesetzlichen Voraussetzungen erf\u00fcllen.<\/p>\n\n\n\n<p>Damit profitieren Hersteller medizinischer Software nur von dem Nachfrageboom, wenn ihre Systeme zu den f\u00f6rderw\u00fcrdigen Tatbest\u00e4nden z\u00e4hlen und die gesetzlichen Anforderungen erf\u00fcllen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"5-offene-wunsche\">5. Offene W\u00fcnsche<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-wirkliche-interoperabilitat\">a) Wirkliche Interoperabilit\u00e4t<\/h3>\n\n\n\n<p>Die gematik hat mit der TI Interoperabilit\u00e4t versprochen. Doch es gibt noch Bedarf zur Nachbesserung:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die TI funktioniert nur mit einem veralteten und beschr\u00e4nkten Konnektor. Das Problem ist bekannt und wird angegangen.<\/li>\n\n\n\n<li>Es gibt L\u00fccken auf der semantischen Ebene, die noch geschlossen werden.<\/li>\n\n\n\n<li>Die organisatorische Ebene ist unvollst\u00e4ndig. \u00dcbergreifende Workflows und Berechtigungskonzepte fehlen zumindest teilweise. Die Umsetzung von IHE XDS ist unvollst\u00e4ndig.<\/li>\n\n\n\n<li>Der eindeutige Patienten-Identifikator wurde durch die KVNR ersetzt, \u00fcber die nicht alle B\u00fcrger verf\u00fcgen und die auch nicht eineindeutig ist.<\/li>\n\n\n\n<li>Der (derzeitige) Fokus auf Arztpraxisverwaltungs- bzw. Krankenhausinformationssysteme, die \u00fcber einen Konnektor angeschlossen sind, ist per se eine Einschr\u00e4nkung der Interoperabilit\u00e4t. Diese Beschr\u00e4nkung ist bekannt und wird angegangen.<\/li>\n\n\n\n<li>Trotz aller Bem\u00fchungen um Interoperabilit\u00e4t auch \u00fcber Landesgrenzen hinweg bleibt die TI ein deutsches Gew\u00e4chs, das keine durchg\u00e4ngige europaweite Interoperabilit\u00e4t schafft.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"b-usability\">b) Usability<\/h3>\n\n\n\n<p>Um von den Vorteilen einer TI profitieren zu k\u00f6nnen, sind die H\u00fcrden teilweise hoch. Das betrifft sowohl die implementierenden Hersteller als auch die Anwender.<\/p>\n\n\n\n<p>Selbst das viel gepriesene KIM muss ohne IMAP auskommen. Wie will man Anwendern erkl\u00e4ren, dass sie gef\u00fchlt wieder in den 1990er-Jahren angekommen sind, wo man E-Mails nur auf einem Client speichern kann? Hier ist keine L\u00f6sung in Sicht, auch weil der Datenschutz im Weg steht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"c-it-sicherheit\">c) IT-Sicherheit<\/h3>\n\n\n\n<p>Die IT-Sicherheit der Systeme wurde genauso oft versprochen wie widerlegt. Es muss klar sein, dass jedes IT-System gehackt werden kann. Aber angesichts der Bem\u00fchungen um den Datenschutz und der Einschr\u00e4nkungen, die man diesbez\u00fcglich akzeptieren muss, verwundert es, wenn oft peinlich gro\u00dfe L\u00fccken klaffen, wie <a href=\"https:\/\/www.heise.de\/news\/c-t-deckt-auf-Sicherheitsluecke-in-elektronischer-Patientenakte-6304671.html\" target=\"_blank\" rel=\"noreferrer noopener\">von c\u2019t berichtet<\/a> oder dem CCC aufgedeckt.<\/p>\n\n\n\n<p>Auch die H\u00e4ufigkeit, mit der Systeme wie Konnektoren und Backendsysteme nicht verf\u00fcgbar sind, schadet der Initiative.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Gematik-Meldung-ePA-Telematikinfrastruktur.png\" data-rel=\"lightbox-image-3\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"187\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Gematik-Meldung-ePA-Telematikinfrastruktur-1024x187.png\" alt=\"Meldung der gematik \u00fcber eine St\u00f6rung an der (nicht von ihr betriebenen) Telematikinfrastruktur\" class=\"wp-image-4599254\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Gematik-Meldung-ePA-Telematikinfrastruktur-1024x187.png 1024w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Gematik-Meldung-ePA-Telematikinfrastruktur-300x55.png 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Gematik-Meldung-ePA-Telematikinfrastruktur-768x140.png 768w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Gematik-Meldung-ePA-Telematikinfrastruktur-1536x280.png 1536w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Gematik-Meldung-ePA-Telematikinfrastruktur-200x37.png 200w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Gematik-Meldung-ePA-Telematikinfrastruktur-400x73.png 400w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Gematik-Meldung-ePA-Telematikinfrastruktur-600x110.png 600w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Gematik-Meldung-ePA-Telematikinfrastruktur-800x146.png 800w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Gematik-Meldung-ePA-Telematikinfrastruktur-1200x219.png 1200w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Gematik-Meldung-ePA-Telematikinfrastruktur.png 1742w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Abb. 4: Meldung der gematik \u00fcber mehrere Tage zu einer St\u00f6rung an der (nicht von ihr betriebenen) Telematikinfrastruktur<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"d-funktionalitat\">d) Funktionalit\u00e4t<\/h3>\n\n\n\n<p>Viele Use Cases werden noch nicht unterst\u00fctzt, an vielen Stellen mangelt es an Funktionalit\u00e4ten. So ist die Aussage, dass die Telematikinfrastruktur eine Fallnummernsuche erm\u00f6glicht, nur bedingt korrekt.<\/p>\n\n\n\n<p>Die Fallnummern vergeben die Gesundheitsdienstleister bzw. deren IT-Systeme. Externe Systeme kennen also weder die F\u00e4lle noch deren Nummern. Daher m\u00fcssen Externe die Patienten direkt suchen k\u00f6nnen. Aber aufgeben kann und will man die Fallnummern nicht, da die F\u00e4lle f\u00fcr die \u00c4rzte und (Medizin-)Controller eine wichtige Klammer bilden.<\/p>\n\n\n\n<p>Um Funktionalit\u00e4t zu erreichen, wird man als Ergebnis in ISiK 2 wohl eine Anpassung bzgl. der Fallnummer in den FHIR-Standardprofilen vorschlagen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"6-fazit\">6. Fazit<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-es-geht-weiter\">a) Es geht weiter \u2026<\/h3>\n\n\n\n<p>Die Schlinge f\u00fcr die Hersteller von medizinischen Informationssystemen zieht sich enger \u2013 zumindest im Bereich der Interoperabilit\u00e4t. Das ist aber auch gut. Denn offensichtlich hat der Markt es nicht vermocht, die Voraussetzungen f\u00fcr die Digitalisierung zu schaffen: Standardisierte Schnittstellen, die auch genutzt werden.<\/p>\n\n\n\n<p>Erst der gesetzliche Zwang und die Motivation mit Geld (KHZG) haben Bewegung in die Digitalisierung des Gesundheitswesens gebracht.<\/p>\n\n\n\n<p>Sp\u00e4testens die <a href=\"https:\/\/www.gematik.de\/fileadmin\/user_upload\/gematik\/files\/Presseinformationen\/gematik_Whitepaper_Arena_digitale_Medizin_TI_2.0_Web.pdf\">TI 2.0<\/a> wird (weitgehend) vollst\u00e4ndig mit strukturierten Daten arbeiten und somit zum Standard im deutschen Gesundheitswesen werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"b-nach-einem-jahrzehnt-des-peinlichen-stillstands\">b) \u2026 nach einem Jahrzehnt des peinlichen Stillstands<\/h3>\n\n\n\n<p>Es ist auch \u201enur\u201c eine Digitalisierung und noch keine digitale Transformation oder gar digitale Revolution. Denn Technologien und Standards wie REST und E-Mail sind zwar bew\u00e4hrt. Sich aber daf\u00fcr zu feiern, dass man diese nun auch im Gesundheitswesen etabliert, w\u00fcrde in anderen L\u00e4ndern eher Verwunderung ausl\u00f6sen.<\/p>\n\n\n\n<p>Aber es n\u00fctzt nichts, dar\u00fcber zu klagen, dass man \u00fcber ein Jahrzehnt verschlafen hat, dass viele Protagonisten ein peinliches Bild abgeben und die Einf\u00fchrung einer Telematikinfrastruktur behindert und verz\u00f6gert haben.<\/p>\n\n\n\n<p>Wer noch im Jahr 2021 ein Digitalisierungsmoratorium fordert, nachdem Deutschland auf die hinteren R\u00e4nge bei der Digitalisierung abgerutscht ist, ist m\u00f6glicherweise nicht Teil der L\u00f6sung, sondern Teil des Problems.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"c-die-hersteller-sind-gefordert-und-gefordert\">c) Die Hersteller sind gefordert und gef\u00f6rdert<\/h3>\n\n\n\n<p>Wir stehen da, wo wir stehen. Die Hersteller tun gut daran, die gesetzlichen Anforderungen an die Interoperabilit\u00e4t zu erf\u00fcllen. Sp\u00e4testens ab 2024 kann sich diesen Anforderungen keiner mehr entziehen.<\/p>\n\n\n\n<p>Sie sollten sich sogar aktiv an deren Weiterentwicklung beteiligen. Denn sie wissen, was der Markt ben\u00f6tigt. Die Hersteller selbst sind diejenigen, die die Schnittstellen implementieren und nutzen wollen. Es ist an der Zeit, die Monolithen gegen\u00fcber Subsystemen und mobilen Anwendungen zu \u00f6ffnen.<\/p>\n\n\n\n<p>Das Krankenhauszukunftsgesetz KHZG hat eine Goldgr\u00e4berstimmung und einen Digitalisierungsboom ausgel\u00f6st. Das Gesetz beg\u00fcnstigt aber nur Systeme, welche kompatibel mit der ePA\/TI sind und die bereits definierten Standards im Gesundheitswesen einhalten.<\/p>\n\n\n\n<p>Damit k\u00f6nnen schnelle, ungeplante und propriet\u00e4re Eigenentwicklungen von Herstellern ab 2024 nur noch schwer am (deutschen) Markt bestehen.<\/p>\n\n\n\n<p>Bei all dem darf nicht vergessen werden, dass die Digitalisierung und die Sicherstellung der Interoperabilit\u00e4t kein Selbstzweck sein d\u00fcrfen. Es geht um nicht weniger als um die Sicherstellung der Gesundheitsversorgung.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p>Dank geht an Nick Seidel f\u00fcr Korrekturen und Erg\u00e4nzungen &#8211; auch aus Sicht der Krankenhaus-IT.<\/p>\n\n\n\n<p><em>Das Johner Institut unterst\u00fctzt Sie gern bei Ihren Fragen zur Telematikinfrastruktur. Wie genau, erfahren Sie in einem <a href=\"https:\/\/www.johner-institut.de\/kontakt\/\">kostenlosen Expertengespr\u00e4ch<\/a>.<\/em> <\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p>Versionshistorie:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>2024-04-19: Links auf Simplifier.net aktualisiert<\/li>\n\n\n\n<li>2022-03-18: Unter 3d) Hinweise zum ISiP erg\u00e4nzt.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Die Telematikinfrastruktur (TI) ist eine Plattform bzw. ein Netzwerk, \u00fcber das in Deutschland Gesundheitsdaten sicher ausgetauscht werden und auf der Gesundheitsanwendungen wie die elektronische Patientenakte und das e-Rezept betrieben werden sollen. Dieser Beitrag hilft Herstellern medizinischer Software zu verstehen, wann sie welche gesetzlichen und technischen Anforderungen im Kontext dieser Telematikinfrastruktur erf\u00fcllen m\u00fcssen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Welche Anforderungen an die Telematikinfrastruktur m\u00fcssen Software-Hersteller beachten, um im Markt zu bestehen? Unser neuer Artikel verschafft Ihnen einen \u00dcberblick.\n\n#medizintechnik #medtech #software","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,1108],"tags":[198,1107,269],"ppma_author":[1210],"class_list":["post-4583377","post","type-post","status-publish","format-standard","hentry","category-gesundheitswesen","category-regulatory-affairs","tag-interoperabilitat","tag-krankenhaus","tag-medizinische-software","category-5","category-1108","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Telematikinfrastruktur: 5 Anforderungen, die Software-Hersteller beachten m\u00fcssen<\/title>\n<meta name=\"description\" content=\"Der Beitrag gibt einen \u00dcberblick \u00fcber die Telematikinfrastruktur und die technischen und gesetzlichen Anforderungen. Must-Read f\u00fcr Hersteller\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Telematikinfrastruktur: 5 Anforderungen, die Software-Hersteller beachten m\u00fcssen\" \/>\n<meta property=\"og:description\" content=\"Der Beitrag gibt einen \u00dcberblick \u00fcber die Telematikinfrastruktur und die technischen und gesetzlichen Anforderungen. Must-Read f\u00fcr Hersteller\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/\" \/>\n<meta property=\"og:site_name\" content=\"Regulatorisches Wissen f\u00fcr Medizinprodukte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JohnerInstitut\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-19T18:09:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-20T13:48:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"337\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Prof. Dr. Christian Johner\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prof. Dr. Christian Johner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"18\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/\"},\"author\":{\"name\":\"Prof. Dr. Christian Johner\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/77ee54cd54e987c0b5738d4cb4c80441\"},\"headline\":\"Telematikinfrastruktur: 5 Anforderungen, die Software-Hersteller beachten m\u00fcssen\",\"datePublished\":\"2024-04-19T18:09:10+00:00\",\"dateModified\":\"2024-10-20T13:48:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/\"},\"wordCount\":3172,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Telematikinfrastruktur-small.png\",\"keywords\":[\"Interoperabilit\u00e4t - auch gesetzlich verpflichtend\",\"Krankenh\u00e4user - Labore - Praxen und andere Betreiber\",\"Medizinische Software \\\/ Medical Device Software\"],\"articleSection\":[\"Gesundheitswesen &amp; Health IT\",\"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/\",\"name\":\"Telematikinfrastruktur: 5 Anforderungen, die Software-Hersteller beachten m\u00fcssen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Telematikinfrastruktur-small.png\",\"datePublished\":\"2024-04-19T18:09:10+00:00\",\"dateModified\":\"2024-10-20T13:48:03+00:00\",\"description\":\"Der Beitrag gibt einen \u00dcberblick \u00fcber die Telematikinfrastruktur und die technischen und gesetzlichen Anforderungen. Must-Read f\u00fcr Hersteller\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Telematikinfrastruktur-small.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Telematikinfrastruktur-small.png\",\"width\":1000,\"height\":337},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/regulatory-affairs\\\/telematikinfrastruktur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/category\\\/regulatory-affairs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Telematikinfrastruktur: 5 Anforderungen, die Software-Hersteller beachten m\u00fcssen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"name\":\"Regulatorisches Wissen f\u00fcr Medizinprodukte\",\"description\":\"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\",\"name\":\"Johner Institut GmbH\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"width\":1213,\"height\":286,\"caption\":\"Johner Institut GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JohnerInstitut\\\/\",\"https:\\\/\\\/x.com\\\/christianjohner\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/JohnerInstitut\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/77ee54cd54e987c0b5738d4cb4c80441\",\"name\":\"Prof. Dr. Christian Johner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Christian_Johner.jpgab057afc2debeb41aaf55cce7e79e618\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Christian_Johner.jpg\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Christian_Johner.jpg\",\"caption\":\"Prof. Dr. Christian Johner\"},\"description\":\"Professor Johner ist Experte f\u00fcr die Entwicklung und Zulassung von Medizinprodukten, die Software enthalten oder Software sind. Als Auditor, als Mitglied eines Normen-Komitees, als Ausbilder benannter Stellen sowie als Autor mehrerer B\u00fccher und Leitf\u00e4den tr\u00e4gt der promovierte Physiker zur Weiterentwicklung der regulatorischen Landschaft bei. Davon zeugen auch Leitf\u00e4den, die er f\u00fcr die WHO und die Benannten Stellen entwickelt hat. Sein Unternehmen, das Johner Institut, unterst\u00fctzt Medizinproduktehersteller weltweit beim Aufbau von QM-Systemen, bei der Zulassung und Pr\u00fcfung ihrer Produkte sowie bei der digitalen Transformation regulatorischer Prozesse. Es bietet Weiterbildungen wie E-Learning und Seminare an und \u00fcbernimmt f\u00fcr Hersteller Prozesse wie die \u00dcberwachung der Regularien und der Produkte im Markt. Christian Johner lehrte an mehreren Universit\u00e4ten u.a. an der Hochschule Konstanz, der Universit\u00e4t St. Gallen, der Universit\u00e4t W\u00fcrzburg sowie der Stanford University v.a. Software-Architektur, Software-Qualit\u00e4tssicherung und medizinische Informatik.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/christianjohner\\\/\",\"https:\\\/\\\/x.com\\\/christianjohner\"],\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/author\\\/christian\\\/\"}]}<\/script>\n<meta name=\"copyright\" content=\"Johner Institut GmbH\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Telematikinfrastruktur: 5 Anforderungen, die Software-Hersteller beachten m\u00fcssen","description":"Der Beitrag gibt einen \u00dcberblick \u00fcber die Telematikinfrastruktur und die technischen und gesetzlichen Anforderungen. Must-Read f\u00fcr Hersteller","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/","og_locale":"de_DE","og_type":"article","og_title":"Telematikinfrastruktur: 5 Anforderungen, die Software-Hersteller beachten m\u00fcssen","og_description":"Der Beitrag gibt einen \u00dcberblick \u00fcber die Telematikinfrastruktur und die technischen und gesetzlichen Anforderungen. Must-Read f\u00fcr Hersteller","og_url":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/","og_site_name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","article_publisher":"https:\/\/www.facebook.com\/JohnerInstitut\/","article_published_time":"2024-04-19T18:09:10+00:00","article_modified_time":"2024-10-20T13:48:03+00:00","og_image":[{"width":1000,"height":337,"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small.png","type":"image\/png"}],"author":"Prof. Dr. Christian Johner","twitter_misc":{"Verfasst von":"Prof. Dr. Christian Johner","Gesch\u00e4tzte Lesezeit":"18\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/#article","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/"},"author":{"name":"Prof. Dr. Christian Johner","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/77ee54cd54e987c0b5738d4cb4c80441"},"headline":"Telematikinfrastruktur: 5 Anforderungen, die Software-Hersteller beachten m\u00fcssen","datePublished":"2024-04-19T18:09:10+00:00","dateModified":"2024-10-20T13:48:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/"},"wordCount":3172,"commentCount":4,"publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small.png","keywords":["Interoperabilit\u00e4t - auch gesetzlich verpflichtend","Krankenh\u00e4user - Labore - Praxen und andere Betreiber","Medizinische Software \/ Medical Device Software"],"articleSection":["Gesundheitswesen &amp; Health IT","Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/","url":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/","name":"Telematikinfrastruktur: 5 Anforderungen, die Software-Hersteller beachten m\u00fcssen","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/#primaryimage"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small.png","datePublished":"2024-04-19T18:09:10+00:00","dateModified":"2024-10-20T13:48:03+00:00","description":"Der Beitrag gibt einen \u00dcberblick \u00fcber die Telematikinfrastruktur und die technischen und gesetzlichen Anforderungen. Must-Read f\u00fcr Hersteller","breadcrumb":{"@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/#primaryimage","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2022\/01\/Telematikinfrastruktur-small.png","width":1000,"height":337},{"@type":"BreadcrumbList","@id":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/telematikinfrastruktur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.johner-institut.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte","item":"https:\/\/www.johner-institut.de\/blog\/category\/regulatory-affairs\/"},{"@type":"ListItem","position":3,"name":"Telematikinfrastruktur: 5 Anforderungen, die Software-Hersteller beachten m\u00fcssen"}]},{"@type":"WebSite","@id":"https:\/\/www.johner-institut.de\/blog\/#website","url":"https:\/\/www.johner-institut.de\/blog\/","name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","description":"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen","publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.johner-institut.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.johner-institut.de\/blog\/#organization","name":"Johner Institut GmbH","url":"https:\/\/www.johner-institut.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","width":1213,"height":286,"caption":"Johner Institut GmbH"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JohnerInstitut\/","https:\/\/x.com\/christianjohner","https:\/\/www.youtube.com\/user\/JohnerInstitut"]},{"@type":"Person","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/77ee54cd54e987c0b5738d4cb4c80441","name":"Prof. Dr. Christian Johner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpgab057afc2debeb41aaf55cce7e79e618","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpg","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpg","caption":"Prof. Dr. Christian Johner"},"description":"Professor Johner ist Experte f\u00fcr die Entwicklung und Zulassung von Medizinprodukten, die Software enthalten oder Software sind. Als Auditor, als Mitglied eines Normen-Komitees, als Ausbilder benannter Stellen sowie als Autor mehrerer B\u00fccher und Leitf\u00e4den tr\u00e4gt der promovierte Physiker zur Weiterentwicklung der regulatorischen Landschaft bei. Davon zeugen auch Leitf\u00e4den, die er f\u00fcr die WHO und die Benannten Stellen entwickelt hat. Sein Unternehmen, das Johner Institut, unterst\u00fctzt Medizinproduktehersteller weltweit beim Aufbau von QM-Systemen, bei der Zulassung und Pr\u00fcfung ihrer Produkte sowie bei der digitalen Transformation regulatorischer Prozesse. Es bietet Weiterbildungen wie E-Learning und Seminare an und \u00fcbernimmt f\u00fcr Hersteller Prozesse wie die \u00dcberwachung der Regularien und der Produkte im Markt. Christian Johner lehrte an mehreren Universit\u00e4ten u.a. an der Hochschule Konstanz, der Universit\u00e4t St. Gallen, der Universit\u00e4t W\u00fcrzburg sowie der Stanford University v.a. Software-Architektur, Software-Qualit\u00e4tssicherung und medizinische Informatik.","sameAs":["https:\/\/www.linkedin.com\/in\/christianjohner\/","https:\/\/x.com\/christianjohner"],"url":"https:\/\/www.johner-institut.de\/blog\/author\/christian\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":4179626,"url":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/dvpmg\/","url_meta":{"origin":4583377,"position":0},"title":"DVPMG \u2013 Digitale-Versorgung-und-Pflege-Modernisierungs-Gesetz","author":"Claudia Schmitt","date":"27. Januar 2023","format":false,"excerpt":"Seit dem 09. Juni 2021 gilt das Gesetz zur digitalen Modernisierung von Versorgung und Pflege. Es tr\u00e4gt auch den Titel \u201eDigitale-Versorgung-und-Pflege-Modernisierungs-Gesetz\u201c, kurz DVPMG. Dieses Gesetz \u00e4ndert zahlreiche andere Gesetze und Verordnungen, z. B. das SGB V und die DiGAV. Dabei geht das DVPMG weit \u00fcber die Einf\u00fchrung von digitalen Pflegeanwendungen\u2026","rel":"","context":"In &quot;Gesundheitswesen &amp; Health IT&quot;","block_context":{"text":"Gesundheitswesen &amp; Health IT","link":"https:\/\/www.johner-institut.de\/blog\/category\/gesundheitswesen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2021\/07\/DVPMG-SGB-V-Paragraph-374a.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2021\/07\/DVPMG-SGB-V-Paragraph-374a.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2021\/07\/DVPMG-SGB-V-Paragraph-374a.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2021\/07\/DVPMG-SGB-V-Paragraph-374a.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2021\/07\/DVPMG-SGB-V-Paragraph-374a.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2021\/07\/DVPMG-SGB-V-Paragraph-374a.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":2947521,"url":"https:\/\/www.johner-institut.de\/blog\/gesundheitswesen\/digitale-versorgung-gesetz-dvg\/","url_meta":{"origin":4583377,"position":1},"title":"Das Digitale-Versorgung-Gesetz (DVG) \u2013 als Hersteller damit Geld verdienen?","author":"Claudia Schmitt","date":"27. Januar 2023","format":false,"excerpt":"Das Digitale-Versorgung-Gesetz (DVG) bietet Herstellern digitaler Medizinprodukte eine neue M\u00f6glichkeit, Geld zu verdienen. Die Kostenerstattung soll schneller und einfacher erfolgen als herk\u00f6mmliche Verfahren, z. B. die bisherige Aufnahme in den Hilfsmittelkatalog. Hinweis Das DVG ist ein Gesetz, das bestehende Gesetze (siehe unten) ge\u00e4ndert hat. Mit dem DVPMG hat der Gesetzgeber\u2026","rel":"","context":"In &quot;Gesundheitswesen &amp; Health IT&quot;","block_context":{"text":"Gesundheitswesen &amp; Health IT","link":"https:\/\/www.johner-institut.de\/blog\/category\/gesundheitswesen\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/04\/DVG-Positive-Versorgungsaspekte.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/04\/DVG-Positive-Versorgungsaspekte.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/04\/DVG-Positive-Versorgungsaspekte.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2020\/04\/DVG-Positive-Versorgungsaspekte.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1529674,"url":"https:\/\/www.johner-institut.de\/blog\/regulatory-affairs\/leitfaden-it-sicherheit-guideline-it-security\/","url_meta":{"origin":4583377,"position":2},"title":"Leitfaden IT-Sicherheit \/ Guideline IT Security","author":"Christian Rosenzweig","date":"6. Dezember 2018","format":false,"excerpt":"Gemeinsam mit dem T\u00dcV S\u00dcD, dem T\u00dcV Nord und mit Unterst\u00fctzung von Dr. Heidenreich (Siemens) hat das Johner Institut am 21.11. einen Leitfaden zur IT-Sicherheit\u00a0speziell f\u00fcr Medizinproduktehersteller ver\u00f6ffentlicht. An wen sich der Leitfaden zur IT-Sicherheit wendet Der Leitfaden richtet sich an alle Hersteller von Medizinprodukten (Inverkehrbringer, Dienstleister). Er sollte v.a.\u2026","rel":"","context":"In &quot;Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte&quot;","block_context":{"text":"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte","link":"https:\/\/www.johner-institut.de\/blog\/category\/regulatory-affairs\/"},"img":{"alt_text":"Leitfaden IT-Sicherheit","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2018\/12\/Leitfaden-IT-Sicherheit-300x242.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5372085,"url":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/iec-80001-1\/","url_meta":{"origin":4583377,"position":3},"title":"DIN EN IEC 80001-1:2023","author":"Christian Rosenzweig","date":"6. Juni 2023","format":false,"excerpt":"Die IEC 80001-1 tr\u00e4gt den langen Titel \u201eAnwendung des Risikomanagements f\u00fcr IT-Netzwerke, die Medizinprodukte beinhalten\u00a0\u2013 Teil 1: Aufgaben, Verantwortlichkeiten und Aktivit\u00e4ten\u201c. Was die Norm verlangt und weshalb sich auch die Hersteller damit besch\u00e4ftigten sollen, verr\u00e4t dieser Artikel. 1. \u00dcber die DIN EN IEC 80001-1 a) Ziele der DIN EN IEC\u2026","rel":"","context":"In &quot;Risikomanagement &amp; ISO 14971&quot;","block_context":{"text":"Risikomanagement &amp; ISO 14971","link":"https:\/\/www.johner-institut.de\/blog\/category\/iso-14971-risikomanagement\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/Kapitelstruktur-IEC-80001-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/Kapitelstruktur-IEC-80001-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/Kapitelstruktur-IEC-80001-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/Kapitelstruktur-IEC-80001-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/Kapitelstruktur-IEC-80001-1.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/04\/Kapitelstruktur-IEC-80001-1.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":2972888,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/medical-grade-software\/","url_meta":{"origin":4583377,"position":4},"title":"Medical Grade Software","author":"Prof. Dr. Christian Johner","date":"10. Dezember 2019","format":false,"excerpt":"\u201eWir entwickeln Medical Grade Software\u201c, behaupten Hersteller und Entwicklungsdienstleister, ohne zu spezifizieren, was sie unter \u201eMedical Grade\u201c verstehen. Diese Definition ist wichtig. Nur so l\u00e4sst sich einsch\u00e4tzen, wie sehr diese Software beitragen kann, um regulatorische Anforderungen zu erf\u00fcllen. Hersteller werben mit dem Attribut \u201eMedical Grade Software\u201c. Zudem schie\u00dfen neue Pr\u00fcfsiegel\u2026","rel":"","context":"In &quot;Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte&quot;","block_context":{"text":"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte","link":"https:\/\/www.johner-institut.de\/blog\/category\/regulatory-affairs\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2019\/12\/Medical-Grade-Software-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2019\/12\/Medical-Grade-Software-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2019\/12\/Medical-Grade-Software-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2019\/12\/Medical-Grade-Software-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5376998,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/it-security-bei-legacy-devices\/","url_meta":{"origin":4583377,"position":5},"title":"IT-Security bei \u201cLegacy Devices\u201d","author":"Christian Rosenzweig","date":"28. November 2023","format":false,"excerpt":"Dass Gesetze und Normen die IT-Security auch bei \u201eLegacy Devices\u201c einfordern, ist verst\u00e4ndlich. Die Art, wie diese Anforderungen formuliert werden, f\u00fchrt allerdings oft zu Verwirrung. Beispielsweise konnten sich Gesetzgeber und Normenkomitees nicht auf gemeinsame Definitionen einigen. So geht es einmal um die IT-Sicherheit bei Legacy Devices, einmal um die IT-Sicherheit\u2026","rel":"","context":"In &quot;Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte&quot;","block_context":{"text":"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte","link":"https:\/\/www.johner-institut.de\/blog\/category\/regulatory-affairs\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/11\/IT-Security_bei_Legacy_Devices.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/11\/IT-Security_bei_Legacy_Devices.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/11\/IT-Security_bei_Legacy_Devices.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/11\/IT-Security_bei_Legacy_Devices.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/11\/IT-Security_bei_Legacy_Devices.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/11\/IT-Security_bei_Legacy_Devices.png?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pavawf-jelr","jetpack_sharing_enabled":true,"authors":[{"term_id":1210,"user_id":1,"is_guest":0,"slug":"christian","display_name":"Prof. Dr. Christian Johner","avatar_url":{"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpg","url2x":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":""}],"_links":{"self":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/4583377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/comments?post=4583377"}],"version-history":[{"count":82,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/4583377\/revisions"}],"predecessor-version":[{"id":5379709,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/4583377\/revisions\/5379709"}],"wp:attachment":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/media?parent=4583377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/categories?post=4583377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/tags?post=4583377"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/ppma_author?post=4583377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}