{"id":6127,"date":"2025-05-07T13:47:31","date_gmt":"2025-05-07T11:47:31","guid":{"rendered":"http:\/\/www.johner-institut.de\/blog\/?p=6127"},"modified":"2025-05-09T10:24:52","modified_gmt":"2025-05-09T08:24:52","slug":"restrisiko","status":"publish","type":"post","link":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/","title":{"rendered":"Restrisiko: Diese Zahlen sollten Sie kennen"},"content":{"rendered":"\n<p>Ein Restrisiko ist laut ISO 14971 das \u201eRisiko, das nach Durchf\u00fchrung von Ma\u00dfnahmen zur Risikobeherrschung verbleibt.\u201c Doch welche Restrisiken sind akzeptabel? Damit tun sich viele Medizinproduktehersteller schwer.<\/p>\n\n\n\n<p>Lesen Sie hier, wie Sie zu belastbaren Akzeptanzkriterien f\u00fcr das Restrisiko kommen. <a href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko#zahlen\">Diese Zahlen<\/a> k\u00f6nnen Ihnen n\u00fctzlich sein.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">1. Restrisiko: Die Grundlagen<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">a) Kontext<\/h3>\n\n\n\n<p>Medizinprodukte und IVD bergen Risiken, welche die Hersteller durch geeignete Ma\u00dfnahmen so weit wie m\u00f6glich reduzieren m\u00fcssen.<\/p>\n\n\n\n<div class=\"jig_defbox\"><div class=\"jig_defbox-definition\"><div class=\"jig_defbox-icon-wrapper\" style=\"fill:#919191\"><svg viewBox=\"0 0 512 512\" width=\"24\" height=\"24\" class=\"dashicons\" aria-hidden=\"true\"><g><path d=\"M430.9,177.6c-0.3-96-78.1-174.1-174-174.9c-0.1,0-0.2,0-0.4,0c-0.2,0-0.4,0-0.5,0c-0.2,0-0.4,0-0.5,0 c-0.1,0-0.2,0-0.4,0c-95.9,0.8-173.7,78.9-174,174.9c-0.4,7.3-1.9,60.3,36.6,109.2c29.5,37.6,49.4,74.7,55,85.9v63.5 c0,0,0,0.1,0,0.1c0,0.5,0,0.9,0.1,1.4c0,0.3,0.1,0.6,0.1,0.9c0,0.1,0,0.2,0,0.2c0.4,2.7,1.4,5.2,3,7.4l33.7,55.1 c3.1,5.1,8.7,8.2,14.7,8.2h61.8c6,0,11.5-3.1,14.7-8.2l33.7-55.1c1.5-2.1,2.6-4.6,3-7.4c0-0.1,0-0.2,0-0.2c0-0.3,0.1-0.6,0.1-0.9 c0-0.5,0.1-0.9,0.1-1.4c0,0,0-0.1,0-0.1v-60.3c1.2-2.4,22.3-45.5,56.7-89.2C432.8,237.8,431.3,184.9,430.9,177.6z M303.3,418.8 h-96.2v-33.1h96.2V418.8z M276.4,475h-42.5l-13.3-21.6h69L276.4,475z M311.6,351.4H200.4c-8.6-16.3-28-50.6-55.7-85.9 c-32-40.6-29.3-85.7-29.3-86c0-0.4,0.1-0.9,0.1-1.3c0-77.6,63-140.8,140.5-141.1c77.5,0.3,140.5,63.5,140.5,141.1 c0,0.4,0,0.9,0.1,1.3c0,0.4,3.1,44.9-29.3,86C339.5,300.8,320.2,335.1,311.6,351.4z\"><\/path><path d=\"M257.8,64.4c-62,0-112.5,50.5-112.5,112.5c0,9.5,7.7,17.2,17.2,17.2s17.2-7.7,17.2-17.2 c0-43.1,35-78.1,78.1-78.1c9.5,0,17.2-7.7,17.2-17.2S267.3,64.4,257.8,64.4z\"><\/path><\/g><\/svg><\/div><span class=\"jig_defbox-header\" style=\"color:#919191\">Beispiel<\/span><\/div>\n<p>Ein Defibrillator kann versehentlich ausgel\u00f6st werden und zu Sch\u00e4digungen des Patienten f\u00fchren, z. B. dessen Herzens. Die Kombination aus Schweregrad und Wahrscheinlichkeit dieser Sch\u00e4den ist das Risiko.<\/p>\n\n\n\n<p>Wenn der Hersteller den Defibrillator so entwirft, dass die Anwender zwei H\u00e4nde zum Ausl\u00f6sen ben\u00f6tigen, senkt er mit dieser Ma\u00dfnahme die Wahrscheinlichkeit einer versehentlichen Ausl\u00f6sung und damit das Risiko.<\/p>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">b) Einzel-Restrisiko versus Gesamt-Restrisiko<\/h3>\n\n\n\n<p>Beschlie\u00dft der Hersteller, bei einem Risiko keine weiteren Ma\u00dfnahmen durchzuf\u00fchren, so entspricht das Risiko nach den getroffenen Ma\u00dfnahmen dem Einzel-Restrisiko.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Einzelrisiko.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"458\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Einzelrisiko-1024x458.jpg\" alt=\"Ma\u00dfnahmen reduzieren ein Risiko. Erfolgen keine weiteren Ma\u00dfnahmen, entspricht es dem Einzel-Restrisiko.\" class=\"wp-image-5381294\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Einzelrisiko-1024x458.jpg 1024w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Einzelrisiko-300x134.jpg 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Einzelrisiko-768x344.jpg 768w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Einzelrisiko.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Abb. 1: Ma\u00dfnahmen reduzieren ein Risiko. Erfolgen keine weiteren Ma\u00dfnahmen, entspricht es dem Einzel-Restrisiko.<\/figcaption><\/figure>\n\n\n\n<p>Analog entspricht das Gesamt-Restrisiko des Produkts dem Risiko nach allen getroffenen Ma\u00dfnahmen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Gesamtrisiken.jpg\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"426\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Gesamtrisiken-1024x426.jpg\" alt=\"Ma\u00dfnahmen reduzieren die Risiken von Medizinprodukten bzw. IVD. Am Ende dieser Ma\u00dfnahmen verbleibt das Gesamt-Restrisiko.\" class=\"wp-image-5381295\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Gesamtrisiken-1024x426.jpg 1024w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Gesamtrisiken-300x125.jpg 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Gesamtrisiken-768x319.jpg 768w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Gesamtrisiken.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Abb. 2: Ma\u00dfnahmen reduzieren die Risiken von Medizinprodukten bzw. IVD. Am Ende dieser Ma\u00dfnahmen verbleibt das Gesamt-Restrisiko.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"iso14971\">2. Restrisiko: Regulatorische Anforderungen <\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">a) Anforderungen der ISO 14971<\/h3>\n\n\n\n<p>Die ISO 14971 fordert von den Herstellern, jedes Einzel-Restrisiko auf Akzeptanz zu beurteilen. Diese Bewertung muss anhand der im Risikomanagementplan festgelegten Kriterien erfolgen.<\/p>\n\n\n\n<p>Die Hersteller sind zudem verpflichtet sicherzustellen, dass der Nutzen des Produkts die Gesamt-Restrisiken \u00fcberwiegt.<\/p>\n\n\n\n<p>Weiter m\u00fcssen die Hersteller dar\u00fcber entscheiden, welche Restrisiken sie z. B. in einer Gebrauchsanweisung offenlegen.<\/p>\n\n\n\n<p>Schlie\u00dflich fordert die Norm, die Restrisiken und deren Akzeptanz so lange kontinuierlich zu bewerten, wie die Produkte im Markt sind.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">b) MDR<\/h3>\n\n\n\n<p>Die MDR verpflichtet die Hersteller dazu, sowohl die Einzel-Restrisiken als auch das Gesamt-Restrisiko zu minimieren:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Zwecks Risikosenkung zielt das Risikomanagement der Hersteller darauf ab, dass sowohl das mit jeder einzelnen Gef\u00e4hrdung verbundene Restrisiko als auch das Gesamtrestrisiko als akzeptabel eingestuft werden.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><a href=\"https:\/\/mdr-konsolidiert.johner-institut.de\/mdr_de.html#annex-I\">MDR, Anhang I<\/a>, 4.<\/p>\n<\/blockquote>\n\n\n\n<p>Die MDR fordert gleich an zwei Stellen, die Restrisiken in der Gebrauchsanweisung offenzulegen:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Die Hersteller unterrichten die Anwender \u00fcber etwaige Restrisiken.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><a href=\"https:\/\/mdr-konsolidiert.johner-institut.de\/mdr_de.html#annex-I\">MDR, Anhang I<\/a>, 4.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Die Gebrauchsanweisung enth\u00e4lt alle folgenden Angaben:<\/em><\/p>\n\n\n\n<p><em>g) etwaige Restrisiken, Kontraindikationen und alle unerw\u00fcnschten Nebenwirkungen, einschlie\u00dflich der dem Patienten in diesem Zusammenhang mitzuteilenden Informationen;<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><a href=\"https:\/\/mdr-konsolidiert.johner-institut.de\/mdr_de.html#annex-I\">MDR, Anhang I<\/a>, 23.4<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"akzeptanz\">3. Welche Restrisiken sind akzeptabel?<\/h2>\n\n\n\n<p>Dieser <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/risikobewertung\/\">ausf\u00fchrliche Beitrag zur Risikoakzeptanz<\/a> diskutiert, dass ein Risiko nur dann akzeptabel sein kann, wenn der Nutzen h\u00f6her ist.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-ISO-14971.png\" data-rel=\"lightbox-image-2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"158\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-ISO-14971-300x158.png\" alt=\"Restrisiko und Risikoakzeptanz\" class=\"wp-image-12440\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-ISO-14971-300x158.png 300w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-ISO-14971-150x79.png 150w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-ISO-14971.png 936w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Beispiel 1: Restrisiko bei Produkten mit potenziell t\u00f6dlichen Folgen<\/h3>\n\n\n\n<p>Ein Bestrahlungsger\u00e4t dient v. a. dazu, an Krebs erkrankte Patienten zu behandeln. Die Strahlung verursacht aber Strahlensch\u00e4den, die wiederum neuen Krebs ausl\u00f6sen k\u00f6nnen.<\/p>\n\n\n\n<p>Das Risiko dieser strahlungsinduzierten, potenziell t\u00f6dlichen Erkrankung ist nur dann akzeptabel, wenn der Nutzen h\u00f6her ist. Konkret muss die Anzahl der Toten, die mit dem Ger\u00e4t auftreten, kleiner sein als die Anzahl der Toten, die ohne das Ger\u00e4t auftreten. Mit \u201eohne Ger\u00e4t\u201c ist aber nicht gemeint, dass die Patienten \u00fcberhaupt nicht behandelt w\u00fcrden, sondern mit der besten Alternative, z. B. einem anderen Bestrahlungsger\u00e4t, einer Chemotherapie, einer OP usw.<\/p>\n\n\n\n<p>Diese Alternativen stellen den Stand der Technik dar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Beispiel 2: Restrisiko bei Produkten ohne potenziell t\u00f6dliche Folgen<\/h3>\n\n\n\n<p>Bei Medizinprodukten, die nicht lebensrettend sein k\u00f6nnen, greift diese Argumentation nicht. Ein Beispiel ist ein Laufband f\u00fcr die Rehabilitation. Im besten Fall kann das Produkt dazu beitragen, dass die Patienten nach einer Erkrankung oder einem Unfall schneller wieder auf den F\u00fc\u00dfen sind \u2013 im wahrsten Sinne des Wortes.<\/p>\n\n\n\n<p>Dennoch k\u00f6nnen diese Produkte den Tod von Patienten verursachen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Der Patient st\u00fcrzt, beispielsweise weil das Laufband blockiert, und schl\u00e4gt mit dem Kopf auf dem Boden auf.<\/li>\n\n\n\n<li>Die Isolation eines Kabels bricht; daher liegt die Netzspannung direkt auf dem Geh\u00e4use, und der Patient erleidet einen Stromschlag.<\/li>\n<\/ul>\n\n\n\n<p>F\u00fcr die Abw\u00e4gung, ob ein Restrisiko akzeptabel ist, greift der Vergleich der Anzahl von Toten wie im ersten Beispiel nicht mehr. Was tun?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">M\u00f6gliche Risikoakzeptanzkriterien<\/h3>\n\n\n\n<p>Um entscheiden zu k\u00f6nnen, ob ein Restrisiko akzeptabel ist, bieten sich folgende Typen von Kriterien an:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Direkter Vergleich des Nutzens und der Risiken<\/strong> des Produkts und der besten Alternativen, z. B. anhand der\n<ol class=\"wp-block-list\">\n<li>Anzahl der Toten<\/li>\n\n\n\n<li>Anzahl der Verletzten<\/li>\n\n\n\n<li>Lebensdauer<\/li>\n<\/ol>\n<\/li>\n\n\n\n<li><strong>Stand der Technik<\/strong>: Im zweiten Beispiel w\u00fcrde man das Restrisiko durch einen Stromschlag akzeptieren, wenn die elektrische Sicherheit dem Stand der Technik entspricht, also wenn das Medizinprodukt konform mit der <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/iec-60601-1\/\">IEC 60601-1<\/a> entwickelt und produziert wurde.<\/li>\n\n\n\n<li><strong>Vergleich mit den normalen Risiken des Lebens<\/strong>: In anderen Branchen wie der Luftfahrtindustrie vergleicht man die Risiken mit denen des normalen Lebens. Nur wenn letztere Risiken deutlich h\u00f6her sind (z. B. mindestens eine Gr\u00f6\u00dfenordnung), bewertet man ein Restrisiko als akzeptabel.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"zahlen\">3. Tipps zum Umgang mit Restrisiken<\/h2>\n\n\n\n<p>Die folgenden Zahlen k\u00f6nnen Ihnen dienlich sein, wenn Sie \u00fcber die Akzeptanz eines Restrisikos entscheiden m\u00fcssen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>In deutschen Krankenh\u00e4usern treten pro Jahr ca. 500.000 Infektionen auf (z. B. Wundinfektionen nach Operationen) [Quelle: Charit\u00e9]. Wenn\u00a0<span style=\"line-height: 1.5;\">\u00c4rzte behaupten, durch ein Medizinprodukt d\u00fcrften \u00fcberhaupt keine Todesf\u00e4lle verursacht werden, kann man sie darauf hinweisen, dass zwischen 80.000 und 180.000 Infektionen vermeidbar w\u00e4ren [<\/span><a style=\"line-height: 1.5;\" href=\"http:\/\/www.krankenhaushygiene.de\/informationen\/presseinformationen\/pressearchiv\/\">Quelle<\/a><span style=\"line-height: 1.5;\">].<\/span><\/li>\n\n\n\n<li>3.000 Patienten sterben j\u00e4hrlich im Krankenhaus durch MRSA-Infektionen; davon w\u00e4re ein Drittel vermeidbar [<a href=\"http:\/\/www.aerzteblatt.de\/archiv\/79669\/Krankenhaushygiene-Kampf-den-Killerkeimen\">Quelle<\/a>]. Die Wahrscheinlichkeit, an einem Keim zu sterben, betr\u00e4gt somit ca. ein Promille.<\/li>\n\n\n\n<li>Die ISO 13849-1 fordert, dass ein Maschinenanwender seltener als jede 10<sup>7<\/sup>-te Arbeitsstunde einem Ereignis mit schwerwiegender Folge ausgesetzt sein darf.<\/li>\n\n\n\n<li>Die Wahrscheinlichkeit, durch einen Autounfall ums Leben zu kommen, betr\u00e4gt ca. 2\u00d710<sup>-7<\/sup> pro Fahrstunde oder 2,7 Todesf\u00e4lle pro Milliarde Personenkilometer [<a href=\"http:\/\/www.welt.de\/wirtschaft\/article122847399\/Das-Todesrisiko-im-Auto-ist-54-Mal-hoeher-als-im-Zug.html\">Quelle<\/a>].<\/li>\n\n\n\n<li>Die geringste erfasste Sterberate haben ca. 15-j\u00e4hrige M\u00e4dchen: 3,5\u00d710<sup>-8<\/sup>\/h [<a href=\"https:\/\/www.beck-shop.de\/kiecksee-klatt-schwanbom-professionelles-risikomanagement-medizinprodukten\/product\/35197685\">Quelle<\/a>\u00a0S. 130; lesenswert ist das Kapitel 5.2].<\/li>\n<\/ul>\n\n\n\n<p>Diese Zahlen helfen Ihnen, das Restrisiko mit den Risiken des normalen Lebens bzw. den Risiken in einem Krankenhaus zu vergleichen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4. Fazit und Zusammenfassung<\/h2>\n\n\n\n<p>Hersteller m\u00fcssen die Einzel-Restrisiken und das Gesamt-Restrisiko jedes Produkts bestimmen und anhand zuvor festgelegter Kriterien auf Akzeptanz bewerten. Ob sie dieser Pflicht nachkommen, pr\u00fcfen Beh\u00f6rden und Benannte Stellen regelm\u00e4\u00dfig bei Zulassungsverfahren, Audits und Inspektionen.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>\u00c4nderungshistorie<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>2025-05-07: Artikel weitgehend neu geschrieben<\/li>\n\n\n\n<li>2015-12-14: Erste Version des Artikels publiziert<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ein Restrisiko ist laut ISO 14971 das \u201eRisiko, das nach Durchf\u00fchrung von Ma\u00dfnahmen zur Risikobeherrschung verbleibt.\u201c Doch welche Restrisiken sind akzeptabel? Damit tun sich viele Medizinproduktehersteller schwer. Lesen Sie hier, wie Sie zu belastbaren Akzeptanzkriterien f\u00fcr das Restrisiko kommen. Diese Zahlen k\u00f6nnen Ihnen n\u00fctzlich sein.<\/p>\n","protected":false},"author":74,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1103],"tags":[1117,839,737],"ppma_author":[1213],"class_list":["post-6127","post","type-post","status-publish","format-standard","hentry","category-iso-14971-risikomanagement","tag-risikoakzeptanz","tag-risikominimierung","tag-risikomanagementakte","category-1103","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restrisiko: Diese Zahlen sollten Sie kennen<\/title>\n<meta name=\"description\" content=\"Das Restrisiko ist das Risiko, das nach risikominimierenden Ma\u00dfnahmen verbleibt. Doch welche Restrisiken sind akzeptabel? Dieser Beitrag gibt Antworten\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restrisiko: Diese Zahlen sollten Sie kennen\" \/>\n<meta property=\"og:description\" content=\"Das Restrisiko ist das Risiko, das nach risikominimierenden Ma\u00dfnahmen verbleibt. Doch welche Restrisiken sind akzeptabel? Dieser Beitrag gibt Antworten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/\" \/>\n<meta property=\"og:site_name\" content=\"Regulatorisches Wissen f\u00fcr Medizinprodukte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JohnerInstitut\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-07T11:47:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T08:24:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Einzelrisiko.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"537\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Rosenzweig\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Rosenzweig\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/\"},\"author\":{\"name\":\"Christian Rosenzweig\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/a1bfe9a403a4dd4f8aed197335feb568\"},\"headline\":\"Restrisiko: Diese Zahlen sollten Sie kennen\",\"datePublished\":\"2025-05-07T11:47:31+00:00\",\"dateModified\":\"2025-05-09T08:24:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/\"},\"wordCount\":1031,\"commentCount\":13,\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/Restrisiko-Einzelrisiko-1024x458.jpg\",\"keywords\":[\"Risikoakzeptanz\",\"Risikobeherrschung | Risikominimierung\",\"Risikomanagementakte\"],\"articleSection\":[\"Risikomanagement &amp; ISO 14971\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/\",\"name\":\"Restrisiko: Diese Zahlen sollten Sie kennen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/Restrisiko-Einzelrisiko-1024x458.jpg\",\"datePublished\":\"2025-05-07T11:47:31+00:00\",\"dateModified\":\"2025-05-09T08:24:52+00:00\",\"description\":\"Das Restrisiko ist das Risiko, das nach risikominimierenden Ma\u00dfnahmen verbleibt. Doch welche Restrisiken sind akzeptabel? Dieser Beitrag gibt Antworten\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/Restrisiko-Einzelrisiko.jpg\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/Restrisiko-Einzelrisiko.jpg\",\"width\":1200,\"height\":537},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iso-14971-risikomanagement\\\/restrisiko\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Risikomanagement &amp; ISO 14971\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/category\\\/iso-14971-risikomanagement\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Restrisiko: Diese Zahlen sollten Sie kennen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"name\":\"Regulatorisches Wissen f\u00fcr Medizinprodukte\",\"description\":\"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\",\"name\":\"Johner Institut GmbH\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"width\":1213,\"height\":286,\"caption\":\"Johner Institut GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JohnerInstitut\\\/\",\"https:\\\/\\\/x.com\\\/christianjohner\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/JohnerInstitut\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/a1bfe9a403a4dd4f8aed197335feb568\",\"name\":\"Christian Rosenzweig\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Christian_Rosenzweig_300x300.png608f3c25642fdf010fd6a50508840c4c\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Christian_Rosenzweig_300x300.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Christian_Rosenzweig_300x300.png\",\"caption\":\"Christian Rosenzweig\"},\"description\":\"Christian Rosenzweig ist seit mehr als 20 Jahren im regulierten Medizinprodukteumfeld t\u00e4tig und ein absoluter Enthusiast in diesem Bereich. Er ist Mitglied des Normengremiums f\u00fcr Software und vernetzte Medizinprodukte, Experte f\u00fcr aktive Medizinprodukte, Risikomanagement und IT-Security, Leiter des Bereichs Risikomanagement und IT-Security am Johner Institut, Dozent f\u00fcr diese Themenbereiche bei Seminaren des Johner Instituts, sowie in dessen Studieng\u00e4nge. Operative Beratungsarbeit in Kundenprojekten gibt ihm die M\u00f6glichkeit, den Transfer zwischen Theorie und Praxis im Alltag anzuwenden.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/christian-rosenzweig-150810134\\\/\"],\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/author\\\/christianrosenzweig\\\/\"}]}<\/script>\n<meta name=\"copyright\" content=\"Johner Institut GmbH\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restrisiko: Diese Zahlen sollten Sie kennen","description":"Das Restrisiko ist das Risiko, das nach risikominimierenden Ma\u00dfnahmen verbleibt. Doch welche Restrisiken sind akzeptabel? Dieser Beitrag gibt Antworten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/","og_locale":"de_DE","og_type":"article","og_title":"Restrisiko: Diese Zahlen sollten Sie kennen","og_description":"Das Restrisiko ist das Risiko, das nach risikominimierenden Ma\u00dfnahmen verbleibt. Doch welche Restrisiken sind akzeptabel? Dieser Beitrag gibt Antworten","og_url":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/","og_site_name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","article_publisher":"https:\/\/www.facebook.com\/JohnerInstitut\/","article_published_time":"2025-05-07T11:47:31+00:00","article_modified_time":"2025-05-09T08:24:52+00:00","og_image":[{"width":1200,"height":537,"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Einzelrisiko.jpg","type":"image\/jpeg"}],"author":"Christian Rosenzweig","twitter_misc":{"Verfasst von":"Christian Rosenzweig","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/#article","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/"},"author":{"name":"Christian Rosenzweig","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/a1bfe9a403a4dd4f8aed197335feb568"},"headline":"Restrisiko: Diese Zahlen sollten Sie kennen","datePublished":"2025-05-07T11:47:31+00:00","dateModified":"2025-05-09T08:24:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/"},"wordCount":1031,"commentCount":13,"publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Einzelrisiko-1024x458.jpg","keywords":["Risikoakzeptanz","Risikobeherrschung | Risikominimierung","Risikomanagementakte"],"articleSection":["Risikomanagement &amp; ISO 14971"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/","url":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/","name":"Restrisiko: Diese Zahlen sollten Sie kennen","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/#primaryimage"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Einzelrisiko-1024x458.jpg","datePublished":"2025-05-07T11:47:31+00:00","dateModified":"2025-05-09T08:24:52+00:00","description":"Das Restrisiko ist das Risiko, das nach risikominimierenden Ma\u00dfnahmen verbleibt. Doch welche Restrisiken sind akzeptabel? Dieser Beitrag gibt Antworten","breadcrumb":{"@id":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/#primaryimage","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Einzelrisiko.jpg","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/12\/Restrisiko-Einzelrisiko.jpg","width":1200,"height":537},{"@type":"BreadcrumbList","@id":"https:\/\/www.johner-institut.de\/blog\/iso-14971-risikomanagement\/restrisiko\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.johner-institut.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Risikomanagement &amp; ISO 14971","item":"https:\/\/www.johner-institut.de\/blog\/category\/iso-14971-risikomanagement\/"},{"@type":"ListItem","position":3,"name":"Restrisiko: Diese Zahlen sollten Sie kennen"}]},{"@type":"WebSite","@id":"https:\/\/www.johner-institut.de\/blog\/#website","url":"https:\/\/www.johner-institut.de\/blog\/","name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","description":"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen","publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.johner-institut.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.johner-institut.de\/blog\/#organization","name":"Johner Institut GmbH","url":"https:\/\/www.johner-institut.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","width":1213,"height":286,"caption":"Johner Institut GmbH"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JohnerInstitut\/","https:\/\/x.com\/christianjohner","https:\/\/www.youtube.com\/user\/JohnerInstitut"]},{"@type":"Person","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/a1bfe9a403a4dd4f8aed197335feb568","name":"Christian Rosenzweig","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Christian_Rosenzweig_300x300.png608f3c25642fdf010fd6a50508840c4c","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Christian_Rosenzweig_300x300.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Christian_Rosenzweig_300x300.png","caption":"Christian Rosenzweig"},"description":"Christian Rosenzweig ist seit mehr als 20 Jahren im regulierten Medizinprodukteumfeld t\u00e4tig und ein absoluter Enthusiast in diesem Bereich. Er ist Mitglied des Normengremiums f\u00fcr Software und vernetzte Medizinprodukte, Experte f\u00fcr aktive Medizinprodukte, Risikomanagement und IT-Security, Leiter des Bereichs Risikomanagement und IT-Security am Johner Institut, Dozent f\u00fcr diese Themenbereiche bei Seminaren des Johner Instituts, sowie in dessen Studieng\u00e4nge. Operative Beratungsarbeit in Kundenprojekten gibt ihm die M\u00f6glichkeit, den Transfer zwischen Theorie und Praxis im Alltag anzuwenden.","sameAs":["https:\/\/www.linkedin.com\/in\/christian-rosenzweig-150810134\/"],"url":"https:\/\/www.johner-institut.de\/blog\/author\/christianrosenzweig\/"}]}},"authors":[{"term_id":1213,"user_id":74,"is_guest":0,"slug":"christianrosenzweig","display_name":"Christian Rosenzweig","avatar_url":{"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Christian_Rosenzweig_300x300.png","url2x":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/05\/Christian_Rosenzweig_300x300.png"},"author_category":"","first_name":"Christian","last_name":"Rosenzweig","user_url":"","user_url_2":"","job_title":"","description":"Christian Rosenzweig ist seit mehr als 20 Jahren im regulierten Medizinprodukteumfeld t\u00e4tig und ein absoluter Enthusiast in diesem Bereich.\r\nEr ist Mitglied des Normengremiums f\u00fcr Software und vernetzte Medizinprodukte, Experte f\u00fcr aktive Medizinprodukte, Risikomanagement und IT-Security, Leiter des Bereichs Risikomanagement und IT-Security am Johner Institut, Dozent f\u00fcr diese Themenbereiche bei Seminaren des Johner Instituts, sowie in dessen Studieng\u00e4nge.\r\nOperative Beratungsarbeit in Kundenprojekten gibt ihm die M\u00f6glichkeit, den Transfer zwischen Theorie und Praxis im Alltag anzuwenden."}],"_links":{"self":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/6127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/users\/74"}],"replies":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/comments?post=6127"}],"version-history":[{"count":7,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/6127\/revisions"}],"predecessor-version":[{"id":5381320,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/6127\/revisions\/5381320"}],"wp:attachment":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/media?parent=6127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/categories?post=6127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/tags?post=6127"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/ppma_author?post=6127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}