{"id":9264,"date":"2017-03-23T09:00:28","date_gmt":"2017-03-23T08:00:28","guid":{"rendered":"http:\/\/www.johner-institut.de\/blog\/?p=9264"},"modified":"2023-04-14T09:19:19","modified_gmt":"2023-04-14T07:19:19","slug":"java-virtual-machine-jvm","status":"publish","type":"post","link":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/","title":{"rendered":"Java Virtual Machine JVM eine SOUP?"},"content":{"rendered":"<p>Java Virtual Machines (JVM) sind\u00a0Software-Programme, die Hardware und Betriebssysteme abstrahieren, indem sie Programmen eine virtuelle Betriebssystem- und Hardware-unabh\u00e4ngige Schicht zur Verf\u00fcgung stellen. \u201eWrite once, run everywhere\u201c war einst der Slogan.<\/p>\n<p>Eine JVM ist somit\u00a0eine Software. Aber ist eine Java Virtual Machine\u00a0auch eine SOUP? Antworten finden Sie in diesem Beitrag.<\/p>\n<p><!--more--><\/p>\n<h2>JVM: Die urspr\u00fcngliche Idee<\/h2>\n<p>Eine Java Virtual Machine\u00a0erlaubt es, dass Anwendungsprogramme weitgehend unabh\u00e4ngig von der Hardware und dem Betriebssystem entwickelt und kompiliert werden k\u00f6nnen.\u00a0Entwickler schreiben Source-Code in einer der Programmiersprachen f\u00fcr die JVM wie Java, Jython, JRuby, Scala oder Kotlin. Sie kompilieren den Quellcode zu Class-Dateien.\u00a0Dieser sogenannte Bytecode wird dann von einer Java Virtual Machine (JVM) interpretiert. JVMs sind f\u00fcr\u00a0viele verschiedene Betriebssysteme verf\u00fcgbar, die wiederum auf einer bestimmen Hardware laufen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-742516\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/01\/JVM-Code.jpg\" alt=\"Die JVM (Java Virtual Machine) abstrahiert die Hardware und das Betriebssystem\" width=\"224\" height=\"382\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/01\/JVM-Code.jpg 224w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/01\/JVM-Code-176x300.jpg 176w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/01\/JVM-Code-88x150.jpg 88w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/p>\n<p>Die Java Virtual Machine\u00a0dient somit als Abstraktionsschicht zwischen Betriebssystem und der eigenen Software.<\/p>\n<p>Zu den wichtigsten Herstellern von Java Virtual Machines z\u00e4hlen:<\/p>\n<ul>\n<li>Oracle<\/li>\n<li>IBM<\/li>\n<li>JRockit<\/li>\n<li>Android Runtime<\/li>\n<\/ul>\n<h2>Ist eine JVM eine\u00a0SOUP?<\/h2>\n<p>Ob eine Java Virtual Machine eine SOUP ist, h\u00e4ngt davon ab, ob sie Teil des\u00a0Medizinprodukts ist oder Teil der vorausgesetzten Laufzeitumgebung.<\/p>\n<div id=\"attachment_9265\" style=\"width: 289px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/12\/JVM-SOUP-IEC62366.png\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9265\" class=\"wp-image-9265 size-medium\" src=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/12\/JVM-SOUP-IEC62366-279x300.png\" alt=\"Ob die JVM eine SOUP gem\u00e4\u00df IEC 62304 ist, h\u00e4ngt davon ab, ob der Hersteller sie als Teil seines Produkts in Verkehr bringt.\" width=\"279\" height=\"300\" srcset=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/12\/JVM-SOUP-IEC62366-279x300.png 279w, https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/12\/JVM-SOUP-IEC62366.png 665w\" sizes=\"auto, (max-width: 279px) 100vw, 279px\" \/><\/a><p id=\"caption-attachment-9265\" class=\"wp-caption-text\">Ob die JVM eine SOUP gem\u00e4\u00df IEC 62304 ist, h\u00e4ngt davon ab, ob der Hersteller sie als Teil seines Produkts in Verkehr bringt.<\/p><\/div>\n<p>Eine JVM ist nur dann eine SOUP, wenn sie Teil des (ausgelieferten) Medizinprodukts ist.\u00a0Das trifft in den folgenden F\u00e4llen zu:<\/p>\n<ul>\n<li>Der Hersteller liefert das Produkt inklusive Hardware und Betriebssystem sowie\u00a0JVM aus (Fall 4 in obiger\u00a0Abbildung). Das ist bei\u00a0physischen\u00a0Medizinger\u00e4ten der Fall.<\/li>\n<li>Der Hersteller liefert alles au\u00dfer der Hardware aus (Fall 3). D.h. der Hersteller setzt nur eine &#8222;nackte&#8220; Hardware voraus.<\/li>\n<li>Der Hersteller setzt nur die Hardware und das Betriebssystem voraus und liefert seine Software einschlie\u00dflich JVM aus\u00a0(Fall 2).<\/li>\n<\/ul>\n<p>Sobald der Hersteller es dem Kunden \u00fcberl\u00e4sst, die Hardware und das Betriebssystem einschlie\u00dflich Java Virtual Machine\u00a0zu besorgen, und dem Kunden die JVM nicht mitliefert, ist diese Virtual Machine\u00a0keine(!) SOUP, sondern Teil der Laufzeitumgebung (Fall 1). Daran \u00e4ndert sich auch nichts, wenn der Hersteller die Anforderungen an die Laufzeitumgebung spezifiziert z.B. in Form von Hardware-Anforderungen, Mindestversion eines Betriebssystems oder JVM-Version bzw. Hersteller. Die Java Virtual Machine\u00a0ist dann keine SOUP.<\/p>\n<div class=\"defbox\">\n<div class=\"definition\"><i class=\"fa fa-external-link\"><\/i> Weiterf\u00fchrende Informationen<\/div>\n<p>Lesen Sie hier mehr zum Thema <a href=\"https:\/\/www.johner-institut.de\/blog\/tag\/soup\/\">Software of Unknown Provenance (SOUP)<\/a>.<\/p>\n<\/div>\n<h2>Anforderungen an SOUPs (ggf. auch an JVM)<\/h2>\n<p>Die Anforderungen der IEC 62304 an SOUPs gelten auch f\u00fcr Java Virtual Machines. Insbesondere sollten Sie<\/p>\n<ol>\n<li>die Anforderungen an die JVM spezifizieren: Hier empfiehlt es sich, festzulegen, welche Funktionen der JVM besonders relevant sind, wie beispielsweise der Zugriff auf den Netzwerkstack, der Dateizugriff oder die Abstraktion der Bildschirmansteuerung. Diese Anforderungen sind relativ generisch. Stellen Sie fest, welche dieser Anforderungen besonders wichtig sind, um Risiken f\u00fcr Patienten und Anwender zu vermeiden. Zu den Anforderungen k\u00f6nnen auch das Verhalten bei hoher Last oder der Umgang mit vielen Threads betreffen.<\/li>\n<li>die Voraussetzungen spezifizieren, von denen die JVM ausgehen muss: Das sind insbesondere das Betriebssystem (Typ, Versionen) und die Hardware-Konfigurationen.<\/li>\n<\/ol>\n<p>Schlie\u00dflich m\u00fcssen Sie testen, dass die Anforderungen bei den gegebenen Voraussetzungen erf\u00fcllt werden.<\/p>\n<h2>Typische Fehler beim Umgang mit Java Virtual Machines<\/h2>\n<p>Wir sto\u00dfen regelm\u00e4\u00dfig auf folgende Probleme in Audits und bei Einreichungen von Produktakten:<\/p>\n<ul>\n<li>Die Anforderungen an die JVM sind nicht spezifiziert.<\/li>\n<li>Die Hersteller haben die Hardware und das Betriebssystem nicht festgelegt, auf denen die Virtual Machine laufen soll.<\/li>\n<li>Die JVM erscheint nicht in der Liste der SOUPs und\/oder wir in der nachgelagerten Phase nicht verfolgt.<\/li>\n<li>In der Software-Architektur\u00a0wird diese Virtualisierungsschicht nicht beschreiben.<\/li>\n<li>Hersteller lassen sich von Auditoren in\u00a0wenig zielf\u00fchrende Diskussionen verwickeln, ob der Einsatz einer JVM nicht unn\u00f6tige Risiken verursachen w\u00fcrde.<\/li>\n<li>Die JVMs werden nicht gepatched und werden somit zum\u00a0Problem f\u00fcr die IT-Security.<\/li>\n<li>Die Hersteller haben keinen \u00dcberblick dar\u00fcber, in welchem Produkt bzw. bei welchem Kunden welche Version einer Java Virtual Machine l\u00e4uft.<\/li>\n<li>Die Entwickler entwickeln und testen auf anderen Versionen als denen, die bei den Kunden im Einsatz sind.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Java Virtual Machines (JVM) sind\u00a0Software-Programme, die Hardware und Betriebssysteme abstrahieren, indem sie Programmen eine virtuelle Betriebssystem- und Hardware-unabh\u00e4ngige Schicht zur Verf\u00fcgung stellen. \u201eWrite once, run everywhere\u201c war einst der Slogan. Eine JVM ist somit\u00a0eine Software. Aber ist eine Java Virtual Machine\u00a0auch eine SOUP? Antworten finden Sie in diesem Beitrag.<\/p>\n","protected":false},"author":1,"featured_media":9265,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[184],"tags":[269,368],"ppma_author":[1210],"class_list":["post-9264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-iec-62304-medizinische-software","tag-medizinische-software","tag-soup","category-184","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Java Virtual Machine (JVM) ~ Anforderungen &amp; typische Fehler<\/title>\n<meta name=\"description\" content=\"Eine Java Virtual Machine (JVM) wird nur dann zur SOUP gem\u00e4\u00df IEC 62304, wenn sie Bestandteil des in Verkehr gebrachten Medizinprodukts ist.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Java Virtual Machine (JVM) ~ Anforderungen &amp; typische Fehler\" \/>\n<meta property=\"og:description\" content=\"Eine Java Virtual Machine (JVM) wird nur dann zur SOUP gem\u00e4\u00df IEC 62304, wenn sie Bestandteil des in Verkehr gebrachten Medizinprodukts ist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/\" \/>\n<meta property=\"og:site_name\" content=\"Regulatorisches Wissen f\u00fcr Medizinprodukte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JohnerInstitut\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-23T08:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-14T07:19:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/12\/JVM-SOUP-IEC62366.png\" \/>\n\t<meta property=\"og:image:width\" content=\"665\" \/>\n\t<meta property=\"og:image:height\" content=\"714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Prof. Dr. Christian Johner\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prof. Dr. Christian Johner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/\"},\"author\":{\"name\":\"Prof. Dr. Christian Johner\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/77ee54cd54e987c0b5738d4cb4c80441\"},\"headline\":\"Java Virtual Machine JVM eine SOUP?\",\"datePublished\":\"2017-03-23T08:00:28+00:00\",\"dateModified\":\"2023-04-14T07:19:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/\"},\"wordCount\":680,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/JVM-SOUP-IEC62366.png\",\"keywords\":[\"Medizinische Software \\\/ Medical Device Software\",\"SOUP - Software of Unknown Provenance\"],\"articleSection\":[\"Software &amp; IEC 62304\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/\",\"name\":\"Java Virtual Machine (JVM) ~ Anforderungen & typische Fehler\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/JVM-SOUP-IEC62366.png\",\"datePublished\":\"2017-03-23T08:00:28+00:00\",\"dateModified\":\"2023-04-14T07:19:19+00:00\",\"description\":\"Eine Java Virtual Machine (JVM) wird nur dann zur SOUP gem\u00e4\u00df IEC 62304, wenn sie Bestandteil des in Verkehr gebrachten Medizinprodukts ist.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/JVM-SOUP-IEC62366.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/JVM-SOUP-IEC62366.png\",\"width\":665,\"height\":714,\"caption\":\"Ob die JVM eine SOUP gem\u00e4\u00df IEC 62304 ist, h\u00e4ngt davon ab, ob der Hersteller sie als Teil seines Produkts in Verkehr bringt.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/iec-62304-medizinische-software\\\/java-virtual-machine-jvm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Software &amp; IEC 62304\",\"item\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/category\\\/iec-62304-medizinische-software\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Java Virtual Machine JVM eine SOUP?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"name\":\"Regulatorisches Wissen f\u00fcr Medizinprodukte\",\"description\":\"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#organization\",\"name\":\"Johner Institut GmbH\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Johner-Institut.png\",\"width\":1213,\"height\":286,\"caption\":\"Johner Institut GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JohnerInstitut\\\/\",\"https:\\\/\\\/x.com\\\/christianjohner\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/JohnerInstitut\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/#\\\/schema\\\/person\\\/77ee54cd54e987c0b5738d4cb4c80441\",\"name\":\"Prof. Dr. Christian Johner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Christian_Johner.jpgab057afc2debeb41aaf55cce7e79e618\",\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Christian_Johner.jpg\",\"contentUrl\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Christian_Johner.jpg\",\"caption\":\"Prof. Dr. Christian Johner\"},\"description\":\"Professor Johner ist Experte f\u00fcr die Entwicklung und Zulassung von Medizinprodukten, die Software enthalten oder Software sind. Als Auditor, als Mitglied eines Normen-Komitees, als Ausbilder benannter Stellen sowie als Autor mehrerer B\u00fccher und Leitf\u00e4den tr\u00e4gt der promovierte Physiker zur Weiterentwicklung der regulatorischen Landschaft bei. Davon zeugen auch Leitf\u00e4den, die er f\u00fcr die WHO und die Benannten Stellen entwickelt hat. Sein Unternehmen, das Johner Institut, unterst\u00fctzt Medizinproduktehersteller weltweit beim Aufbau von QM-Systemen, bei der Zulassung und Pr\u00fcfung ihrer Produkte sowie bei der digitalen Transformation regulatorischer Prozesse. Es bietet Weiterbildungen wie E-Learning und Seminare an und \u00fcbernimmt f\u00fcr Hersteller Prozesse wie die \u00dcberwachung der Regularien und der Produkte im Markt. Christian Johner lehrte an mehreren Universit\u00e4ten u.a. an der Hochschule Konstanz, der Universit\u00e4t St. Gallen, der Universit\u00e4t W\u00fcrzburg sowie der Stanford University v.a. Software-Architektur, Software-Qualit\u00e4tssicherung und medizinische Informatik.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/christianjohner\\\/\",\"https:\\\/\\\/x.com\\\/christianjohner\"],\"url\":\"https:\\\/\\\/www.johner-institut.de\\\/blog\\\/author\\\/christian\\\/\"}]}<\/script>\n<meta name=\"copyright\" content=\"Johner Institut GmbH\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Java Virtual Machine (JVM) ~ Anforderungen & typische Fehler","description":"Eine Java Virtual Machine (JVM) wird nur dann zur SOUP gem\u00e4\u00df IEC 62304, wenn sie Bestandteil des in Verkehr gebrachten Medizinprodukts ist.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/","og_locale":"de_DE","og_type":"article","og_title":"Java Virtual Machine (JVM) ~ Anforderungen & typische Fehler","og_description":"Eine Java Virtual Machine (JVM) wird nur dann zur SOUP gem\u00e4\u00df IEC 62304, wenn sie Bestandteil des in Verkehr gebrachten Medizinprodukts ist.","og_url":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/","og_site_name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","article_publisher":"https:\/\/www.facebook.com\/JohnerInstitut\/","article_published_time":"2017-03-23T08:00:28+00:00","article_modified_time":"2023-04-14T07:19:19+00:00","og_image":[{"width":665,"height":714,"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/12\/JVM-SOUP-IEC62366.png","type":"image\/png"}],"author":"Prof. Dr. Christian Johner","twitter_misc":{"Verfasst von":"Prof. Dr. Christian Johner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/#article","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/"},"author":{"name":"Prof. Dr. Christian Johner","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/77ee54cd54e987c0b5738d4cb4c80441"},"headline":"Java Virtual Machine JVM eine SOUP?","datePublished":"2017-03-23T08:00:28+00:00","dateModified":"2023-04-14T07:19:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/"},"wordCount":680,"commentCount":0,"publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/12\/JVM-SOUP-IEC62366.png","keywords":["Medizinische Software \/ Medical Device Software","SOUP - Software of Unknown Provenance"],"articleSection":["Software &amp; IEC 62304"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/","url":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/","name":"Java Virtual Machine (JVM) ~ Anforderungen & typische Fehler","isPartOf":{"@id":"https:\/\/www.johner-institut.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/#primaryimage"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/12\/JVM-SOUP-IEC62366.png","datePublished":"2017-03-23T08:00:28+00:00","dateModified":"2023-04-14T07:19:19+00:00","description":"Eine Java Virtual Machine (JVM) wird nur dann zur SOUP gem\u00e4\u00df IEC 62304, wenn sie Bestandteil des in Verkehr gebrachten Medizinprodukts ist.","breadcrumb":{"@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/#primaryimage","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/12\/JVM-SOUP-IEC62366.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/12\/JVM-SOUP-IEC62366.png","width":665,"height":714,"caption":"Ob die JVM eine SOUP gem\u00e4\u00df IEC 62304 ist, h\u00e4ngt davon ab, ob der Hersteller sie als Teil seines Produkts in Verkehr bringt."},{"@type":"BreadcrumbList","@id":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/java-virtual-machine-jvm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.johner-institut.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Software &amp; IEC 62304","item":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62304-medizinische-software\/"},{"@type":"ListItem","position":3,"name":"Java Virtual Machine JVM eine SOUP?"}]},{"@type":"WebSite","@id":"https:\/\/www.johner-institut.de\/blog\/#website","url":"https:\/\/www.johner-institut.de\/blog\/","name":"Regulatorisches Wissen f\u00fcr Medizinprodukte","description":"Fachartikel zur Entwicklung und Zulassung von Medizinprodukten und weiteren regulatorischen Themen","publisher":{"@id":"https:\/\/www.johner-institut.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.johner-institut.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.johner-institut.de\/blog\/#organization","name":"Johner Institut GmbH","url":"https:\/\/www.johner-institut.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/07\/Johner-Institut.png","width":1213,"height":286,"caption":"Johner Institut GmbH"},"image":{"@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JohnerInstitut\/","https:\/\/x.com\/christianjohner","https:\/\/www.youtube.com\/user\/JohnerInstitut"]},{"@type":"Person","@id":"https:\/\/www.johner-institut.de\/blog\/#\/schema\/person\/77ee54cd54e987c0b5738d4cb4c80441","name":"Prof. Dr. Christian Johner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpgab057afc2debeb41aaf55cce7e79e618","url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpg","contentUrl":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpg","caption":"Prof. Dr. Christian Johner"},"description":"Professor Johner ist Experte f\u00fcr die Entwicklung und Zulassung von Medizinprodukten, die Software enthalten oder Software sind. Als Auditor, als Mitglied eines Normen-Komitees, als Ausbilder benannter Stellen sowie als Autor mehrerer B\u00fccher und Leitf\u00e4den tr\u00e4gt der promovierte Physiker zur Weiterentwicklung der regulatorischen Landschaft bei. Davon zeugen auch Leitf\u00e4den, die er f\u00fcr die WHO und die Benannten Stellen entwickelt hat. Sein Unternehmen, das Johner Institut, unterst\u00fctzt Medizinproduktehersteller weltweit beim Aufbau von QM-Systemen, bei der Zulassung und Pr\u00fcfung ihrer Produkte sowie bei der digitalen Transformation regulatorischer Prozesse. Es bietet Weiterbildungen wie E-Learning und Seminare an und \u00fcbernimmt f\u00fcr Hersteller Prozesse wie die \u00dcberwachung der Regularien und der Produkte im Markt. Christian Johner lehrte an mehreren Universit\u00e4ten u.a. an der Hochschule Konstanz, der Universit\u00e4t St. Gallen, der Universit\u00e4t W\u00fcrzburg sowie der Stanford University v.a. Software-Architektur, Software-Qualit\u00e4tssicherung und medizinische Informatik.","sameAs":["https:\/\/www.linkedin.com\/in\/christianjohner\/","https:\/\/x.com\/christianjohner"],"url":"https:\/\/www.johner-institut.de\/blog\/author\/christian\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2014\/12\/JVM-SOUP-IEC62366.png","jetpack-related-posts":[{"id":3981,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/betriebssystem-iec-62304-konform\/","url_meta":{"origin":9264,"position":0},"title":"Betriebssystem konform mit IEC 62304 und FDA?","author":"Prof. Dr. Christian Johner","date":"23. Oktober 2024","format":false,"excerpt":"M\u00fcssen Medizinproduktehersteller bei der Auswahl des Betriebssystems darauf achten, dass das Betriebssystem IEC- 62304-konform ist? Was sagt die FDA? Dieser Artikel \u2026 nennt die regulatorischen Anforderungen (z. B. IEC 62304, FDA) an\u00a0Betriebssysteme. gibt Tipps zur Auswahl von Betriebssystemen. untersucht, ob es eine IEC 62304-Zertifizierung f\u00fcr Betriebssysteme geben kann bzw. muss.\u2026","rel":"","context":"In &quot;Software &amp; IEC 62304&quot;","block_context":{"text":"Software &amp; IEC 62304","link":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62304-medizinische-software\/"},"img":{"alt_text":"Betriebssystem und IEC-62304","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2012\/03\/Betriebssystem-IEC-62304.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3891,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/lebensdauer-von-software\/","url_meta":{"origin":9264,"position":1},"title":"Lebensdauer von Software: Wie wird sie festgelegt?","author":"Christian Rosenzweig","date":"15. Oktober 2015","format":false,"excerpt":"Viele Medizinproduktehersteller tun sich damit schwer, die Lebensdauer von Software festzulegen, schon weil unklar ist, was\u00a0die Lebensdauer von Software\u00a0definiert. Wann ist\u00a0ein neues Release eine neue Software? Dieser Beitrag gibt Hinweise und Tipps. Lebensdauer von Medizinprodukten Dass Hersteller von Medizinprodukten die Lebensdauer festlegen m\u00fcssen, ergibt Sinn, denn die Sterilit\u00e4t eines Produkts\u2026","rel":"","context":"In &quot;Software &amp; IEC 62304&quot;","block_context":{"text":"Software &amp; IEC 62304","link":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62304-medizinische-software\/"},"img":{"alt_text":"Die Lebensdauer von Software ist nicht nur bei Computerspielen endlich","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2012\/02\/Lebensdauer-von-Software.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4658,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/off-the-shelf-software-ots-versus-soup\/","url_meta":{"origin":9264,"position":2},"title":"Off-the-Shelf Software (OTS) versus SOUP","author":"Christopher Seib","date":"30. Oktober 2023","format":false,"excerpt":"Sowohl die FDA als auch die IEC 62304 kennen durch Dritte entwickelte Software. Sie sprechen von Off-the-Shelf Software\u00a0(OTS) bzw. von Software of Unknown Provenance (SOUP). Worin unterscheiden sich OTS und SOUP? Welche Gemeinsamkeiten haben beide? Welche gesetzlichen Anforderungen m\u00fcssen sie erf\u00fcllen? Dieser Artikel gibt Antworten. Abb. 1: SOUP und OTS-Software\u2026","rel":"","context":"In &quot;Software &amp; IEC 62304&quot;","block_context":{"text":"Software &amp; IEC 62304","link":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62304-medizinische-software\/"},"img":{"alt_text":"OTS Software: Level of Concern","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2013\/12\/ots-software.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2013\/12\/ots-software.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2013\/12\/ots-software.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2013\/12\/ots-software.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5377358,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/sbom-software-bills-of-materials\/","url_meta":{"origin":9264,"position":3},"title":"SBOM: Software Bill of Materials","author":"Christian Rosenzweig","date":"23. Januar 2024","format":false,"excerpt":"Gesetze und Normen verpflichten Medizinproduktehersteller zur Software Bill of Materials, der SBOM. Standardisierte SBOM-Formate reichen allerdings nicht immer aus, um diese Anforderungen zu erf\u00fcllen. Insbesondere Medizinproduktehersteller, die f\u00fcr ihre Software keine SBOM ausliefern und nutzen, sind im Markt nicht mehr akzeptiert. Hier sind die Gr\u00fcnde. 1. SBOM: Die Grundlagen a)\u2026","rel":"","context":"In &quot;Software &amp; IEC 62304&quot;","block_context":{"text":"Software &amp; IEC 62304","link":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62304-medizinische-software\/"},"img":{"alt_text":"SBOM Hierarchie der Komponenten","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/01\/SBOM-Komponenten-Hierarchie-Kopie.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/01\/SBOM-Komponenten-Hierarchie-Kopie.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/01\/SBOM-Komponenten-Hierarchie-Kopie.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2024\/01\/SBOM-Komponenten-Hierarchie-Kopie.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6778,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/segregation-von-software-komponenten\/","url_meta":{"origin":9264,"position":4},"title":"Segregation von Software: 5 Ziele, die Sie kennen sollten","author":"Prof. Dr. Christian Johner","date":"26. November 2024","format":false,"excerpt":"Die IEC 62304 verpflichtet die Hersteller, die notwendige\u00a0Segregation (auf Deutsch \"Abgrenzung\") von Software-Komponenten zu bestimmen. Wie diese zu erfolgen hat, legt die Norm nicht fest, was zu vielen Diskussionen f\u00fchrt. Finden Sie hier Antworten auf\u00a0h\u00e4ufige Fragen. 1. Die f\u00fcnf Ziele\u00a0der\u00a0Segregation Die Segregation verfolgt mehrere\u00a0Ziele. Ziel 1: Risiken minimieren Die Segregation\u2026","rel":"","context":"In &quot;Software &amp; IEC 62304&quot;","block_context":{"text":"Software &amp; IEC 62304","link":"https:\/\/www.johner-institut.de\/blog\/category\/iec-62304-medizinische-software\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2015\/11\/Segregation.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":57,"url":"https:\/\/www.johner-institut.de\/blog\/iec-62304-medizinische-software\/security-patch\/","url_meta":{"origin":9264,"position":5},"title":"Security Patches &#8211; aus der regulatorischen Brille betrachtet","author":"Christian Rosenzweig","date":"12. Januar 2018","format":false,"excerpt":"Unter einem Security Patch versteht man eine Nachbesserung an einer Software, um eine Sicherheitsl\u00fccke zu stopfen. F\u00fcr einen Security Patch gelten teilweise andere regulatorische Anforderungen als an andere Software Updates. Auf was Sie achten m\u00fcssen, erfahren Sie in diesem Beitrag. Security Patch Definition Eine etwas l\u00e4ngliche aber hilfreiche Definition des\u2026","rel":"","context":"In &quot;Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte&quot;","block_context":{"text":"Regulatory Affairs: Regulatorische Anforderungen an Medizinprodukte","link":"https:\/\/www.johner-institut.de\/blog\/category\/regulatory-affairs\/"},"img":{"alt_text":"Security Patch","src":"https:\/\/i0.wp.com\/www.johner-institut.de\/blog\/wp-content\/uploads\/2008\/10\/Security-Patch-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/pavawf-2pq","jetpack_sharing_enabled":true,"authors":[{"term_id":1210,"user_id":1,"is_guest":0,"slug":"christian","display_name":"Prof. Dr. Christian Johner","avatar_url":{"url":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpg","url2x":"https:\/\/www.johner-institut.de\/blog\/wp-content\/uploads\/2023\/05\/Christian_Johner.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":""}],"_links":{"self":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/9264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/comments?post=9264"}],"version-history":[{"count":1,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/9264\/revisions"}],"predecessor-version":[{"id":5368029,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/posts\/9264\/revisions\/5368029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/media\/9265"}],"wp:attachment":[{"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/media?parent=9264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/categories?post=9264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/tags?post=9264"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.johner-institut.de\/blog\/wp-json\/wp\/v2\/ppma_author?post=9264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}